{"id":90579,"date":"2018-08-20T12:00:29","date_gmt":"2018-08-20T15:00:29","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=90579"},"modified":"2018-08-20T10:42:30","modified_gmt":"2018-08-20T13:42:30","slug":"brasil-e-pais-com-maior-numero-de-primatas-ameacados-de-extincao-aponta-estudo","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/brasil-e-pais-com-maior-numero-de-primatas-ameacados-de-extincao-aponta-estudo\/","title":{"rendered":"Brasil \u00e9 pa\u00eds com maior n\u00famero de primatas amea\u00e7ados de extin\u00e7\u00e3o, aponta estudo"},"content":{"rendered":"<p class=\"story-body__introduction\"><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/primata.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-90580\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/primata-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/primata-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/primata.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Os primatas do mundo, incluindo gorilas, chimpanz\u00e9s e gib\u00f5es, pedem socorro. Grande parte das 439 esp\u00e9cies conhecidas corre algum risco de ser extinta. O perigo \u00e9 mais iminente para as que vivem nos quatro pa\u00edses com a maior quantidade delas: Brasil (102), Madagascar (100), Indon\u00e9sia (48) e Rep\u00fablica Democr\u00e1tica do Congo (36). Dessas 286, cerca de 60% est\u00e3o amea\u00e7adas de extin\u00e7\u00e3o em algum grau (vulner\u00e1veis, amea\u00e7adas ou criticamente amea\u00e7adas), por causa de a\u00e7\u00f5es humanas.<\/p>\n<p>As conclus\u00f5es s\u00e3o de um amplo estudo realizado por um grupo internacional de 72 especialistas em primatas, entre os quais oito de institui\u00e7\u00f5es brasileiras, e publicado em junho na revista cient\u00edfica PeerJ.<\/p>\n<p>&#8220;Reunimos pesquisadores de diferentes nacionalidades, mas que direta ou indiretamente trabalham num dos quatro pa\u00edses, e compilamos as informa\u00e7\u00f5es dispon\u00edveis na literatura em rela\u00e7\u00e3o \u00e1s press\u00f5es antr\u00f3picas sobre os macacos em cada um deles&#8221;, conta o bi\u00f3logo Leonardo Oliveira, professor da Universidade do Estado do Rio de Janeiro (UERJ) e presidente da Sociedade Brasileira de Primatologia (SBP).<\/p>\n<p>De acordo com ele, o estudo avaliou o papel do Brasil, Madagascar, Indon\u00e9sia e Rep\u00fablica Democr\u00e1tica do Congo para a conserva\u00e7\u00e3o global dos macacos. &#8220;Esses quatro pa\u00edses abrigam dois ter\u00e7os de todos os primatas n\u00e3o humanos do mundo&#8221;, diz. &#8220;Da\u00ed sua import\u00e2ncia para a conserva\u00e7\u00e3o desses animais.&#8221;<\/p>\n<p>Os pesquisadores analisaram a distribui\u00e7\u00e3o das \u00e1reas protegidas e das esp\u00e9cies em cada um dos quatro pa\u00edses e descobriram que a grande maioria das popula\u00e7\u00f5es de primatas n\u00e3o tem seguran\u00e7a adequada. Por exemplo, embora a porcentagem deles em unidades de conserva\u00e7\u00e3o no Brasil seja relativamente alta, 38%, na Indon\u00e9sia e no Congo esses \u00edndices s\u00e3o baixos, 17 e 14%, respectivamente. Em Madagascar ele \u00e9 igual ao do Brasil, 38%.<\/p>\n<div id=\"comp-pattern-library\" class=\"distinct-component-group container-parrot\">\n<aside class=\"parrot\">O estudo avaliou ainda as amea\u00e7as aos macacos em cada um dos quatro pa\u00edses e o que contribui para que elas existam ou sejam potencializadas. Entre as principais est\u00e3o a perda de habitat, em especial no Brasil, Madagascar e Indon\u00e9sia \u2013 no Congo, \u00e9 a ca\u00e7a comercial de carne de esp\u00e9cies silvestres, no caso aqui, de primatas.<\/aside>\n<\/div>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\"><img loading=\"lazy\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/9EF7\/production\/_102959604_gettyimages-621728850.jpg\" alt=\"Gorila com beb\u00ea no Congo\" width=\"640\" height=\"360\" data-highest-encountered-width=\"624\" \/><span class=\"off-screen\">Direito de imagem<\/span><span class=\"story-image-copyright\">GETTY IMAGES<\/span><\/span><figcaption class=\"media-caption\"><span class=\"off-screen\">Image caption<\/span><span class=\"media-caption__text\">Gorilas s\u00e3o amea\u00e7ados por ca\u00e7adores no Congo<\/span><\/figcaption><\/figure>\n<p>Mas existem v\u00e1rias outras, como doen\u00e7as, grandes popula\u00e7\u00f5es humanas em crescimento, explora\u00e7\u00e3o madeireira, minera\u00e7\u00e3o e extra\u00e7\u00e3o de petr\u00f3leo por corpora\u00e7\u00f5es multinacionais, o com\u00e9rcio ilegal deles como animais de estima\u00e7\u00e3o, as mudan\u00e7as clim\u00e1ticas e at\u00e9 a instabilidade pol\u00edtica e a corrup\u00e7\u00e3o.<\/p>\n<p>Depois disso, os pesquisadores modelaram o conflito por espa\u00e7o entre as atuais \u00e1reas onde vivem os primatas e a proje\u00e7\u00e3o da expans\u00e3o agr\u00edcola (um importante impulsionador da fragmenta\u00e7\u00e3o dos habitats, desmatamento e perda de biodiversidade) nestes quatro pa\u00edses mais ricos nesses animais. Foram elaborados diferentes cen\u00e1rios. No pior deles, as \u00e1reas de ocorr\u00eancia dos primatas at\u00e9 o final do s\u00e9culo 21 encolheriam entre 78% no Brasil, 72% na Indon\u00e9sia, 62% em Madagascar e 32% no Congo.<\/p>\n<p>Hoje, a situa\u00e7\u00e3o \u00e9 pior em Madagascar, com 90% de sua fauna de primatas amea\u00e7ada de extin\u00e7\u00e3o, seguido da Indon\u00e9sia com 83%, Brasil com 39% e Congo com 17%. Para piorar o quadro, mesmo n\u00e3o correndo risco imediato de extin\u00e7\u00e3o, grandes partes das popula\u00e7\u00f5es de macacos dos quatro pa\u00edses est\u00e3o em decl\u00ednio. De novo, a situa\u00e7\u00e3o mais grave \u00e9 a da grande ilha africana, com 97% das esp\u00e9cies diminuindo ano a ano, seguida pela Indon\u00e9sia com 94%, Brasil com 48% e Congo com 39%.<\/p>\n<p>Em Madagascar, uma das esp\u00e9cies mais amea\u00e7adas \u00e9 o l\u00eamure-de-cauda-anelada (<i>Lemur catta<\/i>), famoso pela cauda listrada de preto e branco e pelos olhos esbugalhados em tons alaranjados, principalmente por causa do aumento da minera\u00e7\u00e3o ilegal de cobalto, n\u00edquel e ouro nas florestas, inclusive em \u00e1reas de prote\u00e7\u00e3o ambiental. Na Indon\u00e9sia, o garimpo de ouro tamb\u00e9m \u00e9 respons\u00e1vel por colocar primatas em perigo, como, por exemplo, o macaco-narigudo (<i>Nasalis larvatus<\/i>) e o gib\u00e3o-cinza (<i>Hylobates muelleri<\/i>).<\/p>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\"><img loading=\"lazy\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/1850B\/production\/_102959599_gettyimages-824860718.jpg\" alt=\"L\u00eamure-de-cauda-anelada\" width=\"640\" height=\"360\" data-highest-encountered-width=\"624\" \/><span class=\"off-screen\">Direito de imagem<\/span><span class=\"story-image-copyright\">GETTY IMAGES<\/span><\/span><figcaption class=\"media-caption\"><span class=\"off-screen\">Image caption<\/span><span class=\"media-caption__text\">O l\u00eamure-de-cauda-anelada \u00e9 uma das esp\u00e9cies mais amea\u00e7adas em Madagascar<\/span><\/figcaption><\/figure>\n<p>No mesmo pa\u00eds, a constru\u00e7\u00e3o de uma usina hidrel\u00e9trica no norte da ilha de Sumatra, destruir\u00e1 a floresta Batang Toru, habitat do raro orangotango-de-tapanuli (<i>Pongo tapanuliensis<\/i>), amea\u00e7ando a sua sobreviv\u00eancia. Na Rep\u00fablica Democr\u00e1tica do Congo, a vil\u00e3 \u00e9 a ca\u00e7a, que est\u00e1 acabando com os gorilas (<i>Gorilla gorilla<\/i>) e os bonobos (<i>Pan paniscus<\/i>).<\/p>\n<p>No caso espec\u00edfico do Brasil, em n\u00fameros absolutos, existem hoje 35 esp\u00e9cies amea\u00e7adas de extin\u00e7\u00e3o, em diferentes graus. &#8220;Temos g\u00eaneros completos em risco, como o\u00a0<i>Leontopithecus<\/i>\u00a0(dos micos-le\u00f5es, 4 esp\u00e9cies) e o\u00a0<i>Brachyteles<\/i>\u00a0(dos muriquis, duas)&#8221;, informa Oliveira. &#8220;Al\u00e9m disso, possu\u00edmos duas outras entre as 25 mais amea\u00e7adas do mundo, o\u00a0<i>Alouatta guariba guariba<\/i>\u00a0(bugio ruivo), restrito aos Estados da Bahia e Minas Gerais) e o\u00a0<i>Cebus kaapori<\/i>\u00a0(caiarara), que vive apenas em uma pequena parte do Par\u00e1 e Maranh\u00e3o.&#8221;<\/p>\n<p>H\u00e1 ainda no pa\u00eds algumas esp\u00e9cies na categoria criticamente amea\u00e7adas de extin\u00e7\u00e3o, como o sagui-de-coleira (<i>Saguinus bicolor<\/i>), restrito \u00e0 regi\u00e3o dos munic\u00edpios de Manaus, Rio Preto da Eva e Itacoatiara; o guig\u00f3-da-caatinga (<i>Callicebus barbarabrownae<\/i>), \u00fanico primata end\u00eamico daquele bioma; o cuxi\u00fa-preto (<i>Chiropotes satan\u00e1s<\/i>), que ocorre no leste da Amaz\u00f4nia no arco do desmatamento; e o muriqui-do-norte (<i>Brachyteles hypoxanthus<\/i>), exclusivo da Mata Atl\u00e2ntica, vivendo em fragmentos florestais de Minas Gerais, Esp\u00edrito Santo e da Bahia.<\/p>\n<p>A preocupa\u00e7\u00e3o com a sobreviv\u00eancia dos primatas n\u00e3o humanos se justifica por uma s\u00e9rie de motivos. Eles s\u00e3o de grande import\u00e2ncia para a biodiversidade, pois desempenham diversas fun\u00e7\u00f5es, auxiliam em processos ecol\u00f3gicos e no fornecimento de servi\u00e7os ecossist\u00eamicos.<\/p>\n<p>&#8220;S\u00e3o nossos parentes biol\u00f3gicos vivos mais pr\u00f3ximos, oferecendo insights sobre a evolu\u00e7\u00e3o humana, biologia e comportamento&#8221;, explica Oliveira. &#8220;Esses animais t\u00eam tamb\u00e9m grande import\u00e2ncia cultural e religiosa em muitas sociedades, al\u00e9m de servir como fonte de prote\u00edna, ajudando na subsist\u00eancia de v\u00e1rias popula\u00e7\u00f5es humanas.&#8221;<\/p>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\"><img loading=\"lazy\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/ED17\/production\/_102959606_gettyimages-639723946.jpg\" alt=\"Bonobos no Congo\" width=\"640\" height=\"360\" data-highest-encountered-width=\"624\" \/><span class=\"off-screen\">Direito de imagem<\/span><span class=\"story-image-copyright\">GETTY IMAGES<\/span><\/span><figcaption class=\"media-caption\"><span class=\"off-screen\">Image caption<\/span><span class=\"media-caption__text\">Os bonobos s\u00e3o outra esp\u00e9cie em perigo<\/span><\/figcaption><\/figure>\n<p>Por isso, as consequ\u00eancias de sua extin\u00e7\u00e3o s\u00e3o graves. A perda de primatas n\u00e3o humanos pode desencadear, por exemplo, perda de dispers\u00e3o de sementes de v\u00e1rias esp\u00e9cies de plantas, essenciais para regenera\u00e7\u00e3o de florestas. &#8220;Mas n\u00e3o \u00e9 s\u00f3 isso&#8221;, alerta Oliveira. &#8220;Em alguns lugares, os macacos podem funcionar como atrativo tur\u00edstico e at\u00e9 mesmo serem considerados sagrados.&#8221;<\/p>\n<p>\u00c9 neste contexto que o levantamento do grupo internacional se reveste de import\u00e2ncia. &#8220;Creio que este seja um estudo bastante completo, pois mostra o cen\u00e1rio atual com as amea\u00e7as que os primatas n\u00e3o humanos sofrem, as causas delas e os fatores que contribuem para que elas ocorram&#8221;, diz Oliveira. &#8220;Analisamos essas informa\u00e7\u00f5es em um contexto de crescimento populacional humano, baixo n\u00edvel de desenvolvimento social e desigualdade econ\u00f4mica, instabilidade pol\u00edtica e governan\u00e7a fraca nesses quatro pa\u00edses.&#8221;<\/p>\n<p>Para o tamb\u00e9m bi\u00f3logo Ricardo Dobrovolski, da Universidade Federal da Bahia (UFBA), outro integrante do grupo, o estudo lembra que \u00e9 precioso encontrar formas de conviver com a biodiversidade e garantir o bem-estar para as pessoas. &#8220;Esse bem-estar deve ser pensado tamb\u00e9m para os animais domesticados, como os movimentos em defesa deles t\u00eam lembrado, e para o resto da biodiversidade&#8221;, diz. &#8220;Talvez os primatas, pelo parentesco, nos motivem a iniciar esse processo. Essa \u00e9 a mensagem de fundo do estudo.&#8221;<\/p>\n<p>No final do trabalho, o grupo fez algumas recomenda\u00e7\u00f5es e apontou v\u00e1rias potenciais solu\u00e7\u00f5es para evitar a extin\u00e7\u00e3o dos primatas no Brasil, na Indon\u00e9sia, em Madagascar e no Congo.<\/p>\n<p>A primeira delas \u00e9 expandir as \u00e1reas protegidas. Outras s\u00e3o criar corredores florestais para a migra\u00e7\u00e3o entre subpopula\u00e7\u00f5es atualmente isoladas, incentivar a restaura\u00e7\u00e3o das comunidades florestais naturais, aumentar a seguran\u00e7a alimentar e as oportunidades que beneficiam a qualidade de vida das pessoas, priorizar a sustentabilidade e as energias limpas, e exigir que os pa\u00edses consumidores e as corpora\u00e7\u00f5es internacionais paguem um fundo de sustentabilidade e conserva\u00e7\u00e3o para compensar a sobre-explora\u00e7\u00e3o e os danos ambientais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os primatas do mundo, incluindo gorilas, chimpanz\u00e9s e gib\u00f5es, pedem socorro. Grande parte das 439<\/p>\n","protected":false},"author":2,"featured_media":90580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/primata.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/primata-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/primata-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/primata.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/primata.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/primata.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/primata.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/primata.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/primata.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/primata.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Os primatas do mundo, incluindo gorilas, chimpanz\u00e9s e gib\u00f5es, pedem socorro. Grande parte das 439","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/90579"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=90579"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/90579\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/90580"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=90579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=90579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=90579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}