{"id":90482,"date":"2018-08-19T10:05:04","date_gmt":"2018-08-19T13:05:04","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=90482"},"modified":"2018-08-19T10:05:04","modified_gmt":"2018-08-19T13:05:04","slug":"universidade-holandesa-cria-desafio-com-estufas-autonomas-e-sem-a-intervencao-humana","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/universidade-holandesa-cria-desafio-com-estufas-autonomas-e-sem-a-intervencao-humana\/","title":{"rendered":"Universidade holandesa cria desafio com estufas aut\u00f4nomas e sem a interven\u00e7\u00e3o humana"},"content":{"rendered":"<p><span class=\"intro\"><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/estufa.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-90483\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/estufa-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/estufa-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/estufa.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>C<\/span>omputadores podem produzir uma safra t\u00e3o bem quanto o ser humano? Essa \u00e9 a pergunta que Universidade Wageningen, da Holanda, pretende responder, ao iniciar o Autonomous Greenhouse Challenge (Desafio da Estufa Aut\u00f4noma).<\/p>\n<p>Segundo comunicado da institui\u00e7\u00e3o, o desafio \u00e9 converter conhecimento agron\u00f4mico em algoritmos que permitam aos computadores manejar uma planta\u00e7\u00e3o, mesmo em locais onde houver lacunas de conhecimento. Cinco equipes ter\u00e3o que cultivar pepinos sem a interven\u00e7\u00e3o humana.<\/p>\n<div class=\"teads-inread sm-screen\"><\/div>\n<p>Cada time ter\u00e1 \u00e0 disposi\u00e7\u00e3o uma \u00e1rea de 96 metros quadrados. A produ\u00e7\u00e3o deve ser feita considerando o uso mais eficiente poss\u00edvel de \u00e1gua, nutri\u00e7\u00e3o e energia para atingir o m\u00e1ximo poss\u00edvel de produtividade.<\/p>\n<p>Os algor\u00edtimos j\u00e1 vem sendo desenvolvidos, com base em par\u00e2metros de temperatura, quantidade de luz, concentra\u00e7\u00e3o de carbono, aduba\u00e7\u00e3o e diversos outros relativos ao cultivo do pepino. A partir de dados coletados tamb\u00e9m de forma remota por sensores instalados nas estufas, os c\u00f3digos ser\u00e3o ajustados.<\/p>\n<p>\u201cA meta \u00e9 fazer com que o programa possa substituir gradativamente a tomada de decis\u00e3o por parte do ser humano\u201d, diz, no comunicado da Universidade, o chefe da equipe de pesquisa em horticultura, Slike Hemming.<\/p>\n<p>Hemming diz ainda que o pepino foi a cultura escolhida por ser de crescimento r\u00e1pido e por ser afetado rapidamente por algum eventual erro de manejo. Desta forma, \u00e9 poss\u00edvel obter uma grande quantidade de informa\u00e7\u00f5es pelo per\u00edodo de quatro meses.<\/p>\n<p>Ainda de acordo com o comunicado, a universidade se compromete a dar todo o apoio tecnol\u00f3gico e de informa\u00e7\u00e3o necess\u00e1rios. Funcion\u00e1rios da institui\u00e7\u00e3o ficar\u00e3o respons\u00e1veis pela colheita e pelo fornecimento das informa\u00e7\u00f5es sobre a produ\u00e7\u00e3o \u00e0s equipes.<\/p>\n<p>Os dados ser\u00e3o avaliados por um juri formado por pesquisadores e professores das \u00e1reas de agronomia e tecnologia da informa\u00e7\u00e3o. O projeto tamb\u00e9m inclui uma estufa de refer\u00eancia, que ser\u00e1 mantida por profissionais da universidade e produtores holandeses de pepino.<\/p>\n<p>O desafio poder\u00e1 ser acompanhado\u00a0<a href=\"http:\/\/www.autonomousgreenhouses.com\/\"><strong>via internet<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Computadores podem produzir uma safra t\u00e3o bem quanto o ser humano? Essa \u00e9 a pergunta<\/p>\n","protected":false},"author":2,"featured_media":90483,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/estufa.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/estufa-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/estufa-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/estufa.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/estufa.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/estufa.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/estufa.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/estufa.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/estufa.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/08\/estufa.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Computadores podem produzir uma safra t\u00e3o bem quanto o ser humano? Essa \u00e9 a pergunta","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/90482"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=90482"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/90482\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/90483"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=90482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=90482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=90482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}