{"id":82537,"date":"2018-03-31T00:00:56","date_gmt":"2018-03-31T03:00:56","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=82537"},"modified":"2018-03-31T15:57:42","modified_gmt":"2018-03-31T18:57:42","slug":"projeto-educaocean","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/projeto-educaocean\/","title":{"rendered":"Projeto EducaOcean"},"content":{"rendered":"<p><img class=\"alignleft\" src=\"https:\/\/static.vakinha.com.br\/uploads\/vakinha\/image\/149568\/cover_logo.jpg\" alt=\"Resultado de imagem para Projeto EducaOcean\" \/><\/p>\n<p>Projeto de extens\u00e3o do Departamento de Oceanografia da Universidade Federal de Pernambuco (UFPE), o EducaOcean tem por finalidade promover conhecimento e aplica\u00e7\u00f5es com temas pertinentes \u00e0 Oceanografia e Educa\u00e7\u00e3o Ambiental atrav\u00e9s de diferentes meios integrando-os \u00e0 sociedade.<\/p>\n<p><strong>Miss\u00e3o<\/strong><\/p>\n<p>Abordagem de variados temas relacionados \u00e0 Oceanografia Socioambiental visando a aplica\u00e7\u00e3o dos conceitos da Educa\u00e7\u00e3o Ambiental. Executar atividades de conscientiza\u00e7\u00e3o ambiental junto \u00e0 sociedade.<\/p>\n<p>O projeto de extens\u00e3o EducaOcean \u00e9 composto principalmente por discentes do curso de Oceanografia da UFPE entre outras \u00e1reas afins e, volunt\u00e1rios do grupo Oceano \u00e0 Vista (O\u00e0V), que possui atua\u00e7\u00e3o nacional.<\/p>\n<p>O mesmo tem o intuito de abordar temas relacionados \u00e0 Oceanografia Socioambiental (OS), atuando como um agente de conex\u00e3o entre a sociedade e o meio acad\u00eamico visando a aplica\u00e7\u00e3o dos conceitos de Educa\u00e7\u00e3o Ambiental (EA) na preserva\u00e7\u00e3o dos ambientes, sendo estes ambientes costeiros e estuarinos de Pernambuco. O projeto visa atuar atrav\u00e9s de duas vertentes, promovendo atividades com alunos tanto do ensino fundamental quanto m\u00e9dio, al\u00e9m de realizar interven\u00e7\u00f5es de limpeza de praias, mangues e estu\u00e1rios junto \u00e0 sociedade para a retirada do lixo e promo\u00e7\u00e3o da conscientiza\u00e7\u00e3o ambiental.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Projeto de extens\u00e3o do Departamento de Oceanografia da Universidade Federal de Pernambuco (UFPE), o EducaOcean<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"cream-magazine-thumbnail-2":false,"cream-magazine-thumbnail-3":false,"cream-magazine-thumbnail-4":false},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Projeto de extens\u00e3o do Departamento de Oceanografia da Universidade Federal de Pernambuco (UFPE), o EducaOcean","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/82537"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=82537"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/82537\/revisions"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=82537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=82537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=82537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}