{"id":82533,"date":"2018-03-31T15:28:59","date_gmt":"2018-03-31T18:28:59","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=82533"},"modified":"2018-03-31T15:28:59","modified_gmt":"2018-03-31T18:28:59","slug":"tailandesas-criam-pratos-descartaveis-feitos-de-folhas","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/tailandesas-criam-pratos-descartaveis-feitos-de-folhas\/","title":{"rendered":"Tailandesas criam pratos descart\u00e1veis feitos de folhas"},"content":{"rendered":"<div id=\"attachment_33766\" class=\"wp-caption aligncenter\">\n<p><img loading=\"lazy\" class=\"size-full wp-image-33766\" src=\"http:\/\/www.pensamentoverde.com.br\/wp-content\/uploads\/2016\/04\/1-Pratos-Descart%C3%A1veis.jpg\" alt=\"\" width=\"640\" height=\"425\" \/><\/p>\n<p class=\"wp-caption-text\">Prato suporta \u00e1gua quente e n\u00e3o vaza.<\/p>\n<\/div>\n<p>Devido aos graves problemas ambientais causados pelos seres humanos a sustentabilidade passou a ser essencial para o nosso futuro e das pr\u00f3ximas gera\u00e7\u00f5es. Sem a cultura do reaproveitamento e do consumo consciente, tudo o que \u00e9 produzido requer o uso de recursos naturais e isso gera um grande impacto ao meio ambiente.<\/p>\n<p>Certos materiais demoram milhares de anos para se decompor. Um bom exemplo \u00e9 o isopor, t\u00e3o usado como embalagem para alimentos, que leva em torno de 500 anos para desaparecer por completo na natureza.<\/p>\n<p>Pensando nisso um grupo de pesquisadores da Universidade de Naresuan, na Tail\u00e2ndia, desenvolveu um prato descart\u00e1vel feito de folhas de \u00e1rvores. O projeto do prato durou mais de um ano e seu objetivo \u00e9 substituir o isopor sem perder a qualidade no uso.<\/p>\n<p>Samorn Hiranpraditsakul, professor de engenharia industrial, disse em entrevista ao site Bangkok Post que a inspira\u00e7\u00e3o para a cria\u00e7\u00e3o do recipiente ecol\u00f3gico veio de uma visita a um templo no Norte, onde viu as enormes pilhas de descarte.<\/p>\n<h2><strong>Benef\u00edcios do prato de folhas<\/strong><\/h2>\n<p>Eles suportam \u00e1gua quente, n\u00e3o vazam e se degradam naturalmente depois de serem descartados, pois n\u00e3o afetam negativamente o solo e outros organismos naturais. Para que ele ficasse resistente, foi utilizado amido no lugar de verniz, deixando o utens\u00edlio mais firme e com brilho.<\/p>\n<p>Segundo os pesquisadores foram muitas tentativas erradas at\u00e9 acertar o material ideal. As folhas que apresentaram melhor desempenho s\u00e3o nativas de tr\u00eas tipos de \u00e1rvores diferentes: Tectona Grandis, Petchara Chaowarat e Ficus Benghalensis.<\/p>\n<p>Segundo Sitintip Tantanee, professor na universidade e integrante da equipe de engenharia que desenvolveu o produto, a inten\u00e7\u00e3o \u00e9 trabalhar com as autoridades municipais para que os eventos oficiais troquem, o quanto antes, o isopor pelos pratos feitos de folhas.<\/p>\n<p>Curiosidade: os indianos j\u00e1 t\u00eam a tradi\u00e7\u00e3o de transformar folhas em recipientes. Um exemplo \u00e9 o Patravali, muito utilizado em jantares tradicionais, festivais e celebra\u00e7\u00f5es. Os pratos s\u00e3o feitos de grandes folhas secas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prato suporta \u00e1gua quente e n\u00e3o vaza. Devido aos graves problemas ambientais causados pelos seres<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"cream-magazine-thumbnail-2":false,"cream-magazine-thumbnail-3":false,"cream-magazine-thumbnail-4":false},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Prato suporta \u00e1gua quente e n\u00e3o vaza. Devido aos graves problemas ambientais causados pelos seres","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/82533"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=82533"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/82533\/revisions"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=82533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=82533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=82533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}