{"id":82491,"date":"2018-03-31T13:30:32","date_gmt":"2018-03-31T16:30:32","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=82491"},"modified":"2018-03-30T20:36:02","modified_gmt":"2018-03-30T23:36:02","slug":"com-sindrome-de-apert-menina-ja-passou-por-seis-cirurgias-antes-dos-dois-anos","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/com-sindrome-de-apert-menina-ja-passou-por-seis-cirurgias-antes-dos-dois-anos\/","title":{"rendered":"Com s\u00edndrome de Apert, menina j\u00e1 passou por seis cirurgias antes dos dois anos"},"content":{"rendered":"<div id=\"noticia\">\n<p class=\"\"><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/sindrome.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-82492\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/sindrome-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/sindrome-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/sindrome.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Apesar da pouca idade, Isadora Maria Teodora Henrique Fernandes j\u00e1 \u00e9 uma verdadeira guerreira. A pequena nasceu com s\u00edndrome de Apert e, aos dois anos de idade, j\u00e1 passou por seis cirurgias. O diagn\u00f3stico s\u00f3 veio ap\u00f3s o nascimento, mas a m\u00e3e, a advogada Graciela Mendanha Sobrinho, j\u00e1 sabia que sua filha nasceria com alguma condi\u00e7\u00e3o especial.<\/p>\n<div id=\"ad_mrec_intext\" class=\"publicidade advertising-box\" data-google-query-id=\"CKqj_YSaldoCFUsmHwodRLsCmg\"><\/div>\n<p class=\"\">Durante a gesta\u00e7\u00e3o, Graciela realizou uma s\u00e9rie de exames que indicaram que a filha possu\u00eda a cabe\u00e7a com tamanho maior e m\u00e1-forma\u00e7\u00e3o em algumas partes do corpo. Depois que nasceu, ela foi levada ao geneticista e a\u00a0<strong>s\u00edndrome de Apert<\/strong>\u00a0foi confirmada. Em todo o mundo, estima-se que uma a cada 90 mil crian\u00e7as nascidas vivas sejam atingidas.<\/p>\n<p>A condi\u00e7\u00e3o \u00e9 resultado de uma muta\u00e7\u00e3o gen\u00e9tica rara, em que o cr\u00e2nio do portador n\u00e3o se desenvolve normalmente, alterando a estrutura do rosto. A crian\u00e7a tamb\u00e9m pode ter problemas de sa\u00fade e, al\u00e9m disso, os dedos das m\u00e3os e dos p\u00e9s nascem unidos. Dessa forma, para garantir que o portador tenha qualidade de vida, \u00e9 necess\u00e1rio passar alguns procedimentos cir\u00fargicos.<\/p>\n<h3>Quanto antes realizar as cirurgias, melhor<\/h3>\n<figure class=\"foto-legenda gd12\"><img loading=\"lazy\" class=\"\" src=\"http:\/\/statig0.akamaized.net\/bancodeimagens\/1d\/9j\/k7\/1d9jk7o3wy5twegiocjsgptyw.jpg\" alt=\"Montagem mostra as m\u00e3os de Isadora antes da cirurgia e depois do procedimento, com os cinco dedos em cada m\u00e3o\" width=\"639\" height=\"400\" \/><figcaption class=\"undefined\"><cite>Arquivo pessoal<\/cite><\/p>\n<div class=\"undefined\">Montagem mostra as m\u00e3os de Isadora antes da cirurgia e depois do procedimento, com os cinco dedos em cada m\u00e3o<\/div>\n<\/figcaption><\/figure>\n<p class=\" \">Com tr\u00eas meses de vida, a menina realizou a primeira cirurgia das m\u00e3os. A segunda, por sua vez, foi aos seis meses, quando ela passou a ter os dez dedos. \u201cEsta precocidade garante aos pacientes a obten\u00e7\u00e3o dos cinco dedos em cada m\u00e3o, com grande ganho funcional e est\u00e9tico\u201d, explica Cassio Eduardo Raposo do Amaral, cirurgi\u00e3o pl\u00e1stico e vice-presidente do hospital SOBRAPAR, em Campinas.<\/p>\n<p>Amaral foi o m\u00e9dico respons\u00e1vel pelos procedimentos de Isadora. De acordo com o especialista, a primeira cirurgia craniana deve ser feita antes do primeiro ano de vida, como foi o caso da menina, operada aos oitos meses. \u201cO objetivo \u00e9 oferecer espa\u00e7o para o c\u00e9rebro e evitar a deteriora\u00e7\u00e3o do desenvolvimento neurocognitivo da crian\u00e7a com a s\u00edndrome\u201d, relata.<\/p>\n<p>Em rela\u00e7\u00e3o aos p\u00e9s, a primeira opera\u00e7\u00e3o ocorreu aos dez meses, e a segunda, aos 12 meses. A mais recente, em mar\u00e7o deste ano, foi para fazer a corre\u00e7\u00e3o da fenda palatina.\u00a0A pr\u00f3xima deve acontecer na face, aos oito ou nove anos. \u201cA quantidade de cirurgias durante a vida do paciente depende da gravidade de cada apresenta\u00e7\u00e3o cl\u00ednica\u201d, completa o cirurgi\u00e3o pl\u00e1stico.<\/p>\n<h3>Causas e caracter\u00edsticas da s\u00edndrome de Apert<\/h3>\n<p>A causa \u00e9 uma muta\u00e7\u00e3o no gene FGFR2. \u201cEm quase todos os casos, \u00e9 um acidente gen\u00e9tico que ocorre durante a gesta\u00e7\u00e3o. Pode ser de origem heredit\u00e1ria, ligada a um gene autoss\u00f4mico dominante ou ser uma nova muta\u00e7\u00e3o espor\u00e1dica\u201d, explica o especialista.<\/p>\n<p>Entre as\u00a0<strong>caracter\u00edsticas<\/strong>\u00a0, os portadores possuem aus\u00eancia de estruturas cerebrais, anomalias card\u00edacas, pulmonares, dermatol\u00f3gicas e oftalmol\u00f3gicas.<\/p>\n<p>Tratamento<\/p>\n<figure class=\"foto-legenda gd12\"><img loading=\"lazy\" class=\"\" src=\"http:\/\/statig3.akamaized.net\/bancodeimagens\/2k\/gt\/4b\/2kgt4btorrhy3rlyk97q2clkk.jpg\" alt=\"O cirurgi\u00e3o pl\u00e1stico explica que, com o tratamento adequado, \u00e9 poss\u00edvel viver normalmente; fisioterapia est\u00e1 na lista\" width=\"639\" height=\"400\" \/><figcaption class=\"undefined\"><cite>shutterstock<\/cite><\/p>\n<div class=\"undefined\">O cirurgi\u00e3o pl\u00e1stico explica que, com o tratamento adequado, \u00e9 poss\u00edvel viver normalmente; fisioterapia est\u00e1 na lista<\/div>\n<\/figcaption><\/figure>\n<p>O acompanhamento dos pacientes com s\u00edndrome de Apert \u00e9 muito complexo e multidisciplinar, conforme explica o especialista. Isadora faz\u00a0<strong>fisioterapia<\/strong>\u00a0, terapia ocupacional, fonoaudiologia e outras atividades, como bal\u00e9 e nata\u00e7\u00e3o, tr\u00eas vezes por semana. \u201cTem que estimular. A articula\u00e7\u00e3o do bra\u00e7o \u00e9 mais comprometida e precisa fazer exerc\u00edcio para n\u00e3o atrofiar\u201d, conta a m\u00e3e.<\/p>\n<p>No hospital SOBRAPAR, o portador consegue tratamento gratuito. O local conta com uma equipe de profissionais aptos para a reabilita\u00e7\u00e3o dos pacientes, como psic\u00f3logos, fonoaudi\u00f3logos, otorrinos, neurologistas, ortodontistas e assistentes sociais.<\/p>\n<h3>Conscientiza\u00e7\u00e3o<\/h3>\n<p>Para conscientizar as pessoas e reduzir o preconceito em torno da s\u00edndrome, Graciela resolveu criar a\u00a0<a href=\"http:\/\/www.absa.com.br\/\" target=\"_blank\">Associa\u00e7\u00e3o Brasileira da S\u00edndrome de Apert<\/a>\u00a0.\u00a0 A ideia surgiu quando a filha tinha dois meses de vida. Segundo Graciela, um dos objetivos \u00e9 acabar com essa ideia de que a crian\u00e7a \u00e9 \u201ccoitadinha\u201d e mostra que ela vai fazer tudo que os pais estimularem. Al\u00e9m disso,\u00a0 deseja tornar a condi\u00e7\u00e3o conhecida e ajudar outras fam\u00edlias.<\/p>\n<p>Graciela deu andamento ao plano em outubro de 2017 e, no come\u00e7o deste ano, registrou a associa\u00e7\u00e3o e, agora, est\u00e1 montando a equipe.\u00a0Amaral \u00e9 o padrinho e, como madrinha, escolheu Olivia Byington, autora do livro &#8220;O que \u00e9 que ele tem&#8221;, que conta a hist\u00f3ria de Jo\u00e3o, nascido em mar\u00e7o de 1981 e portador da\u00a0<strong>s\u00edndrome de Apert.<\/strong>\u00a0O rapaz \u00e9 irm\u00e3o do ator e humorista Gregorio Duvivier.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Apesar da pouca idade, Isadora Maria Teodora Henrique Fernandes j\u00e1 \u00e9 uma verdadeira guerreira. A<\/p>\n","protected":false},"author":2,"featured_media":82492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/sindrome.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/sindrome-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/sindrome-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/sindrome.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/sindrome.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/sindrome.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/sindrome.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/sindrome.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/sindrome.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/sindrome.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Apesar da pouca idade, Isadora Maria Teodora Henrique Fernandes j\u00e1 \u00e9 uma verdadeira guerreira. A","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/82491"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=82491"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/82491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/82492"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=82491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=82491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=82491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}