{"id":82201,"date":"2018-03-25T16:54:46","date_gmt":"2018-03-25T19:54:46","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=82201"},"modified":"2018-03-25T17:08:37","modified_gmt":"2018-03-25T20:08:37","slug":"maior-duna-isolada-do-sudeste-brasileiro-e-cartao-postal-de-cabo-frio","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/maior-duna-isolada-do-sudeste-brasileiro-e-cartao-postal-de-cabo-frio\/","title":{"rendered":"Maior duna isolada do Sudeste brasileiro \u00e9 cart\u00e3o postal de Cabo Frio"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"\" src=\"http:\/\/s2.glbimg.com\/aIQAm-Gun3MF4ixitRGAoQeQXqQ=\/1200x630\/filters:max_age(3600)\/s02.video.glbimg.com\/deo\/vi\/25\/57\/6605725\" alt=\"Resultado de imagem para Maior duna isolada do Sudeste brasileiro \u00c3\u00a9 cart\u00c3\u00a3o postal de Cabo Frio\" width=\"640\" height=\"336\" \/><\/p>\n<p>L\u00e1 vai a equipe do Globo Rep\u00f3rter explorar um &#8220;deserto&#8221;. Os visitantes s\u00f3 podem ir at\u00e9 o local caminhando. Carros e ve\u00edculos como motos e quadriciclos s\u00e3o proibidos, a n\u00e3o ser &#8211; \u00e9 claro &#8211; os que s\u00e3o usados pelos fiscais do Parque Estadual da Costa do Sol.<\/p>\n<div class=\"saibamais componente_materia\">A equipe anda sobre uma gigante e nem parece que est\u00e1 subindo 33 metros. \u00c9 a Dama Branca, cart\u00e3o postal de Cabo Frio. A maior duna isolada do Sudeste brasileiro. Um patrim\u00f4nio reconhecido pela import\u00e2ncia. \u201cEla serve como uma camada, que protege o manancial de \u00e1gua que fica l\u00e1 por baixo\u201d, explica Maycon Victorino Cardoso, engenheiro ambiental.<\/div>\n<p>Um enorme ba\u00fa, guardando o tesouro mais precioso! Debaixo dela tem \u00e1gua pot\u00e1vel, \u00e1gua doce.<\/p>\n<p>Gr\u00e3os de areia em movimento, protegendo toda a restinga. O sol ali \u00e9 a fonte de energia. A restinga n\u00e3o vive sem o sol. Nem a restinga, nem a Costa do Sol.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00e1 vai a equipe do Globo Rep\u00f3rter explorar um &#8220;deserto&#8221;. Os visitantes s\u00f3 podem ir<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"cream-magazine-thumbnail-2":false,"cream-magazine-thumbnail-3":false,"cream-magazine-thumbnail-4":false},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"L\u00e1 vai a equipe do Globo Rep\u00f3rter explorar um &#8220;deserto&#8221;. Os visitantes s\u00f3 podem ir","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/82201"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=82201"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/82201\/revisions"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=82201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=82201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=82201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}