{"id":82121,"date":"2018-03-25T15:00:56","date_gmt":"2018-03-25T18:00:56","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=82121"},"modified":"2018-03-25T09:42:38","modified_gmt":"2018-03-25T12:42:38","slug":"dr-theo-webert-destaca-cinco-gorduras-que-podem-melhorar-a-saude","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/dr-theo-webert-destaca-cinco-gorduras-que-podem-melhorar-a-saude\/","title":{"rendered":"Dr. Theo Webert destaca cinco gorduras que podem melhorar a sa\u00fade"},"content":{"rendered":"<div class=\"itemIntroText\">\n<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/abacate.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-82122\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/abacate-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/abacate-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/abacate.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>O termo \u201cgordura\u201d, apesar de hoje ser reconhecido tamb\u00e9m em contextos saud\u00e1veis, ainda carrega o peso de ser relacionado a problemas de sa\u00fade. No entanto, h\u00e1 sim as gorduras boas que ajudam numa dieta equilibrada e no reequil\u00edbrio do organismo. O m\u00e9dico especialista em nutrologia e qualidade de vida, Theo Webert, diz que a gordura boa \u00e9 necess\u00e1ria para a fun\u00e7\u00e3o cerebral, a produ\u00e7\u00e3o de horm\u00f4nios, metabolismo, perda de peso, energia, fun\u00e7\u00e3o imune e resposta inflamat\u00f3ria.<\/p>\n<\/div>\n<div class=\"itemFullText\">\n<p>\u201cSessenta por cento do c\u00e9rebro \u00e9 praticamente constitu\u00eddo por gordura. A gordura que comemos literalmente alimenta o nosso c\u00e9rebro, ajudando nossas fun\u00e7\u00f5es neurol\u00f3gicas e a clareza mental que nos permite viver de forma saud\u00e1vel\u201d, afirma o especialista.<\/p>\n<p>O m\u00e9dico destaca cinco fontes naturais de gorduras consideradas boas para o organismo:<\/p>\n<p>1 &#8211; Abacate<\/p>\n<p>O abacate \u00e9 dos principais alimentos ricos em gordura positiva. Se embrulhado como um burrito em uma folha de nori, com brotos e verduras cultivadas, pode ser uma boa op\u00e7\u00e3o de fonte de nutrientes. Por ser de r\u00e1pido consumo, pode ainda ser descascado, picado e armazenado no congelador. Antes de consumido, pode ser batido no liquidificador com cacau e at\u00e9 mesmo leite de am\u00eandoas.<\/p>\n<p>2 &#8211; Ghee, a manteiga caseira<\/p>\n<p>Conhecido como a manteiga caseira, na verdade trata-se de um \u00f3leo purificado da pr\u00f3pria manteiga, onde toda a \u00e1gua e os elementos s\u00f3lidos e toxinas da gordura do leite e lactose s\u00e3o completamente removidos. Ghee \u00e9 um \u00f3leo de cozinha maravilhoso, que suporta o calor, mas pode ser usado tamb\u00e9m num misto de ch\u00e1, onde utilizamos tulsi, adicionando uma colher de ghee, \u00e1gua de rosas, mel ou est\u00e9via\u201d.<\/p>\n<p>3 &#8211; \u00d3leo de coco<\/p>\n<p>O \u00f3leo de coco \u00e9 excelente para cozinhar, uma vez que tamb\u00e9m pode suportar o calor. H\u00e1 quem utilize o \u00f3leo tamb\u00e9m nas receitas de uma barra de chocolate energ\u00e9tico. Ele se une ao cacau, cogumelo reishi, cordyceps (fungo que com propriedades de combater o c\u00e2ncer) e um toque de mel. Para muitos, este \u00e9 o impulso di\u00e1rio de energia.<\/p>\n<p>4 &#8211; Nozes e sementes<\/p>\n<p>As sementes de c\u00e2nhamo, am\u00eandoas, sementes de ab\u00f3bora, castanha do Par\u00e1, semente de linha\u00e7a, castanhas, sementes de gergelim, avel\u00e3s, nozes, macad\u00e2mia e sementes de chia comp\u00f5em uma boa parte de uma dieta equilibrada, ao lado de vegetais verdes. Leites produzidos a partir destas nozes, castanhas e sementes podem ser grandes fontes nutritivas numa alimenta\u00e7\u00e3o balanceada. H\u00e1 tamb\u00e9m como usar para receitas com panquecas, pur\u00ea cremoso de batatas-doces, pudim de chia, macarr\u00e3o e at\u00e9 queijo.<\/p>\n<p>5 &#8211; Azeitonas e azeite de oliva<\/p>\n<p>As azeitonas e, obviamente, o azeite de oliva s\u00e3o uma excelente fonte de gorduras boas. Os \u00e1cidos gordos monoinsaturados presentes no Azeite de Oliva ajudam na redu\u00e7\u00e3o do colesterol mau (LDL) no corpo, reduzindo assim o bloqueio de art\u00e9rias e forma\u00e7\u00e3o praga. Ele tamb\u00e9m ajuda na redu\u00e7\u00e3o da coagula\u00e7\u00e3o do sangue, al\u00e9m de ser tamb\u00e9m uma boa fonte de antioxidantes como fen\u00f3is e Vitamina E, que ajudam a manter o cora\u00e7\u00e3o forte e funcionando corretamente.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O termo \u201cgordura\u201d, apesar de hoje ser reconhecido tamb\u00e9m em contextos saud\u00e1veis, ainda carrega o<\/p>\n","protected":false},"author":2,"featured_media":82122,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/abacate.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/abacate-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/abacate-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/abacate.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/abacate.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/abacate.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/abacate.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/abacate.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/abacate.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/03\/abacate.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"O termo \u201cgordura\u201d, apesar de hoje ser reconhecido tamb\u00e9m em contextos saud\u00e1veis, ainda carrega o","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/82121"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=82121"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/82121\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/82122"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=82121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=82121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=82121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}