{"id":80403,"date":"2018-02-19T09:10:51","date_gmt":"2018-02-19T12:10:51","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=80403"},"modified":"2018-02-19T09:14:26","modified_gmt":"2018-02-19T12:14:26","slug":"brasileira-vira-destaque-internacional-com-projeto-que-substitui-animais-por-pele-3d-em-testes-com-cosmeticos","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/brasileira-vira-destaque-internacional-com-projeto-que-substitui-animais-por-pele-3d-em-testes-com-cosmeticos\/","title":{"rendered":"Brasileira vira destaque com projeto que substitui animais por pele 3D em testes com cosm\u00e9ticos"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/carolina.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-80404\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/carolina-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/carolina-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/carolina.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>&#8216;Imposs\u00edvel conceber que criaturas t\u00e3o cheias de amor, de inoc\u00eancia e de confian\u00e7a sejam usadas pra tais fins&#8217;, diz a curitibana Carolina Motter.<\/p>\n<p>\u201cAl\u00e9m de todos os argumentos cient\u00edficos para n\u00e3o usar animais em testes cosm\u00e9ticos, para mim, \u00e9 imposs\u00edvel conceber que criaturas t\u00e3o cheias de amor, de inoc\u00eancia e de confian\u00e7a sejam usadas pra tais fins\u201d, acredita a curitibana Carolina Motter Catarino, de 28 anos.<\/p>\n<p>Doutoranda no Instituto Polit\u00e9cnico Rensselaer, em Troy, no estado de Nova York, ela trabalha no desenvolvimento de modelos de pele humana usando a tecnologia de impress\u00e3o 3D.<\/p>\n<p>A pesquisa \u2013 uma das pioneiras na \u00e1rea \u2013 \u00e9 uma chance de dar fim ao\u00a0<a href=\"https:\/\/www.anda.jor.br\/2018\/02\/ativistas-iluminam-ponte-em-protesto-contra-testes-em-animais\/\">uso de animais em testes de laborat\u00f3rios<\/a>.<\/p>\n<p>Em novembro do ano passado, o projeto de Carolina virou destaque internacional. Ela venceu o pr\u00eamio Jovem Pesquisador, na categoria Am\u00e9ricas, concedido pela\u00a0<a href=\"https:\/\/www.anda.jor.br\/2017\/02\/conheca-os-juizes-do-lush-spring-prize\/\">Lush<\/a>\u00a0\u2013 fabricante e revendedora de cosm\u00e9ticos artesanais.<\/p>\n<p>Essa foi a maior premia\u00e7\u00e3o que Carolina j\u00e1 recebeu, mas n\u00e3o foi a \u00fanica.<\/p>\n<p>\u201cO pr\u00eamio \u00e9 concedido a jovens que trabalhem em projetos que t\u00eam como objetivo eliminar o uso de animais em testes de produtos qu\u00edmicos\u201d, explica.<\/p>\n<p>Os cerca de R$ 45 mil que recebeu, ela revela, devem ser investidos na pesquisa e na sua forma\u00e7\u00e3o como cientista.<\/p>\n<p>Depois do reconhecimento pelo estudo, a curitibana garante ter percebido que os brasileiros t\u00eam se importado, cada vez mais, com a prote\u00e7\u00e3o aos animais e com o desenvolvimento cient\u00edfico.<\/p>\n<p>\u201cTem sido muito legal ver as pessoas demonstrando apoio ao projeto, mesmo com o momento que o Brasil vive, com tantos cortes na ci\u00eancia e na educa\u00e7\u00e3o\u201d, diz.<\/p>\n<div id=\"attachment_708307\" class=\"wp-caption aligncenter\" style=\"width: 649px;\">\n<p><img loading=\"lazy\" class=\" wp-image-708307 ing ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed lazyloaded\" src=\"https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-2.jpg\" sizes=\"(max-width: 600px) 100vw, 600px\" srcset=\"https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-2.jpg 600w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-2-300x200.jpg 300w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-2-250x167.jpg 250w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-2-100x67.jpg 100w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-2-177x118.jpg 177w\" alt=\"\" width=\"639\" height=\"426\" data-lazy-src=\"https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-2.jpg\" data-lazy-srcset=\"https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-2.jpg 600w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-2-300x200.jpg 300w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-2-250x167.jpg 250w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-2-100x67.jpg 100w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-2-177x118.jpg 177w\" data-lazy-sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p class=\"wp-caption-text\">Em novembro de 2017, Carolina foi uma dos cinco vencedores do pr\u00eamio Jovem Pesquisador, na categoria Am\u00e9ricas, concedido pela Lush (Foto: Carolina Motter\/Arquivo pessoal)<\/p>\n<\/div>\n<p><strong>Trajet\u00f3ria acad\u00eamica<\/strong><\/p>\n<p>Carolina \u00e9 de Curitiba e foi na capital paranaense mesmo que ela deu in\u00edcio \u00e0 vida acad\u00eamica. Na Universidade Federal do Paran\u00e1 (UFPR), a maior do Paran\u00e1, ela cursou Engenharia de Bioprocessos e Biotecnologia.<\/p>\n<p>Ainda na gradu\u00e7\u00e3o, uma oportunidade de interc\u00e2mbio surgiu e fez toda a diferen\u00e7a na carreira da curitibana.<\/p>\n<p>Ela estudou seis meses na Universidade de Tecnologia de Compi\u00e8gne, na Fran\u00e7a. No semestre seguinte, estagiou na L\u2019Or\u00e9al Paris.<\/p>\n<p>Foi, ent\u00e3o, que teve a chance de conhecer e trabalhar com os modelos de pele que a empresa usa quando testa os seus produtos.<\/p>\n<p>\u201cEu me apaixonei pela \u00e1rea e pela ideia de desenvolver e testar novos produtos cosm\u00e9ticos com m\u00e9todos alternativos ao uso de animais\u201d, lembra.<\/p>\n<p>De volta ao Brasil, depois de formada na UFPR, Carolina continuou investindo no assunto.<\/p>\n<p>Em S\u00e3o Paulo, ela fez mestrado em uma das melhores institui\u00e7\u00f5es de ensino superior do pa\u00eds \u2013 a Universidade de S\u00e3o Paulo (USP).<\/p>\n<p>\u201cNa USP, meu projeto era justamente ajudar a desenvolver um novo modelo de pele para ser usado como plataforma para a avalia\u00e7\u00e3o de riscos e efic\u00e1cia de produtos\u201d, explica.<\/p>\n<p>Quando ainda era estudante de mestrado, Carolina participou do Congresso Mundial de M\u00e9todos Alternativos e Uso de Animais nas Ci\u00eancias da Vida, em Praga, na Rep\u00fablica Tcheca.<\/p>\n<p>No evento, a curitibana conheceu pesquisadores e grupos de pesquisa que estavam trabalhando na \u00e1rea.<\/p>\n<p>\u201cUm dos trabalhos apresentados foi justamente o uso da impressora 3D para reconstruir modelos de pele, que \u00e9 o projeto do meu atual grupo de pesquisa\u201d, relata.<\/p>\n<p>Ao fim da apresenta\u00e7\u00e3o, ela foi logo conversar com o respons\u00e1vel pelo estudo e demonstrar interesse em fazer parte da equipe.<\/p>\n<p>J\u00e1 no ano seguinte, Carolina p\u00f4de, de fato, dar continuidade ao sonho: ela conseguiu uma bolsa de estudos nos Estados Unidos, atrav\u00e9s do programa Ci\u00eancias sem Fronteiras.<\/p>\n<p>No Instituto Polit\u00e9cnico Rensselaer, uma prestigiada institui\u00e7\u00e3o norte-americana de ensino superior, a curitibana deu in\u00edcio ao doutorado, trabalhando no desenvolvimento de modelos de peles por meio da impress\u00e3o 3D.<\/p>\n<p>Desde 2015 em Troy, ela espera obter a titula\u00e7\u00e3o at\u00e9 o fim de 2019.<\/p>\n<p><strong>A pesquisa<\/strong><\/p>\n<p>Carolina explica que as bioimpressoras com as quais trabalha funcionam de maneira semelhante \u00e0s\u00a0<a href=\"https:\/\/www.anda.jor.br\/2015\/11\/tecnologia-3d-uma-nova-oportunidade-para-os-animais\/\">impressoras 3D<\/a>\u00a0dispon\u00edveis no mercado. O equipamento \u00e9 capaz de posicionar precisamente as tintas biol\u00f3gicas \u2013 que s\u00e3o formadas por biomateriais e c\u00e9lulas humanas.<\/p>\n<p>\u201cTodo esse processo de impress\u00e3o da pele come\u00e7a com o isolamento das c\u00e9lulas a partir de peles humanas doadas\u201d, explica.<\/p>\n<p>Com a quantia certa de c\u00e9lulas, as diferentes biotintas s\u00e3o preparadas. S\u00e3o elas que d\u00e3o origem \u00e0s diferentes estruturas da pele.<\/p>\n<p>Em seguida, as biotintas s\u00e3o transferidas para os cartuchos da bioimpressora e, atrav\u00e9s de um software que cont\u00e9m o modelo 3D a ser reproduzido, a pele \u00e9 impressa.<\/p>\n<p>\u201cDepois da impress\u00e3o, a gente mant\u00e9m a pele em uma incubadora por 14 dias para que as c\u00e9lulas se diferenciem e d\u00eaem origem ao modelo que se assemelha ao humano. Essa pele, ent\u00e3o, poder\u00e1 ser usada como uma plataforma para testes para subst\u00e2ncias de cosm\u00e9ticos\u201d, finaliza.<\/p>\n<p>Objetivo \u00e9 gerar modelos de pele que sejam mais complexos em termos de composi\u00e7\u00e3o e de estrutura em rela\u00e7\u00e3o aos j\u00e1 dispon\u00edveis.<\/p>\n<p>\u201cOs avan\u00e7os alcan\u00e7ados podem ter um impacto tanto no desenvolvimento de novos modelos para testes de cosm\u00e9ticos e outras subst\u00e2ncias, como na gera\u00e7\u00e3o de enxertos para tratar queimaduras e feridas, por exemplo\u201d, explica.<\/p>\n<p><strong>Desafios e futuro<\/strong><\/p>\n<div id=\"attachment_708308\" class=\"wp-caption aligncenter\" style=\"width: 649px;\">\n<p><img loading=\"lazy\" class=\" wp-image-708308 ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed ed lazyloaded\" src=\"https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-3.jpg\" sizes=\"(max-width: 600px) 100vw, 600px\" srcset=\"https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-3.jpg 600w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-3-300x232.jpg 300w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-3-250x193.jpg 250w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-3-100x77.jpg 100w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-3-153x118.jpg 153w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-3-120x92.jpg 120w\" alt=\"\" width=\"639\" height=\"493\" data-lazy-src=\"https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-3.jpg\" data-lazy-srcset=\"https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-3.jpg 600w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-3-300x232.jpg 300w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-3-250x193.jpg 250w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-3-100x77.jpg 100w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-3-153x118.jpg 153w, https:\/\/www.anda.jor.br\/wp-content\/uploads\/2018\/02\/carolina-3-120x92.jpg 120w\" data-lazy-sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p class=\"wp-caption-text\">Essa foi a maior premia\u00e7\u00e3o que a curitibana j\u00e1 recebeu, mas n\u00e3o a \u00fanica (Foto: Carolina Motter\/Arquivo pessoal)<\/p>\n<\/div>\n<p>A curitibana relata que tem trabalhado, atualmente, na cria\u00e7\u00e3o de biotintas sem componentes de origem animal. A inten\u00e7\u00e3o \u00e9, al\u00e9m de poupar animais, produzir uma pele mais semelhante \u00e0 humana, j\u00e1 que o homem e o animal s\u00e3o fisiologicamente diferentes.<\/p>\n<p>\u201cMeu projeto tem demonstrado que muitos recursos que usamos para gerar os modelos de pele ainda s\u00e3o de origem animal. \u00c9 o caso de v\u00e1rias prote\u00ednas, como o col\u00e1geno, que s\u00e3o extra\u00eddos da cartilagem ou de tecidos animais e do soro fetal bovino\u201d, explica.<\/p>\n<p>\u201cAssim, uma parte muito importante da pesquisa tem sido buscar alternativas a esses materiais que possam nos ajudar a gerar um modelo de pele que livre de qualquer composto de origem animal\u201d, acrescenta.<\/p>\n<p>A pr\u00f3xima etapa do projeto, conta Carolina, \u00e9 aumentar a complexidade dos modelos atrav\u00e9s da inser\u00e7\u00e3o de c\u00e9lulas que possam originar a estrutura do fol\u00edculo capilar. \u201c\u00c9 o meu grande objetivo\u201d, diz.<\/p>\n<p>Doutora, Carolina pretende voltar ao Brasil e continuar trabalhando na melhoria dos modelos. Ela diz que quer voltar para casa para contribuir ao m\u00e1ximo no avan\u00e7o do campo de pesquisa no pa\u00eds.<\/p>\n<p>\u201cComo cientista, tenho a responsabilidade de usar os melhores recursos para criar alternativas. Como ser humano, tenho todas as motiva\u00e7\u00f5es para seguir em frente, lutando pelos meus objetivos\u201d, finaliza.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Imposs\u00edvel conceber que criaturas t\u00e3o cheias de amor, de inoc\u00eancia e de confian\u00e7a sejam usadas<\/p>\n","protected":false},"author":2,"featured_media":80404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/carolina.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/carolina-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/carolina-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/carolina.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/carolina.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/carolina.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/carolina.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/carolina.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/carolina.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/carolina.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"&#8216;Imposs\u00edvel conceber que criaturas t\u00e3o cheias de amor, de inoc\u00eancia e de confian\u00e7a sejam usadas","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/80403"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=80403"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/80403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/80404"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=80403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=80403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=80403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}