{"id":80379,"date":"2018-02-19T08:00:10","date_gmt":"2018-02-19T11:00:10","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=80379"},"modified":"2018-02-19T07:43:02","modified_gmt":"2018-02-19T10:43:02","slug":"carnaval-e-meio-ambiente-glitter-biodegradavel-e-sucesso-nas-ruas-do-pais","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/carnaval-e-meio-ambiente-glitter-biodegradavel-e-sucesso-nas-ruas-do-pais\/","title":{"rendered":"Carnaval e meio ambiente: glitter biodegrad\u00e1vel \u00e9 sucesso nas ruas do Pa\u00eds"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/gliter.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-80380\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/gliter-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/gliter-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/gliter.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Em meio a toneladas de lixo produzidas pelos mais diversos tipos de atividade, \u00e9 dif\u00edcil imaginar que exista um material espec\u00edfico que \u00e9 respons\u00e1vel por uma das maiores amea\u00e7as ao meio ambiente durante o carnaval. Imprescind\u00edvel na produ\u00e7\u00e3o de fantasias e maquiagens desta popular festa, o glitter \u00e9 tamb\u00e9m um item de destaque quando o assunto \u00e9 polui\u00e7\u00e3o.<\/p>\n<p>Isto porque, embora seja um micro pl\u00e1stico de apenas cinco mil\u00edmetros, o glitter representa um problema potencial que \u00e9 capaz de atingir toda a cadeia alimentar, afetando n\u00e3o somente a alimenta\u00e7\u00e3o de organismos menores (pl\u00e2ncton, m\u00e3e d\u2019\u00e1gua e corais), mas prejudicando tamb\u00e9m o desenvolvimento de animais e vegeta\u00e7\u00f5es \u2014 sobretudo esp\u00e9cies marinhas. Isso tudo sem falar dos perigos \u00e0 sa\u00fade humana.<\/p>\n<p>Para criar uma alternativa que pudesse manter a energia e alegria caracter\u00edsticas do carnaval sem deixar de lado a preocupa\u00e7\u00e3o com o meio ambiente, empresas brasileiras decidiram apostar na cria\u00e7\u00e3o de uma f\u00f3rmula biodegrad\u00e1vel do material, apresentando uma vers\u00e3o muito mais consciente e que est\u00e1 engajada com a responsabilidade individual de cada pessoa durante os eventos.<\/p>\n<p>Lan\u00e7ada na edi\u00e7\u00e3o do ano passado, a nova solu\u00e7\u00e3o sustent\u00e1vel foi aderida por milhares de foli\u00f5es em todo o Brasil e se tornou um dos grandes destaques do carnaval de 2018. Com algumas\u00a0<a href=\"http:\/\/www.pensamentoverde.com.br\/dicas\/ideias-sustentaveis-para-voce-brincar-no-carnaval\/\" target=\"_blank\" rel=\"noopener\">receitas caseiras<\/a>\u00a0dispon\u00edveis na internet, o glitter biodegrad\u00e1vel n\u00e3o demorou muito a cair no gosto popular, a ponto de figurar entre os l\u00edderes de venda em lojas de cosm\u00e9ticos.<\/p>\n<p>Em S\u00e3o Paulo, por exemplo, um chuveiro de glitter 100% ecol\u00f3gico foi instalado no Largo da Batata (um dos principais pontos de folia na capital paulista) para fazer a felicidade dos paulistanos, e ficar\u00e1 \u00e0 disposi\u00e7\u00e3o dos foli\u00f5es at\u00e9 o dia 18 de fevereiro. J\u00e1 no Rio Grande do Sul, a empresa\u00a0<em>Viva Purpurina<\/em>\u00a0desenvolveu sua vers\u00e3o ecol\u00f3gica do glitter e da purpurina. Em outros estados, a iniciativa dos pr\u00f3prios foli\u00f5es chamou a aten\u00e7\u00e3o.<\/p>\n<p>Com o exponencial crescimento do carnaval de rua que o pa\u00eds teve em 2018, a expectativa \u00e9 de que nos pr\u00f3ximos anos n\u00e3o apenas o \u201cbioglitter\u201d seja destaque, mas que diversas outras solu\u00e7\u00f5es sejam criadas e adotadas pessoas nas datas sazonais do calend\u00e1rio nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em meio a toneladas de lixo produzidas pelos mais diversos tipos de atividade, \u00e9 dif\u00edcil<\/p>\n","protected":false},"author":2,"featured_media":80380,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/gliter.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/gliter-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/gliter-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/gliter.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/gliter.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/gliter.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/gliter.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/gliter.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/gliter.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2018\/02\/gliter.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Em meio a toneladas de lixo produzidas pelos mais diversos tipos de atividade, \u00e9 dif\u00edcil","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/80379"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=80379"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/80379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/80380"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=80379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=80379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=80379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}