{"id":72966,"date":"2017-09-25T15:30:40","date_gmt":"2017-09-25T18:30:40","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=72966"},"modified":"2017-09-25T14:50:27","modified_gmt":"2017-09-25T17:50:27","slug":"o-que-faz-do-brasil-uma-ameaca-ao-futuro-dos-tubaroes-que-muita-gente-come-sem-saber","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/o-que-faz-do-brasil-uma-ameaca-ao-futuro-dos-tubaroes-que-muita-gente-come-sem-saber\/","title":{"rendered":"O que faz do Brasil uma amea\u00e7a ao futuro dos tubar\u00f5es, que muita gente come sem saber"},"content":{"rendered":"<div class=\"mc-column content-text active-extra-styles active-capital-letter\" data-block-type=\"unstyled\" data-block-weight=\"25\">\n<p class=\"content-text__container theme-color-primary-first-letter\" data-track-category=\"Link no Texto\" data-track-links=\"\"><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/09\/tubarao.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-72967\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/09\/tubarao-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/09\/tubarao-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/09\/tubarao.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Maior consumidor mundial de carne de tubar\u00e3o, o Brasil pode se tornar um dos principais respons\u00e1veis pelo decl\u00ednio das popula\u00e7\u00f5es desses animais em mar aberto.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"56\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O alerta vem de cinco pesquisadores brasileiros que assinam um artigo publicado neste m\u00eas no peri\u00f3dico Marine Policy (&#8220;Pol\u00edtica Marinha&#8221;, em tradu\u00e7\u00e3o livre). O estudo mergulhou em bancos de dados internacionais, boletins do governo, artigos cient\u00edficos e outras fontes para mapear o cen\u00e1rio das cerca de 45 toneladas anuais que os brasileiros levam \u00e0s suas mesas.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"45\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O motivo-chave para tal protagonismo negativo, afirmam os pesquisadores, seriam as frotas internacionais que alimentam o mercado de nadadeiras de tubar\u00e3o, muito valorizadas no Leste Asi\u00e1tico. A sopa de nadadeira ou barbatana tem apelo afrodis\u00edaco e \u00e9 sinal de status e riqueza entre os chineses.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"62\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;Um quilo de nadadeira desidratada de tubar\u00e3o-martelo, por exemplo, chega a US$ 1,5 mil na \u00c1sia&#8221;, revela o bi\u00f3logo Rodrigo Barreto, bolsista do Centro Nacional de Pesquisa e Conserva\u00e7\u00e3o da Biodiversidade Marinha do Sudeste e Sul do Brasil (CEPSUL-ICMBio) e l\u00edder do estudo. Para compara\u00e7\u00e3o, o quilo da carne de tubar\u00e3o gira em torno de R$ 25 a R$ 30 no Brasil.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"64\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Essas frotas internacionais, no entanto, est\u00e3o proibidas de praticar o finning, ou seja, de manter as nadadeiras e descartar a carca\u00e7a no mar a fim de liberar seus por\u00f5es para mais barbatanas. Em 1998, diante do iminente colapso de algumas popula\u00e7\u00f5es do peixe, uma conven\u00e7\u00e3o internacional transformou a pr\u00e1tica em crime &#8211; o Brasil foi o primeiro pa\u00eds a assinar tratado ratificando essa proibi\u00e7\u00e3o.<\/p>\n<\/div>\n<div class=\"mc-column content-media content-media--normal content-photo\" data-block-type=\"backstage-photo\">\n<div class=\"content-media__container\">\n<div class=\"content-media__image-centered\">\n<div class=\"progressive-img can-open-lightbox\" data-min-size=\"1008x1343\" data-min-size-url=\"https:\/\/s2.glbimg.com\/m--HTPfltM9XyVMok6ufZNtbBus=\/0x0:412x549\/1008x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2017\/b\/8\/GetNWaRdugq5gtUEDx9w\/2-muita-gente-come-tubarao-sem-saber.jpg\" data-max-size=\"1600x2132\" data-max-size-url=\"https:\/\/s2.glbimg.com\/Vp5vhDgaxLB84mTDN94P2VNOW00=\/0x0:412x549\/1600x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2017\/b\/8\/GetNWaRdugq5gtUEDx9w\/2-muita-gente-come-tubarao-sem-saber.jpg\" data-media-index=\"1\">\n<div class=\"placeholder-container\"><\/div>\n<picture><img loading=\"lazy\" class=\"image content-media__image progressive-loaded\" title=\"Muita gente come tubar\u00e3o sem saber  (Foto: M\u00f4nica Manir)\" src=\"https:\/\/s2.glbimg.com\/SryKK3E289j6SVVmItizvTzibUg=\/0x0:412x549\/984x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2017\/b\/8\/GetNWaRdugq5gtUEDx9w\/2-muita-gente-come-tubarao-sem-saber.jpg\" alt=\"Muita gente come tubar\u00e3o sem saber  (Foto: M\u00f4nica Manir)\" width=\"639\" height=\"851\" data-src=\"https:\/\/s2.glbimg.com\/SryKK3E289j6SVVmItizvTzibUg=\/0x0:412x549\/984x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2017\/b\/8\/GetNWaRdugq5gtUEDx9w\/2-muita-gente-come-tubarao-sem-saber.jpg\" \/><\/picture><\/div>\n<\/div>\n<div class=\"content-media__description-centered \">\n<p class=\"content-media__description\"><i class=\"content-media__description__icon theme-color-primary\"><\/i><span class=\"content-media__description__caption\">Muita gente come tubar\u00e3o sem saber (Foto: M\u00f4nica Manir)<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content-ads content-ads--reveal\"><\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"31\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Ocorre que, ansiosas por continuar explorando o mercado de nadadeiras e, ao mesmo tempo, repassar o restante, esse setor encontrou no maior pa\u00eds da Am\u00e9rica do Sul um cais de consumo.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"12\">\n<blockquote class=\"content-blockquote theme-border-color-primary-before\"><p>&#8220;Essas frotas exp\u00f5em aqui uma carne que praticamente ningu\u00e9m quer&#8221;, diz Barreto.<\/p><\/blockquote>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"26\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O bi\u00f3logo paulistano, que hoje mora em Itaja\u00ed (SC), afirma que, tirando Brasil e M\u00e9xico, as postas de tubar\u00e3o n\u00e3o s\u00e3o vendidas em nenhum outro lugar.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"33\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;S\u00e3o pa\u00edses com grande defici\u00eancia em \u00f3rg\u00e3os de vigil\u00e2ncia sanit\u00e1ria, sem manejo pesqueiro e que, al\u00e9m disso, convivem com graves problemas de analfabetismo funcional, condi\u00e7\u00f5es estrat\u00e9gicas para o consumo do produto&#8221;, explica Barreto.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"4\">\n<div class=\"content-intertitle\">\n<h2>Um fator de peso<\/h2>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"53\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A rejei\u00e7\u00e3o generalizada quanto \u00e0 carne de tubar\u00e3o tem um motivo de peso. Grande predador, animal encontra-se no topo da cadeia alimentar. Por um processo de bioacumula\u00e7\u00e3o, ele agrega metais pesados, como merc\u00fario e ars\u00eanio, presentes nos organismos que lhe serviram de alimento. Ingeridas al\u00e9m da conta, essas subst\u00e2ncias podem causar danos cerebrais.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"64\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Um par\u00e2metro de consumo de merc\u00fario vem da Organiza\u00e7\u00e3o Mundial de Sa\u00fade (OMS). Ela preconiza o limite di\u00e1rio de 0,5 miligrama desse metal por quilo. Estudo publicado nos Cadernos de Sa\u00fade P\u00fablica em 2008, por\u00e9m, revela que, em amostras de Prionace glauca, ou tubar\u00e3o-azul, a esp\u00e9cie de tubar\u00e3o mais pescada no mundo, o \u00edndice presente excedeu em mais de duas vezes o topo di\u00e1rio.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"33\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">N\u00e3o \u00e0 toa, a Food and Drug Administration (FDA), ag\u00eancia federal americana, n\u00e3o recomenda a inclus\u00e3o de tubar\u00e3o no card\u00e1pio de gr\u00e1vidas, mulheres que estejam amamentando e crian\u00e7as, seja em que quantidade for.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"65\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Outro dado que ajuda a emoldurar esse cen\u00e1rio \u00e9 o mislabeling, termo em ingl\u00eas que os pesquisadores traduzem como &#8220;rotulagem errada&#8221;. A maioria da popula\u00e7\u00e3o estaria consumindo tubar\u00e3o sem saber disso. Isso porque, nas prateleiras dos supermercados, nas bancas de peixe, nos restaurantes e nas merendas escolares, o animal \u00e9 oferecido apenas sob o nome gen\u00e9rico de &#8220;ca\u00e7\u00e3o&#8221;, carne bem-aceita especialmente pela falta de espinhos.<\/p>\n<\/div>\n<div class=\"content-ads content-ads--reveal\"><\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"36\">\n<blockquote class=\"content-blockquote theme-border-color-primary-before\"><p>&#8220;Mais de 70% das pessoas n\u00e3o sabem que ca\u00e7\u00e3o \u00e9 tubar\u00e3o&#8221;, afirma Hugo Bornatowski, professor do Centro de Estudos do Mar da Universidade Federal do Paran\u00e1 (UFPR) e um dos autores do texto publicado na Marine.<\/p><\/blockquote>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"25\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Em pesquisa feita por ele e mais tr\u00eas estudiosos sobre rotulagem em Curitiba, a maioria dos entrevistados afirmou j\u00e1 ter comido ca\u00e7\u00e3o, mas nunca tubar\u00e3o.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"43\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Respons\u00e1vel no pa\u00eds pela regulamenta\u00e7\u00e3o da rotulagem de alimentos embalados, a Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) afirma n\u00e3o existir regra espec\u00edfica para a designa\u00e7\u00e3o de produtos de origem animal nas embalagens, compet\u00eancia que seria do Minist\u00e9rio da Agricultura, Pecu\u00e1ria e Abastecimento (MAPA).<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"54\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Nesse sentido, remete \u00e0 instru\u00e7\u00e3o normativa MAPA n\u00ba 29, de 23 de setembro de 2015, que determina que a rotulagem de peixes e derivados deve conter o nome comum da esp\u00e9cie, conforme estabelecido na lista anexa \u00e0 instru\u00e7\u00e3o. Na lista, \u00e9 permitido o uso tanto do nome comum &#8220;ca\u00e7\u00e3o&#8221; quanto &#8220;tubar\u00e3o&#8221; para diversas esp\u00e9cies.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"35\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;Desta forma&#8221;, continua a Anvisa, &#8220;o uso do termo ca\u00e7\u00e3o, quando realizado de acordo com o previsto na regulamenta\u00e7\u00e3o do MAPA, n\u00e3o \u00e9 considerado enganoso e, portanto, n\u00e3o contraria o disposto na legisla\u00e7\u00e3o sanit\u00e1ria brasileira&#8221;.<\/p>\n<\/div>\n<div class=\" content-media content-media--normal content-photo\" data-block-type=\"backstage-photo\">\n<div class=\"content-media__container\">\n<div class=\"content-media__image-centered\">\n<div class=\"progressive-img can-open-lightbox\" data-min-size=\"1008x567\" data-min-size-url=\"https:\/\/s2.glbimg.com\/UWFTPLokMwzm6iPTw2rG14VS4k8=\/0x0:976x549\/1008x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2017\/M\/k\/l2NGKhQ7GAW3IYBgnOXw\/3-raia-emplastro-e-caracteristica-da-america-do-sul-e-e-vulneravel-a-pesca-predatoria.jpg\" data-max-size=\"1600x900\" data-max-size-url=\"https:\/\/s2.glbimg.com\/xYnpufLJfwfW5Nm8PbbCX-dVYgQ=\/0x0:976x549\/1600x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2017\/M\/k\/l2NGKhQ7GAW3IYBgnOXw\/3-raia-emplastro-e-caracteristica-da-america-do-sul-e-e-vulneravel-a-pesca-predatoria.jpg\" data-media-index=\"2\">\n<div class=\"placeholder-container\"><\/div>\n<picture><img loading=\"lazy\" class=\"image content-media__image progressive-loaded\" title=\"Raia emplastro \u00e9 caracter\u00edstica da Am\u00e9rica do Sul e \u00e9 vulner\u00e1vel \u00e0 pesca predat\u00f3ria  (Foto: Otto Bismarck F. Gadig)\" src=\"https:\/\/s2.glbimg.com\/UWFTPLokMwzm6iPTw2rG14VS4k8=\/0x0:976x549\/1008x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2017\/M\/k\/l2NGKhQ7GAW3IYBgnOXw\/3-raia-emplastro-e-caracteristica-da-america-do-sul-e-e-vulneravel-a-pesca-predatoria.jpg\" alt=\"Raia emplastro \u00e9 caracter\u00edstica da Am\u00e9rica do Sul e \u00e9 vulner\u00e1vel \u00e0 pesca predat\u00f3ria  (Foto: Otto Bismarck F. Gadig)\" width=\"640\" height=\"360\" data-src=\"https:\/\/s2.glbimg.com\/UWFTPLokMwzm6iPTw2rG14VS4k8=\/0x0:976x549\/1008x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2017\/M\/k\/l2NGKhQ7GAW3IYBgnOXw\/3-raia-emplastro-e-caracteristica-da-america-do-sul-e-e-vulneravel-a-pesca-predatoria.jpg\" \/><\/picture><\/div>\n<\/div>\n<div class=\"content-media__description-centered mc-column\">\n<p class=\"content-media__description\"><i class=\"content-media__description__icon theme-color-primary\"><\/i><span class=\"content-media__description__caption\">Raia emplastro \u00e9 caracter\u00edstica da Am\u00e9rica do Sul e \u00e9 vulner\u00e1vel \u00e0 pesca predat\u00f3ria (Foto: Otto Bismarck F. Gadig)<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"1\">\n<div class=\"content-intertitle\">\n<h2>Conserva\u00e7\u00e3o<\/h2>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"39\">\n<blockquote class=\"content-blockquote theme-border-color-primary-before\"><p>&#8220;N\u00e3o dissemos que a rotulagem da carne de tubar\u00e3o no Brasil \u00e9 ilegal&#8221;, rebate Bornatowski. &#8220;Mas o consumidor deve saber o que est\u00e1 comendo e de onde est\u00e1 vindo o produto, o que facilita quanto \u00e0 conserva\u00e7\u00e3o e conscientiza\u00e7\u00e3o.&#8221;<\/p><\/blockquote>\n<\/div>\n<div class=\"content-ads content-ads--reveal\"><\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"64\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Mesmo porque, diz o professor da UFPR, o termo &#8220;ca\u00e7\u00e3o&#8221;, importado do espanhol &#8220;caz\u00f3n&#8221;, \u00e9 muito amplo, e v\u00e1rias esp\u00e9cies vendidas sob esse r\u00f3tulo est\u00e3o amea\u00e7adas de extin\u00e7\u00e3o &#8211; \u00e9 o caso do tubar\u00e3o-martelo. Na mesma linha de racioc\u00ednio estariam as raias, outro elasmobr\u00e2nquio bastante apreciado fora do pa\u00eds, mas que tamb\u00e9m tem seu mercado interno como ingrediente de moquecas, past\u00e9is e outras iguarias.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"46\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;Ningu\u00e9m sabe de qual raia estamos falando porque nunca houve no Brasil uma resolu\u00e7\u00e3o taxin\u00f4mica adequada que ajudasse no controle desses recursos&#8221;, lembra Fabio Motta, professor do Instituto do Mar da Universidade Federal de S\u00e3o Paulo (Unifesp) em Santos, tamb\u00e9m autor do artigo publicado na Marine.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"13\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;Quando falo de ca\u00e7\u00e3o ou raia, falo de um mundo de esp\u00e9cies&#8221;, enfatiza.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"42\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Entre elas, Motta destaca a raia viola e a raia emplastro, esta \u00faltima end\u00eamica no sul da Am\u00e9rica do Sul, de distribui\u00e7\u00e3o restrita, crescimento lento e poucos filhotes. Uma pescaria direcionada para elas seria cr\u00edtica. &#8220;Se sumirem dali, sumiram do mundo&#8221;, diz.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"21\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Atualmente, a propor\u00e7\u00e3o de elasmobr\u00e2nquios amea\u00e7ados no Brasil (33% de 145 esp\u00e9cies) excede a taxa global identificada para o grupo (25%).<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"55\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Segundo o Sistema de Permissionamento de Embarca\u00e7\u00f5es Pesqueiras Marinhas, tubar\u00f5es s\u00e3o considerados &#8220;pescaria incidental&#8221;. A Secretaria de Aquicultura e Pesca afirma que, como os dados de produ\u00e7\u00e3o das pescarias gerados oficialmente s\u00e3o voltados para as esp\u00e9cies-alvo da captura dentro desse sistema estabelecido, o \u00f3rg\u00e3o n\u00e3o tem informa\u00e7\u00f5es atuais de esp\u00e9cies desses animais pescadas no Brasil.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"28\">\n<blockquote class=\"content-blockquote theme-border-color-primary-before\"><p>&#8220;Ningu\u00e9m admite que o tubar\u00e3o-azul, por exemplo, \u00e9 esp\u00e9cie-alvo&#8221;, diz Motta. &#8220;Mas, do jeito que as pessoas comem carne de tubar\u00e3o no Brasil, isso n\u00e3o \u00e9 mais assim.&#8221;<\/p><\/blockquote>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"12\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Nessa pesca direcionada, seriam enredados tamb\u00e9m tubar\u00f5es e raias em situa\u00e7\u00e3o vulner\u00e1vel.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"1\">\n<div class=\"content-intertitle\">\n<h2>&#8216;Apag\u00e3o&#8217;<\/h2>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"23\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O Brasil n\u00e3o apenas consome, como pesca tubar\u00f5es. Somos o 11\u00ba que mais os captura, e o 17\u00ba que mais exporta suas barbatanas.<\/p>\n<\/div>\n<div class=\"content-ads content-ads--reveal\"><\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"57\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O grosso, por\u00e9m, vem da importa\u00e7\u00e3o. De acordo com tabela enviada pelo Minist\u00e9rio do Desenvolvimento, Ind\u00fastria e Com\u00e9rcio, sob o qual est\u00e1 a Secretaria de Aquicultura e Pesca, o Brasil liderou as importa\u00e7\u00f5es de dogfish e outros tubar\u00f5es em 2014, quando atingiu o patamar de US$ 45,2 milh\u00f5es. Nos dois anos seguintes, Hong Kong assumiu a lideran\u00e7a.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"34\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Na segunda coloca\u00e7\u00e3o, a importa\u00e7\u00e3o brasileira teria sido de US$ 26,8 milh\u00f5es em 2015 e de US$ 24,8 bilh\u00f5es em 2016. O minist\u00e9rio n\u00e3o soube informar quais esp\u00e9cies estariam sob o chap\u00e9u &#8220;outros tubar\u00f5es&#8221;.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"43\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Barreto destaca que muita dessa importa\u00e7\u00e3o se refere a animais pescados no Atl\u00e2ntico Sul por pa\u00edses como Espanha, China e Portugal. Donos de embarca\u00e7\u00f5es nas quais conseguem resfriar o ca\u00e7\u00e3o, eles j\u00e1 o congelam fatiado em postas, prontos para o consumo no Brasil.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"58\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Os estudiosos afirmam ainda que n\u00e3o se coloca em pr\u00e1tica a obrigatoriedade de observadores de bordo nas viagens de pesca de embarca\u00e7\u00f5es com mais de 15 metros, prevista na portaria n\u00ba 166 do Ibama, de 18 de julho de 2007. &#8220;O observador de bordo seria uma contrapartida, ele colheria informa\u00e7\u00f5es e faria a resolu\u00e7\u00e3o taxin\u00f4mica adequada&#8221;, explica Motta.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"21\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Para os pesquisadores, aflige a falta de informa\u00e7\u00f5es e de estat\u00edsticas do setor no pa\u00eds. O \u00faltimo dado seria de 2007.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"38\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;Faz dez anos que n\u00e3o sabemos o que se captura de peixes na costa brasileira&#8221;, contabiliza Motta. &#8220;Temos um apag\u00e3o da infraestrutura de gest\u00e3o pesqueira no Brasil, na qual as arenas est\u00e3o enfraquecidas e algumas nem existem mais.&#8221;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Maior consumidor mundial de carne de tubar\u00e3o, o Brasil pode se tornar um dos principais<\/p>\n","protected":false},"author":2,"featured_media":72967,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/09\/tubarao.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/09\/tubarao-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/09\/tubarao-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/09\/tubarao.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/09\/tubarao.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/09\/tubarao.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/09\/tubarao.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/09\/tubarao.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/09\/tubarao.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/09\/tubarao.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Maior consumidor mundial de carne de tubar\u00e3o, o Brasil pode se tornar um dos principais","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/72966"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=72966"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/72966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/72967"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=72966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=72966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=72966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}