{"id":65204,"date":"2017-05-06T14:59:32","date_gmt":"2017-05-06T17:59:32","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=65204"},"modified":"2017-05-06T14:59:33","modified_gmt":"2017-05-06T17:59:33","slug":"por-que-as-galinhas-sao-muito-mais-inteligentes-do-que-voce-imagina","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/por-que-as-galinhas-sao-muito-mais-inteligentes-do-que-voce-imagina\/","title":{"rendered":"Por que as galinhas s\u00e3o muito mais inteligentes do que voc\u00ea imagina"},"content":{"rendered":"<p class=\"story-body__introduction\"><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/por-que-as-galinhas-sao-muito-mais-inteligentes-do-que-voce-imagina\/galinha-11\/\" rel=\"attachment wp-att-65205\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-65205\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/galinha-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/galinha-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/galinha.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>A reputa\u00e7\u00e3o das galinhas n\u00e3o \u00e9 das melhores. Para muitos, elas s\u00e3o mais burras do que qualquer outra ave e n\u00e3o passam de f\u00e1bricas ambulantes de carne com a capacidade de deixar ovos deliciosos por a\u00ed.<\/p>\n<p>Mas a realidade \u00e9 outra. A ave mais comum do mundo na verdade \u00e9 inteligente e talvez at\u00e9 sens\u00edvel em rela\u00e7\u00e3o ao bem-estar de seus semelhantes &#8211; o que levanta algumas quest\u00f5es \u00e9ticas sobre a avicultura industrial.<\/p>\n<p class=\"story-body__link\">H\u00e1 algo de estranho no mundo das galinhas. Mundialmente, elas somam mais de 19 bilh\u00f5es, o que as torna a esp\u00e9cie de vertebrados mais abundante no planeta. Ainda assim, muitas pessoas t\u00eam pouco ou nenhum contato com as aves &#8211; ao menos n\u00e3o enquanto elas est\u00e3o vivas.<\/p>\n<p>Isso provocou algumas suposi\u00e7\u00f5es estranhas em rela\u00e7\u00e3o \u00e0s galinhas. Elas s\u00e3o grandes representantes das galin\u00e1ceas, um grupo de aves que tamb\u00e9m inclui perus, perdizes e pav\u00f5es. Mas, de acordo com alguns estudos, as pessoas muitas vezes n\u00e3o as veem como p\u00e1ssaros.<\/p>\n<p>Tamb\u00e9m \u00e9 comum a vis\u00e3o de que s\u00e3o animais nada inteligentes e desprovidas de caracter\u00edsticas psicol\u00f3gicas complexas que animais &#8220;mais elevados&#8221; t\u00eam, como os macacos.<\/p>\n<p>Essa ideia \u00e9 refor\u00e7ada por algumas descri\u00e7\u00f5es delas na cultura popular, e pode ajudar as pessoas a se sentirem menos mal por comer ovos e carne de frango.<\/p>\n<p>Mas a verdade \u00e9 que as galinhas n\u00e3o s\u00e3o nada burras: elas conseguem contar, demonstram ter um certo n\u00edvel de autopercep\u00e7\u00e3o e at\u00e9 se manipulam entre si usando t\u00e1ticas maquiav\u00e9licas.<\/p>\n<figure class=\"media-landscape has-caption full-width\"><\/figure>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\">\u00a0 <span class=\"story-image-copyright\"><img loading=\"lazy\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/4C64\/production\/_95765591_b5d933c0-a4a6-4d3d-a5b7-bc5f41ffa11a.jpg\" alt=\"Heihei, do filme Moana\" width=\"640\" height=\"360\" data-highest-encountered-width=\"624\" \/><\/span><\/span><figcaption class=\"media-caption\"><span class=\"off-screen\">Image caption<\/span> <span class=\"media-caption__text\"> Heihei, personagem da anima\u00e7\u00e3o Moana, \u00e9 completamente burra <\/span><\/figcaption><\/figure>\n<h2 class=\"story-body__crosshead\">Experimentos<\/h2>\n<p>As galinhas s\u00e3o t\u00e3o espertas que basta passar um tempo perto delas para acabar com os preconceitos arraigados.<\/p>\n<p>A fim de realizar um estudo publicado em 2015, Lisel O&#8217;Dwyer e Susan Hazel deram uma aula sobre esses animais a estudantes de gradua\u00e7\u00e3o da Universidade de Adelaide, na Austr\u00e1lia.<\/p>\n<p>Os alunos fizeram alguns experimentos envolvendo o treinamento dessas aves para aprender sobre psicologia e cogni\u00e7\u00e3o.<\/p>\n<p>Antes de a aula come\u00e7ar, os estudantes completaram um question\u00e1rio, cujo resultado mostrou que a maioria havia passado pouco tempo com galinhas. Al\u00e9m disso, eles as viam como criaturas simples, incapazes de sentir t\u00e9dio, frustra\u00e7\u00e3o ou felicidade.<\/p>\n<p>Depois de apenas duas horas treinando os p\u00e1ssaros, os alunos se mostraram mais propensos a acreditar no fato de elas sentirem os tr\u00eas estados emocionais citados acima.<\/p>\n<p>&#8220;As galinhas s\u00e3o muito mais espertas do que eu pensava&#8221;, comentou um estudante em um question\u00e1rio posterior. &#8220;Nunca pensei que as galinhas fossem t\u00e3o inteligentes e aprendessem t\u00e3o r\u00e1pido&#8221;, disse outro.<\/p>\n<figure class=\"media-landscape has-caption full-width\"><\/figure>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\">\u00a0 <span class=\"story-image-copyright\"><img loading=\"lazy\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef-1.bbci.co.uk\/news\/624\/cpsprodpb\/159EC\/production\/_95765588_e7ce8adc-71ca-42e3-b260-7dd0534ade65.jpg\" alt=\"Galinha\" width=\"640\" height=\"360\" data-highest-encountered-width=\"624\" \/><\/span><\/span><figcaption class=\"media-caption\"><span class=\"off-screen\">Image caption<\/span> <span class=\"media-caption__text\"> H\u00e1 mais de 19 bilh\u00f5es de galinhas no mundo <\/span><\/figcaption><\/figure>\n<p>Em um estudo ainda n\u00e3o publicado, O&#8217;Dwyer repetiu esse experimento com funcion\u00e1rios da ind\u00fastria av\u00edcola e encontrou os mesmos resultados.<\/p>\n<p>&#8220;Basicamente tivemos dois grupos sociais bem diferentes um do outro e encontramos as mesmas atitudes iniciais e a mesma mudan\u00e7a de atitude em ambos&#8221;, disse.<\/p>\n<p>Ela agora pretende estudar se essas experi\u00eancias t\u00eam algum impacto nos h\u00e1bitos alimentares das pessoas &#8211; por exemplo, se elas passam a comer frango criado em formas que elas consideram mais aceit\u00e1veis eticamente.<\/p>\n<h2 class=\"story-body__crosshead\">Cogni\u00e7\u00e3o<\/h2>\n<p>A pesquisa de O&#8217;Dwyer \u00e9 uma entre as v\u00e1rias escolhidas por Lori Marino, do Centro de Defesa de Animais Kimmela em Kanab (Utah, nos EUA), como parte de uma an\u00e1lise cient\u00edfica sobre a cogni\u00e7\u00e3o dos frangos publicada em janeiro de 2017.<\/p>\n<p>&#8220;O estudo \u00e9 parte de uma iniciativa coletiva da (organiza\u00e7\u00e3o de prote\u00e7\u00e3o animal) Farm Sanctuary e o Centro Kimella chamada <i>O Projeto Algu\u00e9m<\/i>&#8220;, diz Marino. &#8220;O objetivo do projeto \u00e9 educar as pessoas sobre quem s\u00e3o os animais criados para consumo a partir de dados cient\u00edficos.&#8221;<\/p>\n<p>Marino diz que evid\u00eancias cient\u00edficas deixam claro que as galinhas t\u00eam mais intelig\u00eancia e consci\u00eancia do que a maioria das pessoas acredita.<\/p>\n<figure class=\"media-landscape has-caption full-width\"><\/figure>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\">\u00a0 <span class=\"story-image-copyright\"><img loading=\"lazy\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/9A84\/production\/_95765593_chicken-2205233_1920.jpg\" alt=\"Pintinho\" width=\"640\" height=\"360\" data-highest-encountered-width=\"624\" \/><\/span><\/span><figcaption class=\"media-caption\"><span class=\"off-screen\">Image caption<\/span> <span class=\"media-caption__text\"> At\u00e9 mesmo pintinhos s\u00e3o capazes de contar <\/span><\/figcaption><\/figure>\n<p>Um exemplo disso foi apontado por uma s\u00e9rie de estudos publicados na \u00faltima d\u00e9cada por Rosa Rugani, da Universidade de Padova (It\u00e1lia) e seus colegas.<\/p>\n<p>Ao trabalhar com pintinhos, o grupo demonstrou que as galinhas s\u00e3o capazes contar e realizar opera\u00e7\u00f5es aritm\u00e9ticas b\u00e1sicas.<\/p>\n<p>Os pintinhos foram criados em meio a cinco objetos &#8211; as embalagens de pl\u00e1stico do Kinder Ovo. Depois de alguns dias, os cientistas tiraram os objetos e esconderam dois atr\u00e1s de uma tela e tr\u00eas atr\u00e1s de outra.<\/p>\n<p>Resultado: a tend\u00eancia dos pintinhos foi de se aproximar da tela que tinha mais objetos escondidos.<\/p>\n<p>Um experimento subsequente testou sua mem\u00f3ria e habilidade de somar e subtrair. Depois de esconder os objetos atr\u00e1s das duas telas, os cientistas come\u00e7aram a mudar os objetos de lugar diante dos pintinhos, que pareciam acompanhar os movimentos e continuaram se aproximando das telas com o maior n\u00famero de objetos.<\/p>\n<p>Isso mostra que as galinhas t\u00eam uma boa compreens\u00e3o num\u00e9rica desde cedo, mesmo sem muito tempo de vida, diz Rugani.<\/p>\n<figure class=\"media-landscape has-caption full-width\"><\/figure>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\">\u00a0 <span class=\"story-image-copyright\"><img loading=\"lazy\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/10460\/production\/_95765666_8cc714cc-8aed-43fd-8e87-78785073a37f.jpg\" alt=\"Galinha\" width=\"636\" height=\"358\" data-highest-encountered-width=\"624\" \/><\/span><\/span><figcaption class=\"media-caption\"><span class=\"off-screen\">Image caption<\/span> <span class=\"media-caption__text\"> As galinhas t\u00eam capacidade para opera\u00e7\u00f5es aritm\u00e9ticas <\/span><\/figcaption><\/figure>\n<p>Ela acha que essa \u00e9 uma caracter\u00edstica de animais em geral, n\u00e3o apenas delas.<\/p>\n<p>&#8220;Essas habilidades podem ajudar os animais em seu ambiente natural, por exemplo para chegar at\u00e9 uma quantidade maior de comida ou para encontrar um grupo maior deles&#8221;, diz Siobhan Abeyesinghe, na Universidade de Bristol (Reino Unido).<\/p>\n<p>Abeyesinghe deu \u00e0s galinhas a op\u00e7\u00e3o de bicar uma chave que lhes daria um breve acesso a comida ap\u00f3s dois segundos ou de bicar uma segunda chave que lhes daria um acesso prolongado a comida depois de seis segundos.<\/p>\n<p>Na maioria das vezes as aves escolheram a segunda chave, que oferecia mais comida depois de um tempo um pouco maior. Em outras palavras, elas demonstraram autocontrole, um tra\u00e7o que bi\u00f3logos acreditam que indica um n\u00edvel de autoconsci\u00eancia.<\/p>\n<h2 class=\"story-body__crosshead\">&#8216;Pegadinhas&#8217; sociais<\/h2>\n<p>As galinhas tamb\u00e9m s\u00e3o seres complexos socialmente.<\/p>\n<p>Alguns estudos indicam que essas aves podem perceber como outras galinhas veem o mundo e usar essa informa\u00e7\u00e3o em sua vantagem.<\/p>\n<figure class=\"media-landscape has-caption full-width\"><\/figure>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\">\u00a0 <span class=\"story-image-copyright\"><img loading=\"lazy\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef-1.bbci.co.uk\/news\/624\/cpsprodpb\/17990\/production\/_95765669_8cec80a3-7adc-4697-a196-b7310ea6250e.jpg\" alt=\"Galinhas\" width=\"640\" height=\"360\" data-highest-encountered-width=\"624\" \/><\/span><\/span><figcaption class=\"media-caption\"><span class=\"off-screen\">Image caption<\/span> <span class=\"media-caption__text\"> Galinhas tamb\u00e9m t\u00eam vida social <\/span><\/figcaption><\/figure>\n<p>Se um galo em busca de comida acha um alimento apetitoso, ele frequentemente tentar\u00e1 impressionar as f\u00eameas \u00e0 volta com uma dan\u00e7a, enquanto faz um chamado de comida caracter\u00edstico.<\/p>\n<p>No entanto, machos subordinados que fazem esse mesmo passo de dan\u00e7a com canto correm o risco de serem flagrados e atacados por machos dominantes. Por isso, o subordinado faz essa dan\u00e7a espec\u00edfica em sil\u00eancio, em uma tentativa de impressionar f\u00eameas sem o dominante perceber.<\/p>\n<p>Outros machos tentam seduzir f\u00eameas fazendo a mesma coisa mesmo quando n\u00e3o encontraram um bom petisco. Previsivelmente, as f\u00eameas rapidamente identificam os machos que preparam esse tipo de emboscada com muita frequ\u00eancia.<\/p>\n<p>H\u00e1 at\u00e9 algumas indica\u00e7\u00f5es de que elas t\u00eam uma esp\u00e9cie rudimentar de empatia umas pelas outras.<\/p>\n<figure class=\"media-landscape has-caption full-width\"><\/figure>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\">\u00a0 <span class=\"story-image-copyright\"><img loading=\"lazy\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef-1.bbci.co.uk\/news\/624\/cpsprodpb\/6C08\/production\/_95765672_f876b6fa-290c-4a88-a0df-92286d63c87f.jpg\" alt=\"Galo\" width=\"640\" height=\"360\" data-highest-encountered-width=\"624\" \/><\/span><\/span><figcaption class=\"media-caption\"><span class=\"off-screen\">Image caption<\/span> <span class=\"media-caption__text\"> Galos e galinhas podem ser bastante comunicativos <\/span><\/figcaption><\/figure>\n<p>Em uma s\u00e9rie de estudos durante os \u00faltimos seis anos, Joanne Edgar, da Universidade de Bristol (Reino Unido) e seus colegas estudaram como elas reagem ao ver seus pintinhos levando uma golfada de ar &#8211; algo que elas aprenderam, por experi\u00eancia pr\u00f3pria, que \u00e9 desagrad\u00e1vel.<\/p>\n<p>Quando o ar foi disparado contra os pintinhos, o cora\u00e7\u00e3o das galinhas come\u00e7ou a acelerar e elas passaram a chamar os filhotes com maior frequ\u00eancia. Elas n\u00e3o fizeram o mesmo quando o ar foi lan\u00e7ado perto deles, mas sem incomod\u00e1-los.<\/p>\n<p>Isso sugere que elas podem responder ao desconforto dos pintinhos por seu conhecimento pr\u00f3prio, em vez simplesmente reagir a sinais de estresse nos mais novos.<\/p>\n<figure class=\"media-landscape has-caption full-width\"><\/figure>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\">\u00a0 <span class=\"story-image-copyright\"><img loading=\"lazy\" class=\"responsive-image__img js-image-replace\" src=\"https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/E19C\/production\/_95765775_570bdbb9-d829-48e4-ba60-8fe29c1955b1.jpg\" alt=\"Galinhas\" width=\"636\" height=\"358\" data-highest-encountered-width=\"624\" \/><\/span><\/span><figcaption class=\"media-caption\"><span class=\"off-screen\">Image caption<\/span> <span class=\"media-caption__text\"> Galinhas s\u00e3o criadas em v\u00e1rias partes do globo <\/span><\/figcaption><\/figure>\n<p>A pesquisa continua em andamento, segundo Edgar.<\/p>\n<p>&#8220;N\u00f3s ainda n\u00e3o determinamos se as respostas comportamentais e fisiol\u00f3gicas que observamos nos pintinhos em situa\u00e7\u00e3o de leve estresse indicam uma resposta emocional ou s\u00e3o apenas uma rea\u00e7\u00e3o ao est\u00edmulo.&#8221;<\/p>\n<p>Se for comprovado que as galinhas demonstram empatia quando outras aves est\u00e3o em situa\u00e7\u00e3o de estresse, isso pode levantar quest\u00f5es s\u00e9rias a respeito de como os frangos s\u00e3o mantidos em criadouros.<\/p>\n<p>&#8220;H\u00e1 uma s\u00e9rie de situa\u00e7\u00f5es em que animais em cria\u00e7\u00e3o s\u00e3o expostos a vis\u00f5es, barulhos e cheiros de outros demonstrando dor e estresse&#8221;, disse Edgar. &#8220;\u00c9 importante determinar se o seu bem-estar \u00e9 reduzido nesses momentos.&#8221;<\/p>\n<p>Marino tamb\u00e9m acredita que esteja na hora de discutir essas quest\u00f5es.<\/p>\n<p>&#8220;A percep\u00e7\u00e3o de galinhas (como seres ignorantes) \u00e9 motivada em parte pela tend\u00eancia em diminuir sua intelig\u00eancia e sensibilidade porque as pessoas as comem&#8221;, diz ela.<\/p>\n<p>A desconfort\u00e1vel verdade sobre galinhas \u00e9 que elas s\u00e3o mais avan\u00e7adas cognitivamente do que muitas pessoas pensam. Contudo, ainda n\u00e3o se sabe se os consumidores v\u00e3o mudar seus h\u00e1bitos alimentares por causa dessa informa\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A reputa\u00e7\u00e3o das galinhas n\u00e3o \u00e9 das melhores. Para muitos, elas s\u00e3o mais burras do<\/p>\n","protected":false},"author":6,"featured_media":65205,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/galinha.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/galinha-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/galinha-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/galinha.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/galinha.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/galinha.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/galinha.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/galinha.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/galinha.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/galinha.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"A reputa\u00e7\u00e3o das galinhas n\u00e3o \u00e9 das melhores. Para muitos, elas s\u00e3o mais burras do","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/65204"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=65204"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/65204\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/65205"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=65204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=65204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=65204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}