{"id":65086,"date":"2017-05-05T08:00:33","date_gmt":"2017-05-05T11:00:33","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=65086"},"modified":"2017-05-04T19:14:56","modified_gmt":"2017-05-04T22:14:56","slug":"pesquisadores-fazem-apelo-no-surto-de-febre-amarela-nao-matem-os-macacos","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/pesquisadores-fazem-apelo-no-surto-de-febre-amarela-nao-matem-os-macacos\/","title":{"rendered":"Pesquisadores fazem apelo no surto de febre amarela: n\u00e3o matem os macacos"},"content":{"rendered":"<div id=\"widgetNotify\" class=\"widgetNotify\"><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/?attachment_id=65087\" rel=\"attachment wp-att-65087\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-65087\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/macaco-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/macaco-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/macaco.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Enquanto se espalha pelo Brasil o medo do ressurgimento da febre amarela, as autoridades de sa\u00fade lan\u00e7am uma advert\u00eancia: parem de matar os macacos.<\/div>\n<section id=\"conteudo\" class=\"has-submenu\">\n<div class=\"centraliza\">\n<section>\n<article id=\"conteudo-principal\" class=\"canal-media rod news\">\n<div id=\"texto\">\n<p>Algumas pessoas mataram macacos a pauladas em rea\u00e7\u00f5es de p\u00e2nico ao mais alarmante surto em d\u00e9cadas de um v\u00edrus que assolou o Brasil no s\u00e9culo 19 e in\u00edcio do 20. As autoridades encontraram outros macacos mortos com o cr\u00e2nio quebrado depois de ser atacados com pedras. Um macaco foi queimado.<\/p>\n<div class=\"mod-foto-embed w300x200\">\n<p><span class=\"credito\">Halder Ramos\/Divulga\u00e7\u00e3o Gramadozoo<\/span><\/p>\n<div class=\"figure\">\n<div class=\"pinit-wraper\"><img loading=\"lazy\" class=\"pinit-img\" src=\"https:\/\/conteudo.imguol.com.br\/c\/noticias\/7c\/2017\/02\/01\/01fev2017---bugio-ruivo-atacado-em-nova-petropolis-se-recupera-no-zoologico-de-gramado-rs-1485972190646_300x200.jpg\" width=\"636\" height=\"424\" \/><\/div>\n<\/div>\n<p><span class=\"legenda pg-color10\">Bugio-ruivo atacado em Nova Petr\u00f3polis, no Rio Grande do Sul<\/span><\/p>\n<\/div>\n<p><strong>Especialistas em doen\u00e7as infecciosas dizem que as pessoas est\u00e3o visando o alvo errado. Os mosquitos, e n\u00e3o macacos, s\u00e3o na verdade o vetor do v\u00edrus<\/strong>, e os primatas est\u00e3o morrendo de febre amarela em n\u00famero muito maior que os seres humanos no Brasil. Os que matam macacos est\u00e3o agravando a situa\u00e7\u00e3o, ao dizimar as popula\u00e7\u00f5es de macacos que servem como ind\u00edcios de onde a febre est\u00e1 se espalhando, dizem os epidemiologistas.&#8221;Eles est\u00e3o colocando os seres humanos em risco ainda maior ao matar o mensageiro&#8221;, disse Renato Alves, uma autoridade do Minist\u00e9rio da Sa\u00fade do Brasil que est\u00e1 acompanhando o surto.<\/p>\n<p><cite>Os macacos s\u00e3o um mecanismo de alerta crucial, que monitoramos para distribuir vacinas e iniciativas de preven\u00e7\u00e3o nos lugares certos.&#8221;<\/cite><\/p>\n<p><strong>Renato Alves<\/strong><\/p>\n<p>Os apelos das autoridades para que parem de matar os macacos no Brasil, que tem a mais rica diversidade de primatas do mundo,\u00a0ocorrem em meio \u00e0 ampla preocupa\u00e7\u00e3o sobre o vigor renovado de um v\u00edrus que se classifica entre as maiores amea\u00e7as \u00e0 sa\u00fade p\u00fablica aqui antes do in\u00edcio dos programas de vacina\u00e7\u00e3o em massa, nos anos 1940.<\/p>\n<p>A febre amarela, que pode incluir sintomas como icter\u00edcia, febre alta e falhas de m\u00faltiplos \u00f3rg\u00e3os, j\u00e1 matou pelo menos 240 pessoas nos \u00faltimos meses, segundo o Minist\u00e9rio. A doen\u00e7a, normalmente encontrada em partes da bacia Amaz\u00f4nica, se disseminou pelos Estados mais populosos do pa\u00eds: Minas Gerais, Rio de Janeiro e S\u00e3o Paulo.<\/p>\n<div class=\"mod-foto-embed w615x300\">\n<p><span class=\"credito\">Ricardo Borges\/Folhapress<\/span><\/p>\n<div class=\"figure\">\n<div class=\"pinit-wraper\"><img loading=\"lazy\" class=\"pinit-img\" src=\"https:\/\/conteudo.imguol.com.br\/c\/noticias\/40\/2017\/03\/21\/febre-amarela-no-rio-retoma-medo-de-avanco-e-urbanizacao-da-doenca-1490086551409_615x300.jpg\" width=\"638\" height=\"311\" \/><\/div>\n<\/div>\n<p><span class=\"legenda pg-color10\">Fila para vacina\u00e7\u00e3o contra febre amarela no Rio de Janeiro<\/span><\/p>\n<\/div>\n<p>Enquanto a febre amarela sai da Amaz\u00f4nia, as autoridades de v\u00e1rias \u00e1reas do sudeste do Brasil relataram nas \u00faltimas semanas epis\u00f3dios de macacos sendo mortos ilegalmente, envolvendo uma s\u00e9rie de m\u00e9todos, como envenenamento, tiros e pauladas.<\/p>\n<p>As mortes refletem uma grande incompreens\u00e3o no pa\u00eds sobre como a febre amarela se propaga. Os casos selv\u00e1ticos, que ocorrem na natureza, envolvem macacos que s\u00e3o infectados por esp\u00e9cies de mosquitos que habitam a floresta.<\/p>\n<p>Os mesmos mosquitos transmitem o v\u00edrus para seres humanos que entram na mata, como garimpeiros, ca\u00e7adores ou madeireiros. Esses surtos s\u00e3o geralmente pequenos. Enquanto a febre amarela \u00e9 muitas vezes assintom\u00e1tica em humanos, os pacientes que desenvolvem sintomas severos podem morrer em sete a dez dias.<\/p>\n<p>&#8220;As pessoas nas regi\u00f5es onde a febre amarela est\u00e1 avan\u00e7ando muitas vezes n\u00e3o percebem como os macacos s\u00e3o importantes para nos informar sobre a doen\u00e7a&#8221;, disse Danilo Simonini Teixeira, presidente da Sociedade Brasileira de Primatologia.<\/p>\n<p>Os macacos morreram em n\u00famero muito maior que os humanos no atual surto selv\u00e1tico no Brasil. <strong>As autoridades estimam que mais de 4.400 desses animais morreram de febre amarela nos \u00faltimos meses; subesp\u00e9cies como os bugios s\u00e3o especialmente vulner\u00e1veis.<\/strong><\/p>\n<h3>Avan\u00e7o da febre amarela<\/h3>\n<p>Enquanto o surto deixou muitas pessoas nervosas, especialistas em v\u00edrus temem a possibilidade de que a febre amarela possa sair de controle, disseminando-se rapidamente pelas cidades, despertando fantasmas de epidemias que devastaram \u00e1reas urbanas como o Rio de Janeiro h\u00e1 mais de um s\u00e9culo.<\/p>\n<p>Nos surtos urbanos, as pessoas infectadas geralmente introduzem a febre amarela em \u00e1reas muito populosas, onde o v\u00edrus pode ser transmitido por mosquitos <em>Aedes aegypti<\/em>, a mesma esp\u00e9cie de grande resist\u00eancia que propaga v\u00edrus como chikungunya, dengue e zika.<\/p>\n<p>Enquanto a \u00c1frica enfrentou recentemente esses surtos urbanos, inclusive uma epidemia em 2016 em Angola, eles s\u00e3o raros nas cidades da Am\u00e9rica do Sul. Em 2008, epidemiologistas encontraram transmiss\u00e3o de febre amarela por <em>Aedes aegypti<\/em> na capital do Paraguai, Assun\u00e7\u00e3o. <strong>O \u00faltimo surto urbano confirmado da doen\u00e7a nas Am\u00e9ricas teria ocorrido nos anos 1940.<\/strong><\/p>\n<p>Enquanto as autoridades voltam a combater esse mal no Brasil, manifestam seu al\u00edvio de que ele n\u00e3o evoluiu para um surto urbano. Quase 19 milh\u00f5es de doses da vacina est\u00e3o sendo distribu\u00eddas em \u00e1reas onde o v\u00edrus se espalha. A <strong>Organiza\u00e7\u00e3o Mundial de Sa\u00fade tamb\u00e9m est\u00e1 fornecendo ao pa\u00eds 3,5 milh\u00f5es de doses da vacina de seu estoque de emerg\u00eancia.<\/strong><\/p>\n<p>Al\u00e9m de pedir que as pessoas sejam vacinadas e parem de matar os macacos, as autoridades brasileiras est\u00e3o pedindo que eliminem locais com \u00e1gua parada, onde os mosquitos podem procriar, como pneus velhos ou pisos de chuveiros. Mas em partes pobres do Brasil, onde a febre amarela atingiu mais forte, alguns dizem que as autoridades demoraram para reagir.<\/p>\n<div class=\"modflash center modulos grande uolmais\">\n<div class=\"conteudo\">\n<h3 class=\"color14\">Sal em recipiente que acumula \u00e1gua evita mosquito; veja dicas de agente<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/section>\n<\/div>\n<\/section>\n<div id=\"texto\">\n<p>&#8220;\u00c9 claro que ca\u00e7ar macacos \u00e9 errado, mas quando os macacos come\u00e7aram a aparecer mortos de febre amarela a vacina\u00e7\u00e3o deveria ter come\u00e7ado&#8221;, disse Dalia de Oliveira, 30, uma manicure. Seu primo, Watila dos Santos, um oper\u00e1rio da constru\u00e7\u00e3o de 38 anos, morreu em mar\u00e7o pelo v\u00edrus em Casimiro de Abreu, no interior do Estado do Rio.<\/p>\n<p>&#8220;Ele foi ao hospital p\u00fablico e foi diagnosticado erradamente com sinusite&#8221;, disse Oliveira. &#8220;As autoridades poderiam ter sido mais atuantes na preven\u00e7\u00e3o dessa trag\u00e9dia, mas preferiram minimizar a situa\u00e7\u00e3o.&#8221;<\/p>\n<p>O ministro da Sa\u00fade do Brasil, Ricardo Barros, admitiu em uma entrevista que menos pessoas teriam morrido nos \u00faltimos meses se o governo tivesse reagido mais vigorosamente nas primeiras fases do surto.<\/p>\n<p><strong>&#8220;Pode ter havido uma falha na vacina\u00e7\u00e3o depois que os primeiros macacos apareceram mortos em Minas Gerais&#8221;<\/strong>, disse Barros, citando o Estado mais atingido pelo surto, com mais de 160 mortes.<\/p>\n<p>Especialistas em doen\u00e7as infecciosas est\u00e3o tentando determinar por que a febre amarela surge com maior ferocidade neste ano no Brasil. A doutora Anna Durbin, pesquisadora na Escola de Sa\u00fade P\u00fablica Bloomberg da Universidade Johns Hopkins, disse que uma combina\u00e7\u00e3o de fatores pode estar em a\u00e7\u00e3o, incluindo a mudan\u00e7a clim\u00e1tica e o desflorestamento de \u00e1reas que servem como zonas tamp\u00e3o entre florestas tropicais e \u00e1reas urbanas.<\/p>\n<p>&#8220;Uma grande preocupa\u00e7\u00e3o \u00e9 que o v\u00edrus salte o Canal do Panam\u00e1&#8221; para a Am\u00e9rica Central, disse Durbin.<\/p>\n<p>O v\u00edrus tamb\u00e9m pode ter o potencial de se espalhar para Porto Rico e gerar casos relacionados a viagens nos EUA continentais, disseram recentemente no &#8220;The New England Journal of Medicine&#8221; os doutores Anthony S. Fauci e Catharine I. Paules, do Instituto Nacional de Alergias dos EUA. No final de abril, os Centros de Controle e Preven\u00e7\u00e3o de Doen\u00e7as (CDC) dos EUA advertiram sobre a falta de vacinas contra febre amarela no pa\u00eds, por causa de recentes problemas de fabrica\u00e7\u00e3o.<br \/>\nEnquanto os epidemiologistas monitoram o avan\u00e7o da doen\u00e7a em partes do Brasil, os macacos continuam aparecendo mortos, seja pela m\u00e3o do homem ou em consequ\u00eancia do v\u00edrus. Pesquisadores dizem que o v\u00edrus amea\u00e7a esp\u00e9cies j\u00e1 em risco de extin\u00e7\u00e3o, como o mico-le\u00e3o dourado, que vive nas florestas do Rio de Janeiro.<\/p>\n<p>Karen Strier, uma antrop\u00f3loga da Universidade de Wisconsin que estuda macacos na mata Atl\u00e2ntica do Brasil desde os anos 1980, disse que nunca viu macacos morrerem por doen\u00e7a em n\u00fameros t\u00e3o elevados. Ela descreveu uma &#8220;sensa\u00e7\u00e3o de vazio&#8221; em uma reserva perto de Caratinga, em Minas Gerais, de onde desapareceram muitos bugios.<\/p>\n<p><span class=\"tradutor\"> Tradutor:<\/span> Luiz Roberto Mendes Gon\u00e7alves<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Enquanto se espalha pelo Brasil o medo do ressurgimento da febre amarela, as autoridades de<\/p>\n","protected":false},"author":6,"featured_media":65087,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/macaco.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/macaco-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/macaco-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/macaco.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/macaco.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/macaco.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/macaco.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/macaco.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/macaco.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/05\/macaco.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Enquanto se espalha pelo Brasil o medo do ressurgimento da febre amarela, as autoridades de","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/65086"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=65086"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/65086\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/65087"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=65086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=65086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=65086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}