{"id":64703,"date":"2017-04-29T15:00:07","date_gmt":"2017-04-29T18:00:07","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=64703"},"modified":"2017-04-29T09:25:00","modified_gmt":"2017-04-29T12:25:00","slug":"alteracoes-climaticas-sao-responsaveis-pelo-aumento-do-nivel-do-mar-e-seca-intensa","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/alteracoes-climaticas-sao-responsaveis-pelo-aumento-do-nivel-do-mar-e-seca-intensa\/","title":{"rendered":"Altera\u00e7\u00f5es clim\u00e1ticas s\u00e3o respons\u00e1veis pelo aumento do n\u00edvel do mar e seca intensa"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/?attachment_id=64704\" rel=\"attachment wp-att-64704\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-64704\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/alteraco_climatica-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/alteraco_climatica-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/alteraco_climatica.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>O governo cubano aprovou um plano governamental com intuito de minimizar os efeitos das mudan\u00e7as clim\u00e1ticas que desde j\u00e1 amea\u00e7am a ilha, segundo informa\u00e7\u00f5es publicadas nesta sexta-feira na imprensa local. As mudan\u00e7as no clima s\u00e3o respons\u00e1veis pelo aumento do n\u00edvel do mar, desastres naturais e a seca intensa.<\/p>\n<p>Trata-se de uma proposta com intuito de pensar \u201ccomo avan\u00e7ar por meio de a\u00e7\u00f5es concretas para minimizar os impactos (ambientais)\u201d, declarou a ministra cubana de Ci\u00eancia, Tecnologia e Meio Ambiente, Elba Rosa P\u00e9rez.<\/p>\n<p>O plano foi aprovado na \u00faltima ter\u00e7a-feira em reuni\u00e3o do Conselho de ministros, liderada pelo presidente Ra\u00fal Castro. A proposta ser\u00e1 votada na primeira sess\u00e3o do Parlamento, que acontecer\u00e1 em julho, de acordo com o jornal oficial \u201cGranma\u201d.<\/p>\n<p>P\u00e9rez destacou as tr\u00eas \u00e1reas priorit\u00e1rias do macroprojeto: a preserva\u00e7\u00e3o da vida das pessoas nos locais mais vulner\u00e1veis, a seguran\u00e7a alimentar e o desenvolvimento tur\u00edstico, com previs\u00f5es de investimentos \u201cpara curto (2020), m\u00e9dio (2030), longo (2050) e muito longo (2100) prazo\u201d.<\/p>\n<p>Dentre as medidas propostas para \u201cminimizar os efeitos em zonas vulner\u00e1veis\u201d, est\u00e3o \u201ca n\u00e3o permiss\u00e3o da constru\u00e7\u00e3o de novos empreendimentos pr\u00f3ximos \u00e0 zona costeira e a redu\u00e7\u00e3o da \u00e1rea de cultivo agr\u00edcola nesses locais\u201d, argumentou a ministra.<\/p>\n<p>Ela acrescentou que no plano est\u00e3o inclusas a\u00e7\u00f5es com objetivo de \u201cassegurar a disponibilidade e o uso eficiente da \u00e1gua como forma de se enfrentar a seca, al\u00e9m de direcionar o reflorestamento para permitir a m\u00e1xima prote\u00e7\u00e3o do solo e da \u00e1gua, impedir a deteriora\u00e7\u00e3o dos corais, al\u00e9m de repovoar e conserv\u00e1-los\u201d.<\/p>\n<p>As mudan\u00e7as clim\u00e1ticas \u201cagravar\u00e3o os problemas ambientais, transformando-se em fator determinante do desenvolvimento sustent\u00e1vel\u201d, afirma P\u00e9rez. \u201cTemos que nos preparar\u201d.<\/p>\n<p>O arquip\u00e9lago de 111.000 km2 com uma popula\u00e7\u00e3o de 11,2 milh\u00f5es de habitantes, est\u00e1 amea\u00e7ada, assim como o resto das ilhas caribenhas, pelo aumento do n\u00edvel no mar e desastres naturais cada vez mais frequentes, como furac\u00f5es de grande intensidade.<\/p>\n<p>Conforme os especialistas, o clima de Cuba tornou-se mais extremo e quente devido \u00e0s mudan\u00e7as clim\u00e1ticas, e a ilha enfrenta desde 2014 uma situa\u00e7\u00e3o de intensa seca que atinge quase todo o seu territ\u00f3rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governo cubano aprovou um plano governamental com intuito de minimizar os efeitos das mudan\u00e7as<\/p>\n","protected":false},"author":7,"featured_media":64704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/alteraco_climatica.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/alteraco_climatica-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/alteraco_climatica-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/alteraco_climatica.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/alteraco_climatica.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/alteraco_climatica.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/alteraco_climatica.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/alteraco_climatica.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/alteraco_climatica.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/alteraco_climatica.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"O governo cubano aprovou um plano governamental com intuito de minimizar os efeitos das mudan\u00e7as","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/64703"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=64703"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/64703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/64704"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=64703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=64703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=64703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}