{"id":59345,"date":"2017-02-06T12:27:55","date_gmt":"2017-02-06T15:27:55","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=59345"},"modified":"2017-02-06T12:27:56","modified_gmt":"2017-02-06T15:27:56","slug":"avanco-da-mancha-branca-derruba-producao-de-camaroes-no-ceara","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/avanco-da-mancha-branca-derruba-producao-de-camaroes-no-ceara\/","title":{"rendered":"Avan\u00e7o da mancha branca derruba produ\u00e7\u00e3o de camar\u00f5es no Cear\u00e1"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/avanco-da-mancha-branca-derruba-producao-de-camaroes-no-ceara\/camarao-4\/\" rel=\"attachment wp-att-59346\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-59346\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/camarao-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/camarao-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/camarao.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>O aposentado Newton Bruno de Farias est\u00e1 acostumado a comprar camar\u00e3o, mas o pre\u00e7o est\u00e1 sendo uma novidade pra ele. &#8220;\u00c0s vezes eu comprava de dez, vinte quilos, agora \u00e9 s\u00f3 dois quilos e t\u00e1 bom&#8221;, diz.<\/p>\n<p>\u00c9 o comportamento da maioria dos consumidores no mercado dos peixes em Fortaleza. O quilo do camar\u00e3o m\u00e9dio passou de R$ 15 para R$ 35 reais do meio do ano passado para c\u00e1, desde que a mancha branca chegou ao Cear\u00e1.<\/p>\n<p>A mancha branca \u00e9 causada por um v\u00edrus que se manifesta na fase inicial de desenvolvimento, calcificando e mudando a cor do crust\u00e1ceo. Ele morre e contamina os outros, por isso, produ\u00e7\u00f5es inteiras s\u00e3o perdidas antes de chegar ao consumidor.<\/p>\n<p>A doen\u00e7a foi detectada pela primeira vez na \u00c1sia em 1993. Dois anos depois j\u00e1 atingia os Estados Unidos e logo chegou \u00e0 Am\u00e9rica do Sul. A mancha branca apareceu no <a class=\"premium-tip\" href=\"http:\/\/g1.globo.com\/tudo-sobre\/ceara\">Cear\u00e1<\/a> no meio do ano passado. Em seis meses, 30 mil toneladas de camar\u00e3o foram perdidas; o equivalente a 60% da produ\u00e7\u00e3o do per\u00edodo.<\/p>\n<p>Em uma fazenda de cultivo em Cascavel, o surgimento da doen\u00e7a pegou o dono de surpresa. Antes da doen\u00e7a, todo o ciclo de crescimento do camar\u00e3o acontecia nos viveiros ao ar livre. Com a mancha branca foi preciso construir estufas pra servirem como ber\u00e7\u00e1rio nos trinta primeiros dias. Mas agora, o camar\u00e3o vai ser cultivado dentro de uma estufa na fazenda, at\u00e9 sair pro consumidor.<\/p>\n<p>&#8220;N\u00e3o adiantou a gente ter feito a estufa, se a larva n\u00e3o veio de qualidade. N\u00e3o era uma larva boa. J\u00e1 veio com v\u00edrus. J\u00e1 veio com alta carga viral. Ent\u00e3o replicou no viveiro. N\u00e3o teve sa\u00edda&#8221;, comenta Jo\u00e3o Paulino, engenheiro de pesca.<\/p>\n<p>Na fazenda, pelo menos cinco toneladas foram perdidas, quase toda a produ\u00e7\u00e3o da fazenda. Agora, depois de gastar quatrocentos mil reais nas estufas do ber\u00e7\u00e1rio, ser\u00e1 necess\u00e1rio mais meio milh\u00e3o para cobrir dois viveiros onde o camar\u00e3o vai permanecer at\u00e9 a fase final de engorda.<\/p>\n<p>&#8220;A gente vai tentar fazer o cultivo numa temperatura alta, temperatura m\u00e9dia de trinta e dois graus, que \u00e9 o que inativa o v\u00edrus e a gente tamb\u00e9m tem que monitorar a larva. N\u00e3o adianta a gente fazer o dever de casa e a larva vim uma larva ruim\u201d, explica o engenheiro.<\/p>\n<p>O presidente da Associa\u00e7\u00e3o Cearense de Criadores de Camar\u00e3o concorda. Ele diz que todos os pa\u00edses onde a mancha branca chegou, passaram a investir no trabalho em laborat\u00f3rio, para selecionar larvas mais resistentes, e em cuidados no manejo.<\/p>\n<p>&#8220;L\u00e1 na fazenda o produtor vai ter que se acostumar com ela: criar menos animal por metros quadrado, que diminui a carga viral do viveiro, e aumentar a capacidade de \u00e1gua, com \u00e1gua melhor, alimenta\u00e7\u00e3o mais forte. Como todo ser vivo, ele tem que estar mais resistente pra poder enfrentar o v\u00edrus&#8221;, alerta Cristiano Maia, presidente da Associa\u00e7\u00e3o Cearense de Criadores de Camar\u00e3o.<\/p>\n<p>A mancha branca foi encontrada tamb\u00e9m em cria\u00e7\u00f5es em Santa Catarina, Bahia, Pernambuco, Rio Grande do Norte, Sergipe, Para\u00edba e Piau\u00ed.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O aposentado Newton Bruno de Farias est\u00e1 acostumado a comprar camar\u00e3o, mas o pre\u00e7o est\u00e1<\/p>\n","protected":false},"author":7,"featured_media":59346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/camarao.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/camarao-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/camarao-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/camarao.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/camarao.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/camarao.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/camarao.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/camarao.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/camarao.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/camarao.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"O aposentado Newton Bruno de Farias est\u00e1 acostumado a comprar camar\u00e3o, mas o pre\u00e7o est\u00e1","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/59345"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=59345"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/59345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/59346"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=59345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=59345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=59345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}