{"id":59325,"date":"2017-02-06T07:00:34","date_gmt":"2017-02-06T10:00:34","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=59325"},"modified":"2017-02-05T20:22:19","modified_gmt":"2017-02-05T23:22:19","slug":"adocao-de-polietileno-de-origem-renovavel-e-crescente-entre-empresas-do-segmento","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/adocao-de-polietileno-de-origem-renovavel-e-crescente-entre-empresas-do-segmento\/","title":{"rendered":"Ado\u00e7\u00e3o de polietileno de origem renov\u00e1vel \u00e9 crescente entre empresas do segmento"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/?attachment_id=59326\" rel=\"attachment wp-att-59326\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-59326\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/plastico_verde-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/plastico_verde-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/plastico_verde.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Em todo o mundo, o setor de bebidas \u00e9 um dos mais engajados na busca de solu\u00e7\u00f5es inovadoras que tornem seu neg\u00f3cio mais sustent\u00e1vel e, portanto, com menor impacto no meio ambiente. O segmento \u00e9, por exemplo, um dos que adota o Pl\u00e1stico Verde, produzido a partir de etanol de cana-de-a\u00e7\u00facar \u2013tecnologia exclusiva desenvolvida pela Braskem, maior petroqu\u00edmica das Am\u00e9ricas.<\/p>\n<p>A \u00faltima empresa brasileira a adotar o Pl\u00e1stico Verde I\u2019m green\u2122, foi a Serra da Cantareira \u00c1guas Minerais. A companhia passou a utilizar a mat\u00e9ria-prima renov\u00e1vel em tampas de \u00e1gua mineral da marca Puraqua. Ainda em 2016, a Woolworths, uma das principais redes de supermercados \u00c1frica do Sul, tamb\u00e9m anunciou o uso do polietileno de origem renov\u00e1vel em suas embalagens de leite. J\u00e1 a alem\u00e3 Eckes-Guanini passou a usar o Pl\u00e1stico Verde em seus sucos org\u00e2nicos para as marcas Bramhults e Valsolille.<\/p>\n<p>Outras companhias que firmaram parceria com a Braskem foi a japonesa Asahi aplicando o Pl\u00e1stico nas tampas dos refrigerantes da marca Mitsuya Cider, de 1,5 litro. J\u00e1 a japonesa e l\u00edder neste segmento, a Suntory, recentemente passou a utilizar a resina nas tampas de suas garrafas de \u00e1gua mineral de 550 ml \u201cSuntory Aso Tennensui\u201d, cuja produ\u00e7\u00e3o anual \u00e9 estimada em 26 milh\u00f5es de unidades.<\/p>\n<p>Em 2015, a Pernod Ricard Brasil, afiliada da multinacional francesa de destilados, vinhos e champanhes, foi a primeira empresa de destilados a adotar o Pl\u00e1stico Verde I\u2019m green\u2122 nas tampas dos seus produtos Rum Montilla e Vodka Orloff. O polietileno de origem renov\u00e1vel tamb\u00e9m pode ser encontrado em rolhas de garrafas de vinho fabricadas pela Nomacorc. Denominadas Select\u00aeBio, as rolhas s\u00e3o 100% recicl\u00e1veis e apresentam o mesmo desempenho em controle do oxig\u00eanio que a linha convencional, al\u00e9m de evitar a deteriora\u00e7\u00e3o e desperd\u00edcio causados por processos como oxida\u00e7\u00e3o e redu\u00e7\u00e3o.<\/p>\n<p>A Tetra Pak, maior fornecedora mundial de embalagens tipo longa vida, usa desde 2012 tampas feitas de Pl\u00e1stico Verde. Al\u00e9m disso, h\u00e1 mais de dois anos, a companhia tamb\u00e9m usa polietileno de baixa densidade (LDPE) I\u2019m green\u2122 como componente das camadas de suas embalagens cartonadas. A Nestl\u00e9 foi uma das ind\u00fastrias pioneiras no uso do Pl\u00e1stico Verde, ao adotar a solu\u00e7\u00e3o nas linhas Ninho e Molico em junho de 2011, pouco depois do lan\u00e7amento da resina.<\/p>\n<p><strong>Pegada de Carbono<\/strong><\/p>\n<p>Em abril, o pl\u00e1stico verde I\u2019m green\u2122 recebeu a certifica\u00e7\u00e3o da pegada de carbono do Minist\u00e9rio do Desenvolvimento da Ind\u00fastria e do Com\u00e9rcio (MDIC), dentro das a\u00e7\u00f5es para implementar a Pol\u00edtica Nacional de Mudan\u00e7as Clim\u00e1ticas em setores priorit\u00e1rios. De acordo com a medi\u00e7\u00e3o, realizada pela Carbon Trust e pela ABNT (Associa\u00e7\u00e3o Brasileira de Normas T\u00e9cnicas), o polietileno de origem renov\u00e1vel tem uma pegada de emiss\u00f5es negativa, ou seja, ajuda a sequestrar o g\u00e1s poluente da atmosfera.<\/p>\n<p><strong>Sobre o Pl\u00e1stico Verde<\/strong><\/p>\n<p>O Polietileno Verde I\u2019m green\u2122 \u00e9 feito a partir do eteno obtido do etanol de cana-de-a\u00e7\u00facar. Seu grande diferencial \u00e9 contribuir para a redu\u00e7\u00e3o da emiss\u00e3o dos gases do efeito estufa na atmosfera, j\u00e1 que captura g\u00e1s carb\u00f4nico durante o seu processo produtivo. Ele tamb\u00e9m apresenta as mesmas caracter\u00edsticas do polietileno tradicional, ou seja, n\u00e3o necessita de adapta\u00e7\u00f5es de maquin\u00e1rio e \u00e9 100% recicl\u00e1vel. A planta de Pl\u00e1stico Verde da Braskem possui capacidade de produ\u00e7\u00e3o de 200 mil toneladas por ano.<\/p>\n<p><strong>Sobre a Braskem<\/strong><\/p>\n<p>A Braskem \u00e9 a maior produtora de resinas termopl\u00e1sticas das Am\u00e9ricas, com volume anual superior a 20 milh\u00f5es de toneladas, incluindo a produ\u00e7\u00e3o de outros produtos qu\u00edmicos e petroqu\u00edmicos b\u00e1sicos, e com faturamento anual de R$ 54 bilh\u00f5es. Com o prop\u00f3sito de melhorar a vida das pessoas, criando as solu\u00e7\u00f5es sustent\u00e1veis da qu\u00edmica e do pl\u00e1stico, a Braskem atua em mais de 70 pa\u00edses, conta com 8 mil integrantes e opera 41 unidades industriais, localizadas no Brasil, EUA, Alemanha e M\u00e9xico, esta \u00faltima em parceria com a mexicana Idesa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em todo o mundo, o setor de bebidas \u00e9 um dos mais engajados na busca<\/p>\n","protected":false},"author":7,"featured_media":59326,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/plastico_verde.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/plastico_verde-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/plastico_verde-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/plastico_verde.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/plastico_verde.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/plastico_verde.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/plastico_verde.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/plastico_verde.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/plastico_verde.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/02\/plastico_verde.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Em todo o mundo, o setor de bebidas \u00e9 um dos mais engajados na busca","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/59325"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=59325"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/59325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/59326"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=59325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=59325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=59325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}