{"id":57971,"date":"2017-01-17T14:30:41","date_gmt":"2017-01-17T17:30:41","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=57971"},"modified":"2017-01-17T09:20:57","modified_gmt":"2017-01-17T12:20:57","slug":"surto-de-cinomose-ja-matou-mais-de-15-mil-caes-em-oiapoque-ap","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/surto-de-cinomose-ja-matou-mais-de-15-mil-caes-em-oiapoque-ap\/","title":{"rendered":"Surto de cinomose j\u00e1 matou mais de 1,5 mil c\u00e3es na cidade de Oiapoque"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/?attachment_id=57972\" rel=\"attachment wp-att-57972\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-57972\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/01\/cianomose-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/01\/cianomose-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/01\/cianomose.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Um aumento nos casos de cinomose provocou a morte de pelo menos 1,5 mil c\u00e3es nos \u00faltimos 40 dias na cidade de Oiapoque, a 590 quil\u00f4metros de Macap\u00e1. As informa\u00e7\u00f5es s\u00e3o do m\u00e9dico veterin\u00e1rio Arnaldo Ballarini, pesquisador da Universidade Federal do Amap\u00e1 (Unifap).<\/p>\n<p>A doen\u00e7a, que n\u00e3o atinge o homem, \u00e9 fatal para os animais. O v\u00edrus teria vitimado pelo menos 50% da popula\u00e7\u00e3o canina da cidade, de acordo com o m\u00e9dico. Uma campanha de vacina\u00e7\u00e3o foi iniciada em Oiapoque com vacinas importadas dos Estados Unidos para reduzir os \u00edndices.<\/p>\n<p>\u201cNunca tinha visto nos meus 40 anos de profiss\u00e3o, uma mortandade t\u00e3o grande de c\u00e3es como estou vendo aqui em Oiapoque. Estamos passando por uma epidemia muito grande de cinomose e pegou praticamente todos os bairros\u201d, completa Ballarini, que ainda apura a origem do v\u00edrus que transmite a doen\u00e7a na cidade. A vacina\u00e7\u00e3o \u00e9 a principal forma de evitar os casos.<\/p>\n<p>Ap\u00f3s o animal estar contaminado \u00e9 necess\u00e1rio o uso de medicamentos para controlar os sintomas da infec\u00e7\u00e3o, que incluem v\u00f4mito, diarreia, emagrecimento, falta de apetite e des\u00e2nimo. O per\u00edodo de chuvas na cidade e a concentra\u00e7\u00e3o de muitos animais em um mesmo local pode ter sido uma das causas da prolifera\u00e7\u00e3o r\u00e1pida da cinomose.<\/p>\n<p>A doen\u00e7a tem atingido tanto os c\u00e3es adotados quanto os animais abandonados. C\u00e3es com cinomose tamb\u00e9m foram encontrados em distritos de Oiapoque, como em Vila Vit\u00f3ria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um aumento nos casos de cinomose provocou a morte de pelo menos 1,5 mil c\u00e3es<\/p>\n","protected":false},"author":7,"featured_media":57972,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/01\/cianomose.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/01\/cianomose-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/01\/cianomose-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/01\/cianomose.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/01\/cianomose.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/01\/cianomose.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/01\/cianomose.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/01\/cianomose.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/01\/cianomose.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/01\/cianomose.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Um aumento nos casos de cinomose provocou a morte de pelo menos 1,5 mil c\u00e3es","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/57971"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=57971"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/57971\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/57972"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=57971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=57971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=57971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}