{"id":56796,"date":"2016-12-31T12:23:24","date_gmt":"2016-12-31T15:23:24","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=56796"},"modified":"2016-12-31T12:23:46","modified_gmt":"2016-12-31T15:23:46","slug":"programacao-de-ferias-museu-dos-brinquedos-em-belo-horizonte","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/programacao-de-ferias-museu-dos-brinquedos-em-belo-horizonte\/","title":{"rendered":"Programa\u00e7\u00e3o de F\u00e9rias Museu dos Brinquedos em Belo Horizonte"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignright\" src=\"http:\/\/www.revistaecologico.com.br\/esite\/kcfinder\/upload\/images\/eventos\/fachada_do_museu_dos_brinquedos.jpg\" alt=\"fotoEvento\" width=\"321\" height=\"202\" \/>Data: 10 a 31 de janeiro (segunda \u00e0 s\u00e1bado)<br \/>\nLocal: Museu dos Brinquedos (Av. Afonso Pena, 2564 \u2013 Funcion\u00e1rios \/ BH)<br \/>\nHor\u00e1rio: Aberto a partir das 10h. Atividades com hor\u00e1rios diferenciados<br \/>\nInforma\u00e7\u00f5es: (31) 3261 3992<\/p>\n<h1 class=\"faixa box-amarelo-laranja\">Um museu para a crian\u00e7a<\/h1>\n<p><img loading=\"lazy\" class=\"alignright\" src=\"http:\/\/museudosbrinquedos.org.br\/2014\/wp\/wp-content\/uploads\/2014\/06\/exposio-h-1-320x320.jpg\" alt=\"\" width=\"320\" height=\"320\" \/>Um museu para o cheiro de grama molhada, para a sensa\u00e7\u00e3o de pisar o barro.<\/p>\n<p>Um museu para a primeira boneca, para o primeiro dia de aula, para o primeiro gol na pelada de rua.<\/p>\n<p>Um museu para a alegria das manh\u00e3s, para o riso, para a mem\u00f3ria, para a saudade.<\/p>\n<p>Um museu que eternize a inf\u00e2ncia n\u00e3o com a dist\u00e2ncia da vida que ventou e do tempo que passou, mas com a proximidade de saber que n\u00f3s vivemos e brincamos tudo aquilo.<\/p>\n<p>E que tamb\u00e9m por isso somos quem somos.<\/p>\n<p>Da\u00ed que fizemos um museu assim, pra entrar sorrindo e sair menino. Um museu para quem j\u00e1 foi crian\u00e7a e fez da boneca a melhor amiga, da bola de gude a maior conquista, de cada jogo uma aventura.<\/p>\n<p>Um mundo para viver o l\u00fadico. O Museu dos Brinquedos.<\/p>\n<h2 class=\"text-laranja\">Nossa sede<\/h2>\n<p><img loading=\"lazy\" class=\"alignright\" src=\"http:\/\/museudosbrinquedos.org.br\/2014\/wp\/wp-content\/uploads\/2014\/06\/img_20140731_143945731_hdr-320x320.jpg\" alt=\"\" width=\"320\" height=\"320\" \/>Uma casa bonitinha em uma avenida grandona, com nome de presidente. Tem quintal, tem olho que brilha, tem educa\u00e7\u00e3o, cultura e lazer.<\/p>\n<p>A casa \u00e9 do patrim\u00f4nio hist\u00f3rico da cidade de Belo Horizonte e de quem sabe brincar. E \u00e9 tamb\u00e9m de quem quiser pesquisar, preservar e divulgar a brincadeira e o jogo.<\/p>\n<p>S\u00e3o 5 mil brinquedos no acervo e 800, de diversos pa\u00edses, em exposi\u00e7\u00e3o permanente. Agora falta contar quantos sorrisos eles despertam.<\/p>\n<p>*Para conhecer melhor o acervo, acesse o link http:\/\/www.museudosbrinquedos.org.br\/acervo\/<\/p>\n<p>O Museu dos Brinquedos era um museu sem casa. Mentira. Era um museu que morava no cora\u00e7\u00e3o de uma menina sem idade.<\/p>\n<p><img loading=\"lazy\" class=\"alignright\" src=\"http:\/\/museudosbrinquedos.org.br\/2014\/wp\/wp-content\/uploads\/2014\/06\/museu-dos-brinquedos-320x320.png\" alt=\"\" width=\"320\" height=\"320\" \/>De 1986 a 1999, Luiza de Azevedo Meyer fez exposi\u00e7\u00f5es itinerantes em shoppings, casas de cultura e galerias de arte.<\/p>\n<p>Ela, que nasceu em S\u00e3o Jo\u00e3o Del Rey no ano de 1912, sempre soube que o brinquedo \u00e9 pavio da mem\u00f3ria e centelha da alegria. Guardou os seus, os dos seus dez filhos e ainda os dos seus 23 netos. Pesquisou, foi atr\u00e1s, conseguiu outros e plantou a semente de um lugar especial.<\/p>\n<p>Quando Luiza foi brincar com as estrelas em 2000, a fam\u00edlia e amigos prosseguiram com o sonho e criaram o Instituto Cultural Luiza Azevedo Meyer. Em outubro de 2006, o sonho virou Museu dos Brinquedos.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Data: 10 a 31 de janeiro (segunda \u00e0 s\u00e1bado) Local: Museu dos Brinquedos (Av. Afonso<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"cream-magazine-thumbnail-2":false,"cream-magazine-thumbnail-3":false,"cream-magazine-thumbnail-4":false},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Data: 10 a 31 de janeiro (segunda \u00e0 s\u00e1bado) Local: Museu dos Brinquedos (Av. Afonso","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/56796"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=56796"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/56796\/revisions"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=56796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=56796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=56796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}