{"id":56435,"date":"2016-12-26T09:00:25","date_gmt":"2016-12-26T12:00:25","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=56435"},"modified":"2016-12-26T09:06:59","modified_gmt":"2016-12-26T12:06:59","slug":"saiba-como-desintoxicar-o-corpo-apos-os-excessos-durante-o-natal","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/saiba-como-desintoxicar-o-corpo-apos-os-excessos-durante-o-natal\/","title":{"rendered":"Saiba como desintoxicar o corpo ap\u00f3s os excessos durante o Natal"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/saiba-como-desintoxicar-o-corpo-apos-os-excessos-durante-o-natal\/desintoxicar\/\" rel=\"attachment wp-att-56436\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-56436\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/12\/desintoxicar-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/12\/desintoxicar-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/12\/desintoxicar.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Exagerou na ceia de Natal? Consequ\u00eancias como o corpo inchado, alguns quilinhos a mais, cansa\u00e7o, m\u00e1 digest\u00e3o ou dor de cabe\u00e7a podem ser sentidas por causa do consumo de alimentos e bebidas em excesso. Mas calma, nem tudo est\u00e1 perdido. Para limpar o organismo e preparar o corpo para o r\u00e9veillon, especialistas indicam uma dieta de desintoxica\u00e7\u00e3o, mais conhecida como detox, que tem como objetivo diminuir a sobrecarga de subst\u00e2ncias t\u00f3xicas no organismo.<\/p>\n<p>\u2014 Alguns alimentos tamb\u00e9m t\u00eam o poder de eliminar toxinas do nosso organismo, melhorando a nossa disposi\u00e7\u00e3o e aumentando o gasto cal\u00f3rico. Por isso, sabendo us\u00e1-los a nosso favor, temos uma combina\u00e7\u00e3o de elementos primordiais quando o assunto \u00e9 emagrecimento saud\u00e1vel \u2014 afirma a nutricionista Fernanda Marques.<\/p>\n<p>Segundo a nutricionista Samara Lopes, da Renewmed, uma dieta detox \u00e9 rica em alimentos integrais, frescos e funcionais, que al\u00e9m de nutrir, aceleram o metabolismo. Dessa forma, a pessoa perde peso com sa\u00fade e sem sacrif\u00edcios.<\/p>\n<p>\u2014 O m\u00e9todo consiste basicamente em reduzir o consumo de industrializados e evitar refei\u00e7\u00f5es r\u00e1pidas e gordurosas, como frituras e carnes gordas. Os principais alimentos com subst\u00e2ncias antioxidantes s\u00e3o folhas verdes escuras, frutas c\u00edtricas, frutas vermelhas, oleaginosas e sementes \u2014 explica Samara.<\/p>\n<figure><strong> <img loading=\"lazy\" class=\"inline\" src=\"http:\/\/extra.globo.com\/incoming\/20694233-2a3-e58\/w448\/receitas-web.jpg\" alt=\"\" width=\"640\" height=\"1789\" \/> <\/strong><\/figure>\n<p><strong>Vil\u00f5es: radicais livres<\/strong><\/p>\n<p>Os alimentos que fazem parte da dieta antioxidante t\u00eam o poder de tirar os radicais livres de cena. De acordo com a nutricionista Samanta Lopes, em excesso, essas mol\u00e9culas danificam as c\u00e9lulas sadias, que deixam de exercer bem suas fun\u00e7\u00f5es.<\/p>\n<p>Para se defender desses inimigos, o organismo responde com processos inflamat\u00f3rios, comprometendo ainda mais as c\u00e9lulas e estabelecendo o ciclo vicioso de mais radicais livres e inflama\u00e7\u00e3o. E os preju\u00edzos v\u00eam aos montes: resist\u00eancia baixa, falta de disposi\u00e7\u00e3o, flacidez, incha\u00e7o e peso extra e at\u00e9 celulite.<\/p>\n<p>\u2014 Estresse, polui\u00e7\u00e3o, sedentarismo, cigarro, \u00e1lcool e alimenta\u00e7\u00e3o errada colaboram para a produ\u00e7\u00e3o exagerada de radicais livres, que s\u00e3o mol\u00e9culas com el\u00e9trons. \u00c0 procura de um parceiro para essa mol\u00e9cula solit\u00e1ria, os radicais livres se unem \u00e0s nossas c\u00e9lulas. Mas o casamento \u00e9 infeliz. Eles s\u00e3o loucos para enferruj\u00e1-las, acelerando o envelhecimento. E, caso se juntem a uma parte do DNA, podem acarretar doen\u00e7as graves, como c\u00e2ncer \u2014 ressalta Samanta, acrescentando: \u2014 Muita gente tem uma vis\u00e3o errada sobre a dieta detox, achando que ela tem baixa restri\u00e7\u00e3o cal\u00f3rica. O objetivo \u00e9 n\u00e3o comer apenas alimentos n\u00e3o industrializados.<\/p>\n<div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Exagerou na ceia de Natal? Consequ\u00eancias como o corpo inchado, alguns quilinhos a mais, cansa\u00e7o,<\/p>\n","protected":false},"author":6,"featured_media":56436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/12\/desintoxicar.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/12\/desintoxicar-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/12\/desintoxicar-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/12\/desintoxicar.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/12\/desintoxicar.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/12\/desintoxicar.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/12\/desintoxicar.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/12\/desintoxicar.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/12\/desintoxicar.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/12\/desintoxicar.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Exagerou na ceia de Natal? Consequ\u00eancias como o corpo inchado, alguns quilinhos a mais, cansa\u00e7o,","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/56435"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=56435"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/56435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/56436"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=56435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=56435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=56435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}