{"id":53207,"date":"2016-11-06T19:12:08","date_gmt":"2016-11-06T22:12:08","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=53207"},"modified":"2016-11-06T19:12:08","modified_gmt":"2016-11-06T22:12:08","slug":"acoes-de-conservacao-para-a-rppn-botujuru-em-mogi-das-cruzes","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/acoes-de-conservacao-para-a-rppn-botujuru-em-mogi-das-cruzes\/","title":{"rendered":"A\u00e7\u00f5es de conserva\u00e7\u00e3o para a RPPN Botujuru, em Mogi das Cruzes"},"content":{"rendered":"<p><em> Instituto Ecofuturo prop\u00f5e a\u00e7\u00f5es de conserva\u00e7\u00e3o para a RPPN Botujuru, em Mogi das Cruzes<\/em><br \/>\n<em>Entregue este m\u00eas, o resumo executivo do Plano de Manejo da \u00e1rea foi desenvolvido para compartilhar com a sociedade as principais informa\u00e7\u00f5es sobre a reserva.<\/em><\/p>\n<p><a href=\"http:\/\/www.envolverde.com.br\/wp-content\/uploads\/Botujuru.png\"><img loading=\"lazy\" class=\"size-full wp-image-215666 alignright\" src=\"http:\/\/www.envolverde.com.br\/wp-content\/uploads\/Botujuru.png\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"http:\/\/www.envolverde.com.br\/wp-content\/uploads\/Botujuru.png 300w, http:\/\/www.envolverde.com.br\/wp-content\/uploads\/Botujuru-150x150.png 150w\" alt=\"botujuru\" width=\"300\" height=\"300\" \/><\/a> O Ecofuturo, Organiza\u00e7\u00e3o da Sociedade Civil de Interesse P\u00fablico (OSCIP) que tem a Suzano Papel e Celulose como principal mantenedora, apresentou, este m\u00eas, o resumo executivo do Plano de Manejo da Reserva Particular do Patrim\u00f4nio Natural (RPPN) Botujuru \u2013 Serra do Itapety, em Mogi das Cruzes. O objetivo do documento \u00e9 compartilhar as principais informa\u00e7\u00f5es sobre a reserva de 437 hectares, sua import\u00e2ncia para a regi\u00e3o, para a sociedade e para a conserva\u00e7\u00e3o da biodiversidade. Al\u00e9m do resumo, o Instituto coordenou tamb\u00e9m a elabora\u00e7\u00e3o do Plano e \u00e9 respons\u00e1vel, desde 2015, por sua implanta\u00e7\u00e3o.<\/p>\n<p>Com uma \u201cheran\u00e7a natural\u201d privilegiada, Mogi das Cruzes possui atualmente cerca de 57% de seu territ\u00f3rio coberto por \u00e1reas legalmente protegidas. Por sua vez, a Serra do Itapeti, onde est\u00e1 a reserva, abriga aproximadamente 33 mil hectares de remanescentes de Mata Atl\u00e2ntica e \u00e9 a principal forma\u00e7\u00e3o de relevo, protegendo diversas nascentes que abastecem os rios Tiet\u00ea e Para\u00edba do Sul.<\/p>\n<p>J\u00e1 a \u00e1rea da RPPN Botujuru \u2013 Serra do Itapety, que pertence \u00e0 SPLF Investimentos e Participa\u00e7\u00f5es LTDA, empresa do Grupo Suzano, faz parte da Fazenda Rodeio e era anteriormente utilizada para o manejo de eucalipto. Hoje, o local \u00e9 uma reserva particular ambiental com car\u00e1ter perp\u00e9tuo para a conserva\u00e7\u00e3o.<\/p>\n<p>Na RPPN, foram identificadas mais de 380 esp\u00e9cies, sendo 108 da flora, 18 mam\u00edferos, 208 aves e 49 anf\u00edbios \u2013 entre elas, diversas s\u00e3o consideradas end\u00eamicas da Mata Atl\u00e2ntica e algumas est\u00e3o amea\u00e7adas de extin\u00e7\u00e3o, como a on\u00e7a-parda, a jaguatirica e a palmeira ju\u00e7ara. Al\u00e9m disso, durante os trabalhos de campo, registrou-se pela primeira vez nas \u00e1reas da Serra do Itapeti, a ocorr\u00eancia de tr\u00eas novas esp\u00e9cies de morcegos, sendo uma delas, a Myotis ruber, considerada vulner\u00e1vel \u00e0 extin\u00e7\u00e3o.<\/p>\n<p>Paulo Groke, diretor de Sustentabilidade do Instituto Ecofuturo, explica que a RPPN foi criada a partir da necessidade de potencializar esfor\u00e7os para a restaura\u00e7\u00e3o e conserva\u00e7\u00e3o da Mata Atl\u00e2ntica e sua biodiversidade na Serra do Itapeti. \u201cConsider\u00e1vel parte dos remanescentes de vegeta\u00e7\u00e3o nativa de S\u00e3o Paulo est\u00e3o presentes em propriedades particulares, fazendo com que a cria\u00e7\u00e3o e a manuten\u00e7\u00e3o de regi\u00f5es protegidas sejam importantes instrumentos para a conserva\u00e7\u00e3o da biodiversidade da Mata Atl\u00e2ntica no estado\u201d, diz.<\/p>\n<p>Sobre o Plano de Manejo, Groke afirma que este \u00e9 um dos primeiros passos para o direcionamento de a\u00e7\u00f5es necess\u00e1rias para orientar a gest\u00e3o da Unidade de Conserva\u00e7\u00e3o. \u201cO resumo executivo \u00e9 fundamental para compartilhar as principais informa\u00e7\u00f5es sobre a reserva com a sociedade e sua import\u00e2ncia ambiental\u201d, conclui o diretor.<\/p>\n<p>Al\u00e9m de definir os objetivos espec\u00edficos da \u00e1rea, programas para incentivo \u00e0 pesquisa cient\u00edfica e o interc\u00e2mbio de conhecimento t\u00e9cnico-cient\u00edfico, o levantamento apresentou tamb\u00e9m a proposta de zoneamento da reserva, vital para o processo de gest\u00e3o do local.<\/p>\n<p>O resumo executivo e o Plano de Manejo completo da RPPN Botujuru \u2013 Serra do Itapety podem ser acessados na Biblioteca Virtual do Instituto Ecofuturo, dispon\u00edvel para download no link: http:\/\/bibliotecavirtual.ecofuturo.org.br\/<\/p>\n<p>Sobre o Instituto Ecofuturo<br \/>\nO Instituto Ecofuturo \u00e9 uma Organiza\u00e7\u00e3o da Sociedade Civil de Interesse P\u00fablico (OSCIP), institu\u00edda e mantida pela Suzano Papel e Celulose. O Ecofuturo acredita que \u00e9 a partir da integra\u00e7\u00e3o do homem com a natureza, do entendimento de sua rela\u00e7\u00e3o com o todo, que a inten\u00e7\u00e3o se transforma em a\u00e7\u00e3o para mudar o presente e o futuro para melhor. Desde 1999, atua como articulador entre a sociedade civil, o poder p\u00fablico e o setor privado, buscando contribuir para a expans\u00e3o da consci\u00eancia socioambiental por meio do compartilhamento de saberes, pr\u00e1ticas de cuidado e mensura\u00e7\u00e3o de impactos. Mant\u00e9m projetos que contribuem para o fortalecimento das pr\u00e1ticas de leitura e escrita e pela conserva\u00e7\u00e3o do meio ambiente. Para mais informa\u00e7\u00f5es, visite www.ecofuturo.org.br.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Instituto Ecofuturo prop\u00f5e a\u00e7\u00f5es de conserva\u00e7\u00e3o para a RPPN Botujuru, em Mogi das Cruzes Entregue<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"cream-magazine-thumbnail-2":false,"cream-magazine-thumbnail-3":false,"cream-magazine-thumbnail-4":false},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Instituto Ecofuturo prop\u00f5e a\u00e7\u00f5es de conserva\u00e7\u00e3o para a RPPN Botujuru, em Mogi das Cruzes Entregue","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/53207"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=53207"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/53207\/revisions"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=53207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=53207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=53207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}