{"id":51000,"date":"2016-10-03T13:30:49","date_gmt":"2016-10-03T16:30:49","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=51000"},"modified":"2016-10-03T08:01:46","modified_gmt":"2016-10-03T11:01:46","slug":"lixo-politico-diminui-mas-santinhos-ainda-nao-sao-reciclados","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/lixo-politico-diminui-mas-santinhos-ainda-nao-sao-reciclados\/","title":{"rendered":"Lixo pol\u00edtico diminui, mas santinhos ainda n\u00e3o s\u00e3o reciclados"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/?attachment_id=51001\" rel=\"attachment wp-att-51001\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-51001\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/santinho-1-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/santinho-1-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/santinho-1.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Uma not\u00edcia \u00e9 boa: os tapetes de santinhos n\u00e3o s\u00e3o t\u00e3o comuns como nas elei\u00e7\u00f5es passadas. A outra not\u00edcia \u00e9 ruim: os panfletos dos candidatos recolhidos v\u00e3o parar em aterros comuns e n\u00e3o s\u00e3o reciclados. No Rio, Salvador e Recife, ainda se viu\u00a0locais de vota\u00e7\u00e3o, principalmente nas periferias, em que se acumulou o lixo pol\u00edtico, mas em outras cidades, como S\u00e3o Paulo, est\u00e1 mais dif\u00edcil ver a cena antes t\u00edpica das elei\u00e7\u00f5es brasileiras.<\/p>\n<p>A reportagem do UOL percorreu zonas eleitorais no centro e nas\u00a0zonas Oeste e Sul da capital paulista, e viu menos santinhos espalhados na porta de escolas do que em pleitos anteriores. Na cidade de Botelho (MG), a Justi\u00e7a Eleitoral convocou os<a href=\"http:\/\/eleicoes.uol.com.br\/2016\/ao-vivo\/2016\/10\/02\/1-turno-eleicoes-2016.htm#mg-candidatos-a-vereador-sao-obrigados-a-limpar-ruas-20161002130022\"><strong> candidatos a recolherem<\/strong><\/a> os santinhos que soltaram nas ruas.<\/p>\n<p>Em S\u00e3o Paulo, segundo a Amlurb, \u00f3rg\u00e3o respons\u00e1vel pela administra\u00e7\u00e3o da limpeza no munic\u00edpio, os panfletos\u00a0pol\u00edticos devem ser recolhidos com lixo comum e levados para aterros comuns. A Amlurb e as empresas concession\u00e1rias n\u00e3o\u00a0tiveram um esquema especial para a varri\u00e7\u00e3o neste domingo de elei\u00e7\u00e3o.<\/p>\n<p>Segundo as autoridades, os pap\u00e9is s\u00f3 s\u00e3o reciclados se separados e recolhidos em locais apropriados para isso. Nesse per\u00edodo do ano, ap\u00f3s a estiagem do inverno e o in\u00edcio da primavera, h\u00e1 muitas folhas e flores secas nas ruas que se misturam com as folhetos estampados com os candidatos. Depois de prometerem resolver os problemas das cidades e antes de cumprir qualquer coisa, os pol\u00edticos causam esse transtorno para a cidade que querem governar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma not\u00edcia \u00e9 boa: os tapetes de santinhos n\u00e3o s\u00e3o t\u00e3o comuns como nas elei\u00e7\u00f5es<\/p>\n","protected":false},"author":6,"featured_media":51001,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/santinho-1.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/santinho-1-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/santinho-1-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/santinho-1.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/santinho-1.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/santinho-1.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/santinho-1.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/santinho-1.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/santinho-1.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/santinho-1.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Uma not\u00edcia \u00e9 boa: os tapetes de santinhos n\u00e3o s\u00e3o t\u00e3o comuns como nas elei\u00e7\u00f5es","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/51000"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=51000"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/51000\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/51001"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=51000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=51000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=51000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}