{"id":50968,"date":"2016-10-03T15:00:39","date_gmt":"2016-10-03T18:00:39","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=50968"},"modified":"2016-10-03T07:18:52","modified_gmt":"2016-10-03T10:18:52","slug":"barack-obama-se-reune-com-dicaprio-para-debater-sobre-o-clima","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/barack-obama-se-reune-com-dicaprio-para-debater-sobre-o-clima\/","title":{"rendered":"Barack Obama se re\u00fane com DiCaprio para debater sobre o clima"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/?attachment_id=50969\" rel=\"attachment wp-att-50969\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-50969\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/caprio-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/caprio-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/caprio.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>O ator <a class=\"premium-tip\" href=\"http:\/\/g1.globo.com\/tudo-sobre\/leonardo-dicaprio\">Leonardo DiCaprio<\/a> comparecer\u00e1 nesta segunda-feira (3) \u00e0 Casa Branca para debater a quest\u00e3o do clima com o presidente <a class=\"premium-tip\" href=\"http:\/\/g1.globo.com\/tudo-sobre\/barack-obama\">Barack Obama<\/a>. O encontro acontece antes da exibi\u00e7\u00e3o de seu novo document\u00e1rio sobre os efeitos devastadores do aquecimento global.<\/p>\n<p>DiCaprio, vencedor do Oscar de melhor ator por &#8220;O Regresso&#8221;, participar\u00e1 em um debate com a cientista Katharine Hayhoe e com o presidente Obama, para fez da luta contra a mudan\u00e7a clim\u00e1tica uma das prioridades em seus dois mandatos \u00e0 frente dos Estados Unidos.<\/p>\n<p>O encontro acontecer\u00e1 como parte de um festival organizado nos jardins da Casa Branca seguindo o modelo do South by Southwest, que \u00e9 organizado todos os anos em Austin (<a class=\"premium-tip\" href=\"http:\/\/g1.globo.com\/tudo-sobre\/texas\">Texas<\/a>) e que mistura novas tecnologias, cinema e m\u00fasica.<\/p>\n<p>Quase 10 anos depois de seu primeiro document\u00e1rio sobre o desafio do clima, &#8220;The 11th hour&#8221; (&#8220;A \u00daltima Hora&#8221;), o ator retorna com o filme &#8220;Before the Flood&#8221;, no qual Barack Obama e o papa Francisco fazem uma r\u00e1pida apari\u00e7\u00e3o.<\/p>\n<p>&#8220;Sejam corajosos. Somos capazes de resolver os maiores desafios quando encontramos a vontade de trabalhar juntos&#8221;, afirmou DiCaprio em dezembro do ano passado em Paris, durante a confer\u00eancia COP21 sobre o clima.<\/p>\n<p>Em mar\u00e7o, Obama se tornou o primeiro presidente dos <a class=\"premium-tip\" href=\"http:\/\/g1.globo.com\/tudo-sobre\/estados-unidos\">Estados Unidos<\/a> a participar no festival South by Southwest.<\/p>\n<p>Ele anunciou que a Casa Branca organizaria sua pr\u00f3pria vers\u00e3o do evento, chamada de South By South Lawn, para celebrar a criatividade e o esp\u00edrito de inova\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ator Leonardo DiCaprio comparecer\u00e1 nesta segunda-feira (3) \u00e0 Casa Branca para debater a quest\u00e3o<\/p>\n","protected":false},"author":6,"featured_media":50969,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/caprio.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/caprio-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/caprio-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/caprio.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/caprio.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/caprio.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/caprio.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/caprio.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/caprio.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/10\/caprio.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"O ator Leonardo DiCaprio comparecer\u00e1 nesta segunda-feira (3) \u00e0 Casa Branca para debater a quest\u00e3o","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/50968"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=50968"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/50968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/50969"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=50968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=50968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=50968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}