{"id":4797,"date":"2014-08-14T14:00:02","date_gmt":"2014-08-14T14:00:02","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=4797"},"modified":"2014-08-14T12:06:26","modified_gmt":"2014-08-14T12:06:26","slug":"cientistas-pedem-apoio-da-igreja-no-combate-aos-organismos-transgenicos","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/cientistas-pedem-apoio-da-igreja-no-combate-aos-organismos-transgenicos\/","title":{"rendered":"Cientistas pedem apoio da Igreja no combate aos organismos transg\u00eanicos"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2014\/08\/conferencia_bispo.jpg\"><img loading=\"lazy\" class=\"alignleft size-full wp-image-4798\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2014\/08\/conferencia_bispo.jpg\" alt=\"\" width=\"415\" height=\"265\" \/><\/a>Por solicita\u00e7\u00e3o da Via Campesina, os engenheiros agr\u00f4nomos Paulo kageyama e Rubens Nodari entregaram ao secret\u00e1rio-geral da CNBB (Confer\u00eancia Nacional dos Bispos do Brasil), dom Leonardo Ulrich Steiner, e \u00e0 sociedade brasileira uma carta condenando o uso de transg\u00eanicos e explicando seus impactos. O mesmo documento foi entregue ao Papa Francisco em abril com o intuito de pedir que o Sumo Pont\u00edfice se posicione, criticamente, sobre este tipo de cultivo e apoie a agricultura campesina.<\/p>\n<p>A carta foi entregue durante uma entrevista coletiva, que teve tamb\u00e9m a participa\u00e7\u00e3o de Jo\u00e3o Pedro St\u00e9dile, integrante da dire\u00e7\u00e3o nacional do Movimento dos Trabalhadores Rurais Sem Terra (MST), representando os movimentos sociais e em especial a Via Campesina.<\/p>\n<p>Al\u00e9m de kageyama e Nodari, a carta tamb\u00e9m \u00e9 assinada pela engenheira agr\u00f4noma austr\u00edaca Ana Maria Primavesi; o argentino Andr\u00e9s Carrasco, especialista em biologia celular; Elena \u00c1lvarez-Buylla Roces, doutora em gen\u00e9tica molecular da Universidade do M\u00e9xico; Pat Mooney, investigador canadense; Paulo Yoshio Kageyama, engenheiro agr\u00f4nomo com especializa\u00e7\u00e3o em gen\u00e9tica e biodiversidade, da Universidade de S\u00e3o Paulo (USP); a f\u00edsica e fil\u00f3sofa indiana Vandana Shiva; e o m\u00e9dico especialista em Medicina do Trabalho Wanderlei Pignati, da Universidade Federal de Mato Grosso.<\/p>\n<p>Em poucas palavras, o documento explica o impacto dos transg\u00eanicos sobre as popula\u00e7\u00f5es rurais e urbanas, a soberania alimentar dos povos, a natureza e a economia, mostrando que os pa\u00edses do Sul v\u00eam sendo os principais afetados. Os cientistas apontam que estudos feitos ao redor do mundo comprovam que as sementes transg\u00eanicas produzem menos por hectare e necessitam de uma quantidade maior de agrot\u00f3xicos, causando tamb\u00e9m um aumento significativo do desemprego rural e, consequentemente, o esvaziamento do campo.<\/p>\n<p>\u201cO tema dos transg\u00eanicos n\u00e3o \u00e9 somente um debate cient\u00edfico e t\u00e9cnico, tem tamb\u00e9m fortes ramifica\u00e7\u00f5es econ\u00f4micas e pol\u00edticas. No entanto, muitos cientistas que defendem os cultivos transg\u00eanicos ocultam a maioria de seus problemas e incertezas cient\u00edficas, assim como o fato de que, com os transg\u00eanicos, as grandes corpora\u00e7\u00f5es de agroneg\u00f3cios avan\u00e7am para o controle absoluto do sistema agroalimentar\u201d, esclarece a carta, acrescentando que esse controle afeta, gravemente, a soberania alimentar, a sa\u00fade e o meio ambiente, al\u00e9m de impedir o desenvolvimento dos diversos sistemas agr\u00edcolas.<\/p>\n<p>Os cientistas destacam que \u00e9 particularmente grave o car\u00e1ter irrevers\u00edvel e a complexidade dos impactos dos transg\u00eanicos. Sendo assim, \u00e9 urgente apoiar e investir nas formas de agricultura sem transg\u00eanicos, baseadas nos conhecimento dos campesinos, campesinas e agricultores e na diversidade e ci\u00eancias respons\u00e1veis social e ambientalmente. Defendem que esse \u00e9 caminho seguro para o combate \u00e0 fome e \u00e0s mudan\u00e7as clim\u00e1ticas mundiais.<\/p>\n<p>Dia ap\u00f3s dia, cientistas e pesquisadores se empenham em divulgar o que realmente s\u00e3o os alimentos transg\u00eanicos, a motiva\u00e7\u00e3o para sua cria\u00e7\u00e3o e quais as implica\u00e7\u00f5es no meio ambiente, na economia e na vida dos seres humanos e dos animais, juntando-se assim a organiza\u00e7\u00f5es campesinas que lutam pela proibi\u00e7\u00e3o dos desse tipo de alimento geneticamente modificado.<\/p>\n<p>Uma carta assinada por 815 cientistas de 82 pa\u00edses j\u00e1 roda o mundo h\u00e1 14 anos. De forma detalhada, o documento denuncia que os transg\u00eanicos foram reprovados nos testes antes de serem lan\u00e7ados no mercado, aponta as muta\u00e7\u00f5es gen\u00e9ticas que podem causar e enumeram centenas de outros preju\u00edzos. O documento pede especificamente a suspens\u00e3o imediata de todas as licen\u00e7as para venda e cultivo de transg\u00eanicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por solicita\u00e7\u00e3o da Via Campesina, os engenheiros agr\u00f4nomos Paulo kageyama e Rubens Nodari entregaram ao<\/p>\n","protected":false},"author":2,"featured_media":4798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2014\/08\/conferencia_bispo.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2014\/08\/conferencia_bispo.jpg",150,96,false],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2014\/08\/conferencia_bispo.jpg",300,192,false],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2014\/08\/conferencia_bispo.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2014\/08\/conferencia_bispo.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2014\/08\/conferencia_bispo.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2014\/08\/conferencia_bispo.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2014\/08\/conferencia_bispo.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2014\/08\/conferencia_bispo.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2014\/08\/conferencia_bispo.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Por solicita\u00e7\u00e3o da Via Campesina, os engenheiros agr\u00f4nomos Paulo kageyama e Rubens Nodari entregaram ao","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/4797"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=4797"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/4797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/4798"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=4797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=4797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=4797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}