{"id":41086,"date":"2016-04-30T13:30:36","date_gmt":"2016-04-30T16:30:36","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=41086"},"modified":"2016-04-29T21:14:53","modified_gmt":"2016-04-30T00:14:53","slug":"pesquisadores-medem-impactos-do-aquecimento-global-sobre-abrolhos","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/pesquisadores-medem-impactos-do-aquecimento-global-sobre-abrolhos\/","title":{"rendered":"Pesquisadores medem impactos do aquecimento global sobre Abrolhos"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/abrolhos.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-41087\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/abrolhos-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/abrolhos-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/abrolhos.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Apesar dos pesares, os maiores recifes do Atl\u00e2ntico Sul est\u00e3o crescendo. Um estudo da <a href=\"http:\/\/www.abrolhos.org\/\" target=\"_blank\">Rede Abrolhos<\/a> demonstra que, entre 2012 e 2014, cada metro quadrado ganhou 580 gramas de carbonato de c\u00e1lcio por ano. A taxa \u00e9 considerada, pelos autores do estudo, intermedi\u00e1ria entre corais que j\u00e1 sofreram algum n\u00edvel de degrada\u00e7\u00e3o. E entre os pesares est\u00e3o os efeitos do aquecimento global, que amea\u00e7am a exist\u00eancia de corais em todo o mundo.<\/p>\n<p>\u201cOs recifes s\u00e3o organismos vivos, sempre em crescimento e suportando uma biodiversidade associada\u201d, explica o bi\u00f3logo Gilberto Menezes Amado-Filho, do Jardim Bot\u00e2nico do Rio de Janeiro e coordenador do estudo. \u201cNa medida em que anomalias (provocadas pelo aquecimento global) se tornam frequentes, eles param de crescer e morrem, diminuindo a diversidade e a biomassa na \u00e1rea\u201d, completa.<\/p>\n<p>\u00c9 a primeira vez que pesquisadores medem o crescimento de recifes coralinos no Atl\u00e2ntico Sul e os dados v\u00e3o servir de base para estudos sobre os efeitos das Mudan\u00e7as Clim\u00e1ticas sobre a regi\u00e3o. Durante os estudos, foi acompanhado o crescimento de organismos sobre placas artificiais montadas no ambiente. Os resultados foram publicados em 27 de abril, na revista cient\u00edfica on-line PLOS One.<\/p>\n<p>\u201cNo Norte da Austr\u00e1lia, na Grande Barreira de Corais, 95% dos recifes est\u00e3o sofrendo branqueamento\u201d, destaca o pesquisador. \u201c\u00c9 como se virassem um monte de concreto sem capa viva, com menor diversidade e consequ\u00eancias para o ciclo de carbono e ciclos biog\u00eanicos.\u201d.<\/p>\n<p>Apesar dos dados obtidos pela Rede Abrolhos n\u00e3o serem t\u00e3o alarmantes, a situa\u00e7\u00e3o ainda sim \u00e9 preocupante. Os pesquisadores verificaram um incremento de tufas de algas e micro-organismos ap\u00f3s ondas de calor registradas no ver\u00e3o de 2013\/2014. Esses tufos formam o segundo grupo mais abundante nas placas de coloniza\u00e7\u00e3o e passaram a ocupar de 1 a 4% da \u00e1rea total das placas em 2012\/2013 para 25% no ver\u00e3o seguinte.<\/p>\n<p>\u201cNa medida em que a temperatura aumenta, organismos que vamos chamar de oportunistas crescem sobre os formadores e os matam, sufocam os organismos construtores\u201d, explica Gilberto Amado-Filho. Os estudos demonstram tamb\u00e9m que algas calc\u00e1rias, e n\u00e3o corais, s\u00e3o os principais formadores dos recifes.<\/p>\n<p>Os pesquisadores continuam a monitorar a regi\u00e3o de Abrolhos, com instala\u00e7\u00e3o de novas placas de coloniza\u00e7\u00e3o e sensores de temperatura e qualidade da \u00e1gua. Apesar de parte dos recifes serem protegidas pelo Parque Nacional e outras unidades de conserva\u00e7\u00e3o, a amplia\u00e7\u00e3o das \u00e1reas de prote\u00e7\u00e3o em Abrolhos, prometida pelo Minist\u00e9rio do Meio Ambiente h\u00e1 quase uma d\u00e9cada, ainda est\u00e1 parada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apesar dos pesares, os maiores recifes do Atl\u00e2ntico Sul est\u00e3o crescendo. Um estudo da Rede<\/p>\n","protected":false},"author":2,"featured_media":41087,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/abrolhos.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/abrolhos-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/abrolhos-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/abrolhos.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/abrolhos.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/abrolhos.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/abrolhos.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/abrolhos.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/abrolhos.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/abrolhos.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Apesar dos pesares, os maiores recifes do Atl\u00e2ntico Sul est\u00e3o crescendo. Um estudo da Rede","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/41086"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=41086"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/41086\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/41087"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=41086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=41086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=41086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}