{"id":41023,"date":"2016-04-29T12:30:26","date_gmt":"2016-04-29T15:30:26","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=41023"},"modified":"2016-04-28T22:25:51","modified_gmt":"2016-04-29T01:25:51","slug":"el-nino-perde-forca-mas-influencia-clima-ate-junho","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/el-nino-perde-forca-mas-influencia-clima-ate-junho\/","title":{"rendered":"El Ni\u00f1o perde for\u00e7a, mas influencia clima at\u00e9 junho, segundo meteorologista"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/el_nino.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-41024\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/el_nino-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/el_nino-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/el_nino.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>O fen\u00f4meno El Ni\u00f1o come\u00e7a a perder for\u00e7a no Brasil, mas ainda influencia o clima e as temperaturas no Brasil at\u00e9 junho, aponta o Grupo de Trabalho em Previs\u00e3o Clim\u00e1tica Sazonal (GTPCS\/MCTI). At\u00e9 l\u00e1, a regi\u00e3o Sul pode receber chuvas acima da normalidade. J\u00e1 na regi\u00e3o Norte e parte da regi\u00e3o Nordeste, as temperaturas devem come\u00e7ar a cair.<\/p>\n<p>Entre maio e julho, o volume de chuvas em parte do semi\u00e1rido e na faixa leste da regi\u00e3o Nordeste, que compreende o territ\u00f3rio entre o Rio Grande do Norte e o sul da Bahia, deve ser menor do que a normal climatol\u00f3gica, ou seja, mais seco. Para o nordeste do Amazonas, o centro-norte do Par\u00e1, Roraima e Amap\u00e1, \u00e9 previsto um \u00edndice pluviom\u00e9trico dentro da normal climatol\u00f3gica. O mesmo vale para a regi\u00e3o Sul do pa\u00eds.<\/p>\n<p>Segundo o meteorologista Marcelo Seluchi, do Centro Nacional de Monitoramento e Alertas de Desastres Naturais (Cemaden), o fim do El Ni\u00f1o em junho anuncia um inverno mais frio em compara\u00e7\u00e3o com 2015. &#8220;Esse pr\u00f3ximo inverno deve ser mais frio, mas, em compara\u00e7\u00e3o com a m\u00e9dia hist\u00f3rica, com a m\u00e9dia de 30 anos, por exemplo, apenas a regi\u00e3o Sul deve ter um inverno mais ou menos dentro da normalidade.<\/p>\n<p>A parte central do Pa\u00eds, regi\u00f5es Sudeste, Centro-Oeste e o Norte, ainda deve apresentar temperatura acima do normal, talvez n\u00e3o t\u00e3o elevadas quanto no ano passado, mas mais elevadas em compara\u00e7\u00e3o com a m\u00e9dia hist\u00f3rica&#8221;, explicou.<\/p>\n<p>O relat\u00f3rio do GTPCS tamb\u00e9m indica 70% de possibilidade de o fen\u00f4meno La Ni\u00f1a influenciar o clima no Brasil. Oposto do El Ni\u00f1o, o fen\u00f4meno La Ni\u00f1a diminui a temperatura da superf\u00edcie das \u00e1guas do Oceano Pac\u00edfico.<\/p>\n<p>Al\u00e9m do Cemaden, o Instituto Nacional de Pesquisas Espaciais (Inpe\/MCTI) e o Instituto Nacional de Pesquisas da Amaz\u00f4nia (Inpa\/MCTI) tamb\u00e9m participam do GTPCS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O fen\u00f4meno El Ni\u00f1o come\u00e7a a perder for\u00e7a no Brasil, mas ainda influencia o clima<\/p>\n","protected":false},"author":2,"featured_media":41024,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/el_nino.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/el_nino-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/el_nino-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/el_nino.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/el_nino.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/el_nino.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/el_nino.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/el_nino.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/el_nino.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/el_nino.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"O fen\u00f4meno El Ni\u00f1o come\u00e7a a perder for\u00e7a no Brasil, mas ainda influencia o clima","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/41023"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=41023"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/41023\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/41024"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=41023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=41023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=41023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}