{"id":40699,"date":"2016-04-24T11:00:21","date_gmt":"2016-04-24T14:00:21","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=40699"},"modified":"2016-04-23T17:47:08","modified_gmt":"2016-04-23T20:47:08","slug":"umbu-pode-dar-origem-a-um-creme-que-age-contra-o-envelhecimento-da-pele","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/umbu-pode-dar-origem-a-um-creme-que-age-contra-o-envelhecimento-da-pele\/","title":{"rendered":"Umbu pode dar origem a um creme que age contra o envelhecimento da pele"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/umbu.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-40701\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/umbu-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/umbu-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/umbu.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>T\u00edpico da Caatinga, o umbu, fruto do umbuzeiro, \u00e9 conhecido por suas ricas propriedades nutricionais, com destaque para o elevado teor de vitamina C, alto \u00edndice aquoso e v\u00e1rios componentes vol\u00e1teis, especialmente nos frutos maduros. No sert\u00e3o nordestino, ele \u00e9 largamente consumido<em> in natura<\/em> ou processado, na forma de polpa, geleia, doce ou sorvete. Recentemente, um grupo de cientistas brasileiros e su\u00ed\u00e7os concluiu um estudo que revelou novas propriedades dessa fruta arredondada, de casca aveludada e sabor levemente azedo. Eles descobriram que o umbu (<em>Spondias tuberosa<\/em>) \u00e9 rico em compostos fen\u00f3licos com atividade antioxidante, o que faz dele um insumo potencial para fabrica\u00e7\u00e3o de cosm\u00e9ticos com a\u00e7\u00e3o sobre o envelhecimento da pele, como cremes antirrugas ou contra flacidez. Duas das subst\u00e2ncias identificadas s\u00e3o in\u00e9ditas.<\/p>\n<p>Coordenada pela farmac\u00eautica Vanderlan da Silva Bolzani, professora do Instituto de Qu\u00edmica da Universidade Estadual Paulista (IQ-Unesp) de Araraquara, a pesquisa teve a participa\u00e7\u00e3o da Universidade de Genebra (Unigen), na Su\u00ed\u00e7a, e do Centro de Inova\u00e7\u00e3o e Ensaios Pr\u00e9-Cl\u00ednicos (CIEnP), empresa privada sem fins lucrativos com sede em Florian\u00f3polis (SC). \u201cO estudo fornece a primeira documenta\u00e7\u00e3o completa sobre o isolamento de compostos da polpa do umbu, com propriedades antioxidantes e rejuvenescedoras da pele\u201d, explica Maria Luiza Zeraik, que atuou na equipe quando fazia p\u00f3s-doutorado. Atualmente, ela \u00e9 professora do Departamento de Qu\u00edmica do Centro de Ci\u00eancias Exatas da Universidade Estadual de Londrina (UEL), no Paran\u00e1. \u201cUm aspecto relevante do nosso estudo \u00e9 promover uma inova\u00e7\u00e3o tecnol\u00f3gica com valor social para a regi\u00e3o Nordeste\u201d, diz Maria Luiza. O umbuzeiro \u00e9 importante na Caatinga porque d\u00e1 frutos durante a esta\u00e7\u00e3o seca e representa uma fonte de renda para a popula\u00e7\u00e3o local.<\/p>\n<p>A pesquisa contou com recursos dos governos su\u00ed\u00e7o e brasileiro e teve financiamento da FAPESP por meio de uma bolsa de p\u00f3s-doutorado, concedida \u00e0 Maria Luiza, al\u00e9m de um projeto do Sisbiota, programa do CNPq em parceria com a Funda\u00e7\u00e3o. A partir de 2014, o estudo integrou a carteira de projetos do Centro de Pesquisa e Inova\u00e7\u00e3o em Biodiversidade e F\u00e1rmacos (CIBFar), um dos Centros de Pesquisa, Inova\u00e7\u00e3o e Difus\u00e3o (Cepid) da FAPESP, coordenado por Glaucius Oliva, do Instituto de F\u00edsica da Universidade de S\u00e3o Paulo (IFSC-USP) de S\u00e3o Carlos.<\/p>\n<p>Dois pedidos de patentes foram depositados no Brasil e no exterior. Eles s\u00e3o pertinentes ao processo de extra\u00e7\u00e3o e isolamento de compostos presentes na polpa do umbu relativos \u00e0s propriedades antioxidantes, \u00e0 inibi\u00e7\u00e3o da acetilcolinesterase, enzima que promove as liga\u00e7\u00f5es (sinapses) entre os neur\u00f4nios. \u201cAs subst\u00e2ncias relacionadas \u00e0 acetilcolinesterase poderiam, no futuro, originar um medicamento ou um suplemento alimentar para tratar a perda da mem\u00f3ria, quadro comum em idosos\u201d, diz Vanderlan.<\/p>\n<div id=\"attachment_212128\" class=\"wp-caption alignleft\">\n<p class=\"wp_author\">\u00a9 FABIO COLOMBINI<\/p>\n<p><img loading=\"lazy\" class=\"\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2016\/02\/Umbu_umbu-PI-98145.jpg?8963d4\" alt=\"O umbuzeiro se destaca no sert\u00e3o nordestino. Mesmo no per\u00edodo de seca os frutos s\u00e3o suculentos\" width=\"290\" height=\"193\" \/><\/p>\n<p class=\"wp-caption-text\">O umbuzeiro se destaca no sert\u00e3o nordestino. Mesmo no per\u00edodo de seca os frutos s\u00e3o suculentos<\/p>\n<\/div>\n<p><strong>Foco na biodiversidade<\/strong><br \/>\nAs descobertas sobre o umbu fizeram parte de um estudo mais amplo com o objetivo de investigar as propriedades de 22 frutos pertencentes \u00e0 biodiversidade brasileira visando a seu potencial uso na ind\u00fastria de cosm\u00e9ticos e de alimentos. Esse projeto fez parte do Conv\u00eanio Bilateral entre Brasil e Sui\u00e7a, ou Brazilian Swiss Joint Research Programme (BSJRP), coordenado no lado brasileiro pelo Conselho Nacional de Desenvolvimento Cient\u00edfico e Tecnol\u00f3gico (CNPq). O projeto foi iniciado em 2011 e conclu\u00eddo em 2014, no IQ-Unesp, respons\u00e1vel pela triagem qu\u00edmica e biol\u00f3gica inicial de frutos nativos ou end\u00eamicos das regi\u00f5es Norte e Nordeste do pa\u00eds. Al\u00e9m do umbu, tamb\u00e9m est\u00e3o na lista do estudo as frutas bacuri, ciriguela, mangaba, pitomba e caj\u00e1, entre outras.<\/p>\n<p>\u201cO processo de preparo de amostras dos frutos, a extra\u00e7\u00e3o dos componentes qu\u00edmicos por m\u00e9todos anal\u00edticos usuais e os ensaios qu\u00edmicos preliminares dos extratos foram feitos no nosso laborat\u00f3rio NuBBE [N\u00facleo de Bioensaios, Bioss\u00edntese e Ecofisiologia de Produtos Naturais, laborat\u00f3rio com selo verde que excluiu o uso de solventes clorados e outros derivados de petr\u00f3leo em muitas etapas de extra\u00e7\u00e3o e purifica\u00e7\u00e3o]\u201d, explica Vanderlan, que tamb\u00e9m \u00e9 membro da coordena\u00e7\u00e3o do Programa Biota-FAPESP, cujo objetivo \u00e9 mapear e analisar a biodiversidade paulista e avaliar as possibilidades de explora\u00e7\u00e3o sustent\u00e1vel de plantas ou de outros organismos com potencial econ\u00f4mico. \u201cTodas as partes dos frutos [cascas, polpas, sementes] foram analisadas, resultando em mais de 100 extratos. Dentre eles, separamos alguns bastante ativos e a polpa do umbu mostrou-se excelente para iniciar a pesquisa.\u201d Outros frutos \u2013 cujos nomes s\u00e3o mantidos em sigilo pelo grupo \u2013 tamb\u00e9m apresentaram atividades de interesse e ser\u00e3o estudados posteriormente.<\/p>\n<p>A parceria com a Universidade de Genebra, um importante centro europeu de pesquisa em produtos naturais, teve um or\u00e7amento de 173,4 mil francos su\u00ed\u00e7os (equivalentes a atuais R$ 700 mil), divididos entre os governos do Brasil (35% do total) e da Su\u00ed\u00e7a. \u201cEmpregamos metodologias inovadoras de caracteriza\u00e7\u00e3o qu\u00edmica, detectamos, isolamos e identificamos os compostos qu\u00edmicos presentes no umbu respons\u00e1veis pela atividade de inibi\u00e7\u00e3o da acetilcolinesterase, enzima-alvo para o tratamento da doen\u00e7a de Alzheimer\u201d, destaca o farmac\u00eautico brasileiro Emerson Queiroz, professor da Escola de Ci\u00eancias Farmac\u00eauticas da Unigen, na Sui\u00e7a. Os ensaios biol\u00f3gicos <em>in vitro<\/em> com os compostos puros foram realizados pela professora Muriel Cuendet, da mesma universidade.<\/p>\n<p>Como parte do programa su\u00ed\u00e7o-brasileiro, a qu\u00edmica Maria Luiza, na \u00e9poca estagi\u00e1ria de p\u00f3s-doutorado supervisionada por Vanderlan, ficou nove meses na Universidade de Genebra. Nesse per\u00edodo, ela aprendeu os princ\u00edpios do estudo metabol\u00f4mico realizado pelo grupo dos professores Jean-Luc Wolfender e Emerson Queiroz. Wolfender \u00e9 o chefe do Laborat\u00f3rio de Fitoqu\u00edmica e Produtos Naturais Bioativos da universidade e coordenador do projeto bilateral por parte da institui\u00e7\u00e3o su\u00ed\u00e7a. \u201cMetabol\u00f4nica \u00e9 uma abordagem avan\u00e7ada sobre o mapeamento qu\u00edmico ideal para quantificar todos os produtos naturais de um organismo\u201d, explica Maria Luiza. \u201cEla \u00e9 usada para estudarmos todos os compostos metab\u00f3licos secund\u00e1rios de uma planta e, por meio dessas an\u00e1lises, obt\u00e9m-se um <em>fingerprint<\/em>, a identidade metab\u00f3lica vegetal, como um painel das subst\u00e2ncias qu\u00edmicas presentes na esp\u00e9cie.\u201d Para Emerson, a forma\u00e7\u00e3o de recursos humanos e a transfer\u00eancia de conhecimento e tecnologia para o Brasil \u00e9 outro aspecto relevante do programa bilateral Brasil-Su\u00ed\u00e7a.<\/p>\n<div id=\"attachment_212127\" class=\"wp-caption alignright\">\n<p class=\"wp_author\">\u00a9 EDUARDO CESAR<\/p>\n<p><img loading=\"lazy\" class=\"\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2016\/02\/Umbu_fruta.jpg?8963d4\" alt=\"Depois dos testes positivos e um pr\u00eamio, falta agora o interesse de uma empresa\" width=\"290\" height=\"186\" \/><\/p>\n<p class=\"wp-caption-text\">Depois dos testes positivos e um pr\u00eamio, falta agora o interesse de uma empresa<\/p>\n<\/div>\n<p><strong>Ensaios <em>in vitro<\/em> <\/strong><br \/>\nDepois da caracteriza\u00e7\u00e3o feita na Su\u00ed\u00e7a, os extratos de umbu foram padronizados e enviados para o CIEnP, em Florian\u00f3polis, para estudos de prova de conceito, fase essencial quando se almeja posterior colabora\u00e7\u00e3o industrial visando a um poss\u00edvel produto. \u201cFizemos aqui estudos<em> in vitro<\/em> em c\u00e9lulas humanas da pele \u2013 melan\u00f3citos e queratin\u00f3citos \u2013 para avaliar o uso do produto no desenvolvimento de cosm\u00e9ticos com a\u00e7\u00e3o sobre o envelhecimento\u201d, explica Jo\u00e3o Batista Calixto, diretor-presidente do CIEnP e ex-professor da Universidade Federal de Santa Catarina (UFSC). \u201cDurante quase um ano, realizamos por volta de 30 ensaios, envolvendo v\u00e1rias enzimas e mediadores inflamat\u00f3rios potencialmente respons\u00e1veis pelo envelhecimento da pele.\u201d<\/p>\n<p>Financiado pelo governo do estado de Santa Catarina e pelos minist\u00e9rios da Sa\u00fade (MS) e da Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (MCTI), o CIEnP foi criado h\u00e1 dois anos com a miss\u00e3o de contribuir para a inova\u00e7\u00e3o tecnol\u00f3gica nos setores farmac\u00eautico (medicamentos de uso humano e veterin\u00e1rio) e de cosm\u00e9ticos. A maioria dos projetos desenvolvidos na institui\u00e7\u00e3o se d\u00e1 em conjunto com o setor industrial. A pesquisa envolvendo o umbu foi a primeira parceria do centro com uma universidade e a primeira prova de conceito realizada no CIEnP com um produto da biodiversidade brasileira. Segundo Calixto, o extrato padronizado do umbu mostrou-se seguro e com toxicidade em n\u00edveis aceit\u00e1veis. \u201cEsses resultados mostraram que o fruto tem potencial para ser usado como cosm\u00e9tico na preven\u00e7\u00e3o de sintomas de inflama\u00e7\u00e3o da pele observados durante o processo de envelhecimento\u201d, diz ele. \u201cAgora, estamos procurando uma empresa interessada na produ\u00e7\u00e3o e na comercializa\u00e7\u00e3o desse bioativo.\u201d<\/p>\n<p>Em dezembro de 2015, Vanderlan Bolzani, Jo\u00e3o Batista Calixto e Maria Luiza Zeraik receberam o Pr\u00eamio Kurt Politzer de Tecnologia, na categoria Pesquisador, pelo projeto \u201cUtiliza\u00e7\u00e3o sustent\u00e1vel da polpa dos frutos do umbu e umbu-caj\u00e1: produtos fen\u00f3licos de alto valor agregado para a ind\u00fastria de cosm\u00e9tico com propriedades antienvelhecimento\u201d. O reconhecimento \u00e9 concedido pela Associa\u00e7\u00e3o Brasileira da Ind\u00fastria Qu\u00edmica (Abiquim) a projetos de empresas e cientistas que estimulam a pesquisa e a inova\u00e7\u00e3o na \u00e1rea qu\u00edmica no pa\u00eds.<\/p>\n<p><strong>Projetos<\/strong><br \/>\n<strong> 1.<\/strong> Prospec\u00e7\u00e3o de mol\u00e9culas bioativas e estudo de variabilidade infraespec\u00edfica em plantas e microrganismos end\u00f3fitos do Cerrado e Caatinga. Contribui\u00e7\u00e3o para o conhecimento e uso sustent\u00e1vel da biodiversidade brasileira (Sisbiota) (<a href=\"http:\/\/www.bv.fapesp.br\/pt\/auxilios\/30408\/prospeccao-de-moleculas-bioativas-e-estudo-de-variabilidade-infra-especifica-em-plantas-e-microorgan\/\" target=\"_blank\">n\u00ba 2010\/52327-5<\/a>); <strong>Modalidade<\/strong> Programa Biota; <strong>Pesquisadora respons\u00e1vel<\/strong> Vanderlan Bolzani (Unesp); <strong>Investimento<\/strong> R$ 552.668,55 e\u00a0US$ 246.950,72.<br \/>\n<strong>2.<\/strong> Produtos naturais oriundos de plantas do Cerrado e Mata Atl\u00e2ntica, modelos potenciais e \u00fateis para identificar prot\u00f3tipos com a\u00e7\u00e3o oxidante em neutr\u00f3filos e enzima mieloperoxidase (MPO) (<a href=\"http:\/\/www.bv.fapesp.br\/pt\/bolsas\/126016\/produtos-naturais-oriundos-de-plantas-do-cerrado-e-mata-atlantica-modelos-potenciais-e-uteis-para-i\/\" target=\"_blank\">n\u00ba 2011\/03017-6<\/a>); <strong>Modalidade<\/strong> Bolsa de p\u00f3s-doutorado (Maria Luiza Zeraik); <strong>Pesquisadora respons\u00e1vel<\/strong> Vanderlan Bolzani (Unesp); <strong>Investimento<\/strong> R$ 297.813,41.<br \/>\n<strong>3.<\/strong> CIBFar \u2013 Centro de Inova\u00e7\u00e3o em Biodiversidade e F\u00e1rmacos (<a href=\"http:\/\/www.bv.fapesp.br\/pt\/auxilios\/58566\/cibfar-centro-de-inovacao-em-biodiversidade-e-farmacos\/\" target=\"_blank\">n\u00ba 2013\/07600-3<\/a>); <strong>Modalidade<\/strong> Programa Centros de Pesquisa, Inova\u00e7\u00e3o e Difus\u00e3o (Cepid); <strong>Pesquisador respons\u00e1vel<\/strong> Glaucius Oliva (IFSC-USP); <strong>Investimento\u00a0<\/strong>R$ 21.485.493,35 (em quatro anos).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>T\u00edpico da Caatinga, o umbu, fruto do umbuzeiro, \u00e9 conhecido por suas ricas propriedades nutricionais,<\/p>\n","protected":false},"author":2,"featured_media":40701,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/umbu.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/umbu-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/umbu-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/umbu.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/umbu.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/umbu.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/umbu.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/umbu.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/umbu.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/umbu.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"T\u00edpico da Caatinga, o umbu, fruto do umbuzeiro, \u00e9 conhecido por suas ricas propriedades nutricionais,","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/40699"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=40699"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/40699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/40701"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=40699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=40699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=40699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}