{"id":40480,"date":"2016-04-11T12:00:04","date_gmt":"2016-04-11T15:00:04","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=40480"},"modified":"2016-04-11T08:32:29","modified_gmt":"2016-04-11T11:32:29","slug":"fungo-descoberto-em-castanheiras-pode-ter-atividade-bactericida","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/fungo-descoberto-em-castanheiras-pode-ter-atividade-bactericida\/","title":{"rendered":"Fungo descoberto em castanheiras pode ter atividade bactericida"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/fungos.jpg\" rel=\"attachment wp-att-40481\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-40481\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/fungos-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/fungos-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/fungos.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>A castanha-do-brasil ou castanha-do-par\u00e1 \u00e9 objeto de estudo de diversos grupos de pesquisa em todo o pa\u00eds. Um dos objetivos dos estudos \u00e9 entender como evitar a contamina\u00e7\u00e3o das castanhas por esp\u00e9cies de mofo ou bolor que produzem subst\u00e2ncias t\u00f3xicas.<\/p>\n<p>Um subproduto inesperado dessas pesquisas \u00e9 a descri\u00e7\u00e3o de uma nova esp\u00e9cie de fungo, o <i>Penicillium excelsum<\/i>, uma das mais de 350 esp\u00e9cies do g\u00eanero <i>Penicillium<\/i>, o mesmo de onde se extraiu originalmente a penicilina, o primeiro dos antibi\u00f3ticos. <a href=\"http:\/\/journals.plos.org\/plosone\/article?id=10.1371\/journal.pone.0143189\" target=\"_blank\"><b>Publicado<\/b><\/a> no peri\u00f3dico PLoS ONE, o trabalho \u00e9 liderado pela bi\u00f3loga e pesquisadora <a href=\"http:\/\/www.bv.fapesp.br\/pt\/pesquisador\/4454\/marta-hiromi-taniwaki\/\" target=\"_blank\"><b>Marta Hiromi Taniwaki<\/b><\/a>, do Instituto de Tecnologia de Alimentos (ITAL), de Campinas, \u00f3rg\u00e3o da Secretaria de Agricultura e Abastecimento do Estado de S\u00e3o Paulo, com o <a href=\"http:\/\/www.bv.fapesp.br\/pt\/auxilios\/46048\/biodiversidade-das-especies-toxigenicas-de-aspergillus-no-brasil-ocorrencia-taxonomia-polifasica-e\/\" target=\"_blank\"><b>apoio da FAPESP<\/b><\/a>.<\/p>\n<p>A castanheira-do-brasil (<i>Bertholletia excelsa<\/i>) \u00e9 uma \u00e1rvore amaz\u00f4nica que pode alcan\u00e7ar mais de 50 metros de altura. A planta produz ouri\u00e7os que amadurecem e caem no ch\u00e3o da floresta, partindo-se e liberando suas sementes, as castanhas. O Brasil lidera a produ\u00e7\u00e3o mundial. No Acre, o maior produtor nacional, a sementes s\u00e3o conhecidas como castanha-do-acre. J\u00e1 na Bol\u00edvia, o segundo maior produtor, o nome \u00e9 <i>almendra<\/i> (am\u00eandoa), noz amaz\u00f4nica ou noz boliviana. No resto do planeta, a noz comest\u00edvel da castanheira amaz\u00f4nica \u00e9 a <i>Brazil nut<\/i>, a noz do Brasil.<\/p>\n<p>Devido ao desmatamento, desde 1998 a castanheira-do-brasil \u00e9 considerada uma esp\u00e9cie vulner\u00e1vel \u00e0 extin\u00e7\u00e3o, segundo a Lista Vermelha da Uni\u00e3o Internacional para a Conserva\u00e7\u00e3o da Natureza e dos Recursos Naturais. Sua extra\u00e7\u00e3o \u00e9 proibida por lei.<\/p>\n<p>A castanha-do-brasil \u00e9 um produto importante na pauta de exporta\u00e7\u00f5es da ind\u00fastria extrativista da Amaz\u00f4nia. Segundo o Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE), a produ\u00e7\u00e3o brasileira em 2013 foi de 38 mil toneladas. Os maiores consumidores s\u00e3o os Estados Unidos e a China. J\u00e1 a Uni\u00e3o Europeia proibiu em 2000 a importa\u00e7\u00e3o das castanhas. O embargo foi devido \u00e0 presen\u00e7a de aflatoxinas, que s\u00e3o toxinas produzidas por algumas esp\u00e9cies de fungos, em concentra\u00e7\u00f5es acima do permitido pela regula\u00e7\u00e3o sanit\u00e1ria europeia. Estudos mostram que, em altas concentra\u00e7\u00f5es, as aflatoxinas podem atacar o f\u00edgado, causando necrose, cirrose hep\u00e1tica, edema e c\u00e2ncer.<\/p>\n<p>Hoje se sabe que a forma\u00e7\u00e3o das toxinas pelos fungos nas castanhas se deve \u00e0s condi\u00e7\u00f5es de umidade na floresta e ao tempo de estocagem at\u00e9 as sementes atingirem um n\u00edvel seguro de umidade. Castanhas que s\u00e3o secas \u00e0 temperatura de 60 graus e mantidas em estoques apropriados apresentam menos fungos e menor possibilidade de conter as toxinas do que aquelas armazenadas sem os mesmos cuidados.<\/p>\n<p>Ap\u00f3s todos esses estudos e esfor\u00e7os ao longo da cadeia de extra\u00e7\u00e3o e processamento da castanha, em 2011 a Europa levantou o embargo e voltou a comprar nossas castanhas. Ao mesmo tempo, a Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) tamb\u00e9m estabeleceu limites m\u00e1ximos para as aflatoxinas na castanha-do-brasil, a fim de proteger o consumidor.<\/p>\n<p>De acordo com Marta Taniwaki, o objetivo principal de seu trabalho com as castanhas-do-brasil era verificar a ocorr\u00eancia de fungos produtores de aflatoxinas. \u201cAl\u00e9m disso, est\u00e1vamos interessados em conhecer a micobiota, os fungos presentes na castanha e no ecossistema amaz\u00f4nico ao redor das castanheiras\u201d, explica Taniwaki.<\/p>\n<p>A pesquisa determinou a predomin\u00e2ncia das esp\u00e9cies dos g\u00eaneros Aspergillus e Penicillium no ecossistema das castanheiras, \u201csendo que v\u00e1rias esp\u00e9cies de Aspergillus foram capazes de produzir toxinas nos testes in vitro e nas castanhas. Alguns desses trabalhos j\u00e1 foram publicados, outros ainda vir\u00e3o em breve.\u201d<\/p>\n<p>Um primeiro dividendo inesperado da pesquisa foi a <a href=\"http:\/\/journals.plos.org\/plosone\/article?id=10.1371\/journal.pone.0042480\" target=\"_blank\"><b>descri\u00e7\u00e3o<\/b><\/a>, em 2012, de um novo fungo, o <i>Aspergillus bertholletius<\/i>. Agora, com a descri\u00e7\u00e3o do <i>P. excelsum<\/i>, as surpresas continuam. \u201cA descoberta de uma nova esp\u00e9cie de <i>Penicillium<\/i> da floresta amaz\u00f4nica foi surpreendente. \u00c9 uma amostra da grande biodiversidade amaz\u00f4nica ainda pouqu\u00edssimo explorada.\u201d<\/p>\n<p>A esp\u00e9cie <i>P. excelsum<\/i> foi isolada a partir de amostras coletadas no Amazonas e no Par\u00e1, na floresta, em fazendas, em mercados e nas processadoras da castanha. O novo fungo foi detectado em quase todo o ecossistema das castanheiras. Ele estava presente em amostras de folhas, de cascas, de castanhas, dos ouri\u00e7os, nas flores e no solo. O <i>P. excelsum<\/i> foi igualmente identificado nas abelhas que fazem a poliniza\u00e7\u00e3o das flores da castanheira, assim como em formigas. \u201cA esp\u00e9cie vai se propagando por todo o ambiente em torno da castanheira.\u201d<\/p>\n<p>Para isolar a nova esp\u00e9cie, mais de 200 amostras foram coletadas, colocadas em placas de vidro com meio de cultura apropriado e deixadas por cinco dias em estufas \u00e0 temperatura de 25 graus. \u201cForam mais de mil isolamentos\u201d, explica Taniwaki. \u201cDepois de cinco dias na estufa o fungo se desenvolve e forma uma col\u00f4nia.\u201d<\/p>\n<p>Para saber qual seria aquela esp\u00e9cie de bolor, diversos processos foram empregados, nenhum com resultados conclusivos. \u201cA morfologia da col\u00f4nia e a microscopia mostrou que esta esp\u00e9cie era diferente de todas as que conhec\u00edamos. Parecia se tratar de uma nova esp\u00e9cie.\u201d A comprova\u00e7\u00e3o veio de estudos moleculares realizados por Maria Helena Fungaro, na Universidade Estadual de Londrina, e por Jens Frisvad, na Universidade T\u00e9cnica da Dinamarca. A descri\u00e7\u00e3o final da nova esp\u00e9cie foi feita por John Pitt, no CSIRO Food Nutrition, a ag\u00eancia de pesquisa cient\u00edfica de alimentos da Austr\u00e1lia.<\/p>\n<p>Esta nova esp\u00e9cie de <i>Penicillium<\/i> n\u00e3o \u00e9 a primeira a ser detectada no ecossistema das castanheiras. Segundo Taniwaki, as esp\u00e9cies <i>P. glabrum<\/i> e <i>P. citrinum<\/i> j\u00e1 foram isoladas das castanhas-do-brasil. <i>P. citrinum<\/i> produz a micotoxina citrinina, uma subst\u00e2ncia nefrot\u00f3xica com potencial para causar danos aos rins. <i>P. glabrum<\/i> produz a citromicetina, com atividade bactericida. \u201cA diferen\u00e7a entre antibi\u00f3tico e micotoxina \u00e9 que o primeiro combate os microrganismos e a \u00faltima os animais e os humanos\u201d, explica.<\/p>\n<p>Diversas esp\u00e9cies de fungos do g\u00eanero <i>Penicillium<\/i> produzem antibi\u00f3ticos que t\u00eam a propriedade de combater infec\u00e7\u00f5es causadas por v\u00edrus, bact\u00e9rias e outros fungos. A descoberta de tais propriedades se confunde com a descoberta do primeiro antibi\u00f3tico, a penicilina.<\/p>\n<p>Em 1928, o ingl\u00eas Alexander Fleming estudava as propriedades das bact\u00e9rias estafilococos em seu laborat\u00f3rio no Hospital St. Mary, em Londres. Em setembro daquele ano, ao retornar ao laborat\u00f3rio ap\u00f3s um m\u00eas de f\u00e9rias, Fleming percebeu que uma de suas culturas de estafilococos estava contaminada por um fungo e, nos pontos de contato onde a col\u00f4nia circundava o fungo, ela havia sido destru\u00edda.<\/p>\n<p>Ao investigar aquele mist\u00e9rio, Fleming acabou isolando a subst\u00e2ncia produzida pelo fungo do g\u00eanero <i>Penicillium<\/i> que exterminava bact\u00e9rias. Batizou-a com o nome de penicilina.<\/p>\n<p>\u201cAinda n\u00e3o sabemos se esta nova esp\u00e9cie produz alguma subst\u00e2ncia metab\u00f3lica de interesse para a ind\u00fastria farmac\u00eautica\u201d, afirma Taniwaki. \u201cMas vamos investigar.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A castanha-do-brasil ou castanha-do-par\u00e1 \u00e9 objeto de estudo de diversos grupos de pesquisa em todo<\/p>\n","protected":false},"author":2,"featured_media":40481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/fungos.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/fungos-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/fungos-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/fungos.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/fungos.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/fungos.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/fungos.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/fungos.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/fungos.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/fungos.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"A castanha-do-brasil ou castanha-do-par\u00e1 \u00e9 objeto de estudo de diversos grupos de pesquisa em todo","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/40480"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=40480"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/40480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/40481"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=40480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=40480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=40480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}