{"id":40413,"date":"2016-04-10T12:20:33","date_gmt":"2016-04-10T15:20:33","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=40413"},"modified":"2016-04-10T12:21:13","modified_gmt":"2016-04-10T15:21:13","slug":"o-que-as-piramides-ecologicas-tem-a-ver-com-a-picanha-na-nossa-mesa","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/o-que-as-piramides-ecologicas-tem-a-ver-com-a-picanha-na-nossa-mesa\/","title":{"rendered":"O que as pir\u00e2mides ecol\u00f3gicas t\u00eam a ver com a picanha na nossa mesa?"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/piramides_ecologicas.jpg\" rel=\"attachment wp-att-40414\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-40414\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/piramides_ecologicas-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/piramides_ecologicas-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/piramides_ecologicas.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Por Daniel F\u00e1bio Salvador e Maur\u00edcio Luz<\/p>\n<p>Diversas representa\u00e7\u00f5es em forma de pir\u00e2mides t\u00eam sido utilizadas por d\u00e9cadas para representar caracter\u00edsticas de ecossistemas nos livros did\u00e1ticos: as pir\u00e2mides de biomassa, de n\u00fameros e de energia. Cada uma delas contribui para a compreens\u00e3o de uma dimens\u00e3o dos ecossistemas e, como \u00e9 comum, todas apresentam limita\u00e7\u00f5es. Mas como podemos fazer um uso contextualizado e pr\u00e1tico dessas representa\u00e7\u00f5es para abordar uma situa\u00e7\u00e3o do dia a dia dos nossos alunos?<\/p>\n<p>Em geral, essas representa\u00e7\u00f5es s\u00e3o utilizadas nas se\u00e7\u00f5es sobre ecologia dos livros did\u00e1ticos de ci\u00eancias e biologia. Nas pir\u00e2mides de energia dos ambientes terrestres, o n\u00edvel tr\u00f3fico basal representa os produtores, em geral, as plantas. J\u00e1 o segundo n\u00edvel tr\u00f3fico cont\u00e9m os herb\u00edvoros (consumidores prim\u00e1rios). E, para fins de simplifica\u00e7\u00e3o, em geral o terceiro n\u00edvel tr\u00f3fico inclui os carn\u00edvoros (consumidores secund\u00e1rios) que consomem um ou mais tipos de herb\u00edvoros. Os outros n\u00edveis (consumidores de terceira ordem e de ordens seguintes) representam os demais carn\u00edvoros. As pir\u00e2mides de energia s\u00e3o utilizadas para ressaltar visualmente a ideia de que a propor\u00e7\u00e3o da energia presente em um n\u00edvel tr\u00f3fico incorporada pelos indiv\u00edduos do n\u00edvel tr\u00f3fico seguinte \u00e9 bastante pequena.<\/p>\n<p>Isso porque a maior parte da energia \u00e9 consumida no metabolismo dos seres vivos e n\u00e3o fica dispon\u00edvel para os consumidores seguintes. Como regra geral simples, ainda que imprecisa, admite\u00adse que apenas 10% da energia dispon\u00edvel em um n\u00edvel tr\u00f3fico \u00e9 incorporada efetivamente sob a forma de biomassa no n\u00edvel tr\u00f3fico seguinte. Ou seja, em condi\u00e7\u00f5es naturais, 90% da energia \u00e9 gasta pelos pr\u00f3prios consumidores prim\u00e1rios (herb\u00edvoros) e n\u00e3o fica dispon\u00edvel para os seus eventuais predadores \u2013 consumidores de segunda ordem (carn\u00edvoros).<\/p>\n<p>Embora nem sempre as representa\u00e7\u00f5es se atenham a essas propor\u00e7\u00f5es, no caso de ambientes terrestres, elas sempre resultam em pir\u00e2mides de base ampla, com poucos n\u00edveis (\u2018andares\u2019) e um topo extremamente estreito. Afinal, a cada degrau, 90% do que havia no andar anterior s\u00e3o gastos e apenas 10% ficam dispon\u00edveis.<\/p>\n<p>No artigo \u201c<a class=\"internal-link\" title=\"Dietas vegetarianas: moda ou tend\u00eancia alimentar para o futuro?\" href=\"http:\/\/cienciahoje.uol.com.br\/revista-ch\/2016\/334\/dietas-vegetarianas-moda-ou-tendencia-alimentar-para-o-futuro\">Dietas vegetarianas: moda ou tend\u00eancia alimentar para o futuro?<\/a>\u201d desta edi\u00e7\u00e3o, Minuzzo e El-Bacha discutem a pertin\u00eancia dessas dietas para a nossa sa\u00fade e chamam a aten\u00e7\u00e3o para o forte impacto ambiental da pecu\u00e1ria, tanto devido ao desmatamento quanto ao uso da terra. J\u00e1 que buscamos abordagens interdisciplinares na escola, nas avalia\u00e7\u00f5es e nos exames de sele\u00e7\u00e3o para ingresso nas universidades, talvez seja interessante entender por que as pir\u00e2mides ecol\u00f3gicas podem ser instrumentos interessantes para esta belecer conex\u00f5es entre a ecologia, outras \u00e1reas da biologia e tamb\u00e9m outras ci\u00eancias.<\/p>\n<h3>Precisamos mudar nosso papel na cadeia alimentar?<\/h3>\n<p>Quando nos alimentamos de carne (de qualquer tipo), estamos pelos menos no terceiro n\u00edvel tr\u00f3fico de uma cadeia alimentar, j\u00e1 que nos alimentamos de herb\u00edvoros ou de on\u00edvoros cuja maior parte da alimenta\u00e7\u00e3o \u00e9 de origem vegetal. Alguns desses vegetais consumidos pelos herb\u00edvoros s\u00e3o utilizados como alimentos volumosos (capim ou silagens vegetais), enquanto outros s\u00e3o os principais componentes da ra\u00e7\u00e3o do gado de corte (o milho, por exemplo).<\/p>\n<dl class=\"image-inline captioned image-inline\">\n<dt><a href=\"http:\/\/cienciahoje.uol.com.br\/revista-ch\/2016\/334\/Escolhaconscienteerealista02.jpg\" rel=\"lightbox\"><img loading=\"lazy\" class=\"link-overlay alignleft\" title=\"Pir\u00e2mide ecol\u00f3gica\" src=\"http:\/\/cienciahoje.uol.com.br\/revista-ch\/2016\/334\/Escolhaconscienteerealista02.jpg\/image_preview\" alt=\"Pir\u00e2mide ecol\u00f3gica\" width=\"400\" height=\"264\" \/><\/a><\/dt>\n<dd class=\"image-caption\">As pir\u00e2mides ecol\u00f3gicas ou tr\u00f3ficas representam as caracter\u00edsticas dos ecossistemas. (gr\u00e1fico: Luiz Baltar)<\/dd>\n<\/dl>\n<p>Se nos lembrarmos de que apenas 10% da energia presente na biomassa de um n\u00edvel tr\u00f3fico \u00e9 incorporada no n\u00edvel seguinte, a perda relacionada ao consumo de carne em rela\u00e7\u00e3o ao de vegetais \u00e9 impressionante. E ela ficar\u00e1 ainda mais clara se usarmos a tradicional pir\u00e2mide de energia para representar essa cadeia de produ\u00e7\u00e3o de carne.<\/p>\n<p>Compreender os impactos dessa tentativa \u2018de saltar n\u00edveis da cadeia alimentar\u2019 sem conhecimentos de geografia e de outras \u00e1reas da pr\u00f3pria biologia depende mais de uma abordagem interdisciplinar do que parece.<\/p>\n<p>Ao longo da evolu\u00e7\u00e3o, a sele\u00e7\u00e3o natural tornou os ruminantes (como os bovinos) capazes de aproveitar de forma eficiente os carboidratos estruturais (em especial, a celulose, polissacar\u00eddeo predominante nas plantas) como fonte energ\u00e9tica. Na presen\u00e7a de compostos nitrogenados n\u00e3o proteicos, carboidratos derivados da celulose s\u00e3o utilizados por bact\u00e9rias para a s\u00edntese de amino\u00e1cidos. A\u00ed reside o segredo da nutri\u00e7\u00e3o dos bovinos: eles t\u00eam a capacidade de aproveitar esses alimentos relativamente pobres em nutrientes gra\u00e7as a estruturas anat\u00f4micas complexas do seu sistema digest\u00f3rio nas quais ocorre uma rela\u00e7\u00e3o mutual\u00edstica com micro\u00adorganismos que, utilizando processos bioqu\u00edmicos, transformam alimentos fibrosos em prote\u00ednas, \u00e1cidos graxos e vitaminas.<\/p>\n<p>Ou seja, os bovinos t\u00eam pouca necessidade de fontes externas de amino\u00e1cidos essenciais e t\u00eam uma efici\u00eancia superior \u00e0 de muitos outros mam\u00edferos silvestres, superando por vezes a incorpora\u00e7\u00e3o padr\u00e3o de 10% da energia dispon\u00edvel nos produtores que consomem (plantas do primeiro n\u00edvel tr\u00f3fico). Embora n\u00e3o se distancie muito dos 10%, esse aumento \u00e9 muito importante para a produ\u00e7\u00e3o de carne (quando chega a 12%, por exemplo, representa um aumento de 20% na produ\u00e7\u00e3o!).<\/p>\n<p>Abordar liga\u00e7\u00f5es entre agricultura e ecologia abre possibilidades de conex\u00f5es com outras \u00e1reas do conhecimento. O gado bovino brasileiro, conhecido internacionalmente como \u2018boi verde\u2019, \u00e9 considerado resultado da produ\u00e7\u00e3o de uma carne mais saud\u00e1vel (com menos gordura) por ser predominantemente criado nos pastos, e n\u00e3o em confinamento.<\/p>\n<p>Mas existe um dilema a\u00ed. Ao demandar maior quantidade de alimentos volumosos (capim) na sua alimenta\u00e7\u00e3o, o boi \u2018verde\u2019 requer tamb\u00e9m maiores extens\u00f5es de terra. Quando combinamos essa necessidade com a demanda global de milh\u00f5es de toneladas de carne por ano, o impacto do boi \u2018verde\u2019 pode ser assustador: ele n\u00e3o \u00e9 exatamente amig\u00e1vel do ponto de vista ecol\u00f3gico, como a cor em seu apelido sugere. Frequentemente, a pecu\u00e1ria ocupa terras mais distantes dos grandes centros, onde a prote\u00e7\u00e3o por \u00f3rg\u00e3os ambientais governamentais \u00e9 mais dif\u00edcil. Isso porque terras mais valorizadas s\u00e3o usadas para agricultura, cujo rendimento econ\u00f4mico \u00e9 superior. Compreender as press\u00f5es exercidas pela agricultura e pela pecu\u00e1ria sobre a ocupa\u00e7\u00e3o das terras exige conhecimentos que s\u00f3 a geografia e a hist\u00f3ria oferecem.<\/p>\n<p>Conhecer os animais que criamos para produzir alimentos requer uma abordagem interdisciplinar. Do lado biol\u00f3gico, \u00e9 preciso compreender sua fisiologia, seu metabolismo, al\u00e9m das rela\u00e7\u00f5es ecol\u00f3gicas que estabeleceram com outras esp\u00e9cies ao longo da evolu\u00e7\u00e3o. Entender, em conjunto com esses temas, a complexidade da pecu\u00e1ria como atividade social e econ\u00f4mica nos permitir\u00e1, talvez, fazer escolhas mais conscientes e realistas quanto \u00e0 nossa alimenta\u00e7\u00e3o. E ajudar\u00e1 os estudantes, e todos n\u00f3s, a compreender que tais escolhas s\u00f3 s\u00e3o poss\u00edveis quando dispomos de conhecimentos de muitas \u00e1reas distintas.<\/p>\n<p><strong>Daniel F\u00e1bio Salvador<\/strong><br \/>\nFunda\u00e7\u00e3o Centro de Ci\u00eancias e Educa\u00e7\u00e3o Superior a Dist\u00e2ncia do Estado do Rio de Janeiro (Cecierj)<\/p>\n<p><strong>Maur\u00edcio Luz<\/strong><br \/>\nInstituto Oswaldo Cruz, Fiocruz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Daniel F\u00e1bio Salvador e Maur\u00edcio Luz Diversas representa\u00e7\u00f5es em forma de pir\u00e2mides t\u00eam sido<\/p>\n","protected":false},"author":2,"featured_media":40414,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/piramides_ecologicas.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/piramides_ecologicas-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/piramides_ecologicas-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/piramides_ecologicas.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/piramides_ecologicas.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/piramides_ecologicas.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/piramides_ecologicas.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/piramides_ecologicas.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/piramides_ecologicas.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/piramides_ecologicas.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Por Daniel F\u00e1bio Salvador e Maur\u00edcio Luz Diversas representa\u00e7\u00f5es em forma de pir\u00e2mides t\u00eam sido","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/40413"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=40413"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/40413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/40414"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=40413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=40413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=40413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}