{"id":40360,"date":"2016-04-09T11:47:20","date_gmt":"2016-04-09T14:47:20","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=40360"},"modified":"2016-04-09T11:47:20","modified_gmt":"2016-04-09T14:47:20","slug":"com-inovacoes-em-sustentabilidade-estadio-aquatico-olimpico-e-inaugurado","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/com-inovacoes-em-sustentabilidade-estadio-aquatico-olimpico-e-inaugurado\/","title":{"rendered":"Com inova\u00e7\u00f5es em sustentabilidade, Est\u00e1dio Aqu\u00e1tico Ol\u00edmpico \u00e9 inaugurado"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/estadio_aquatico_olimpico.jpg\" rel=\"attachment wp-att-40361\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-40361\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/estadio_aquatico_olimpico-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/estadio_aquatico_olimpico-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/estadio_aquatico_olimpico.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Idealizado a partir de princ\u00edpios de sustentabilidade, o<a href=\"http:\/\/www.rio2016.com\/os-jogos\/mapa-de-instalacoes\/estadio-olimpico-de-desp-aquaticos\" target=\"_blank\"> Est\u00e1dio Aqu\u00e1tico Ol\u00edmpico<\/a> foi oficialmente inaugurado nesta sexta-feira (8), na <a href=\"http:\/\/www.rio2016.com\/mapa-de-instalacoes\" target=\"_blank\">Barra da Tijuca<\/a>, Zona Oeste. E o palco para as competi\u00e7\u00f5es de <a href=\"http:\/\/www.rio2016.com\/natacao\">nata\u00e7\u00e3o<\/a> e <a href=\"http:\/\/www.rio2016.com\/polo-aquatico\" target=\"_blank\">p\u00f3lo aqu\u00e1tico<\/a> nos Jogos <a href=\"http:\/\/www.rio2016.com\" target=\"_blank\">Rio 2016<\/a> j\u00e1 come\u00e7ou chamando a aten\u00e7\u00e3o pelo inovador sistema de ventila\u00e7\u00e3o, que proporciona uma economia de energia consider\u00e1vel.<\/p>\n<p>A Prefeitura do Rio, que supervisionou a constru\u00e7\u00e3o da arena (com investimentos do governo federal), estima que seriam necess\u00e1rios 10 mil aparelhos de ar condicionado para refrigerar o local. No entanto, cerca de quinze mil pequenos furos na estrutura garantem a circula\u00e7\u00e3o do ar e devem proporcionar temperaturas amenas para os espectadores no<a href=\"http:\/\/www.rio2016.com\/noticias\/crescendo-a-olhos-vistos\" target=\"_blank\"> Parque Ol\u00edmpico da Barra<\/a> durante as competi\u00e7\u00f5es Ol\u00edmpicas e Paral\u00edmpicas.<\/p>\n<p>&#8220;De fato, sopra uma brisa agrad\u00e1vel aqui dentro&#8221;, observou a presidente da Rep\u00fablica, Dilma Rousseff, presente no evento, junto com o prefeito Eduardo Paes, o governador em exerc\u00edcio do Rio de Janeiro, Francisco Dornelles, e Carlos Nuzman, presidente do Comit\u00ea Rio 2016.<\/p>\n<h2><em>&#8220;Estamos entregando (uma instala\u00e7\u00e3o) com qualidade, dentro do prazo e com baixo custo&#8221;<\/em><\/h2>\n<p><strong>Dilma Rousseff <\/strong><\/p>\n<p><img loading=\"lazy\" class=\"\" src=\"http:\/\/www.rio2016.com\/sites\/default\/files\/users\/Samuel%20Green\/estadio-aquatico-renato-sette-camara_prefeitura-do-rio_2_-_copia.jpg\" alt=\"Imagem Rio 2016\" width=\"639\" height=\"426\" \/><\/p>\n<h5><em>Tr\u00eas eventos-teste ser\u00e3o realizados na Arena neste m\u00eas de abril (Prefeitura do Rio\/Renato Sette Camara)<\/em><\/h5>\n<p>O Est\u00e1dio Aqu\u00e1tico Ol\u00edmpico tem duas piscinas: uma para competi\u00e7\u00e3o e outra para treinamentos, cada uma com capacidade para 3,7 milh\u00f5es de litros. Os assentos da frente ficam a apenas 10 metros da \u00e1gua. Um sistema de filtros especiais adotado reduz em 25% o uso de produtos quimicos, e a regula\u00e7\u00e3o t\u00e9rmica garante temperatura entre 25 e 28 graus, conforme as recomenda\u00e7\u00f5es da Fina (Federa\u00e7\u00e3o Internaciona de Nata\u00e7\u00e3o).<\/p>\n<p><img loading=\"lazy\" class=\"\" src=\"http:\/\/www.rio2016.com\/sites\/default\/files\/users\/Samuel%20Green\/estadio-aquatico-beth-santos-prefeitura-do-rio.jpg\" alt=\"Imagem Rio 2016\" width=\"639\" height=\"426\" \/><\/p>\n<h5><em>Eduardo Paes, Francisco Dornelles, Dilma Rousseff e Carlos Nuzman na inaugura\u00e7\u00e3o (Prefeitura do Rio\/Renato Sette Camara)<\/em><\/h5>\n<p>O Est\u00e1dio Aqu\u00e1tico vai sediar sua primeira competi\u00e7\u00e3o neste m\u00eas: de 15 a 20 de abril, o Trof\u00e9u Maria Lenk, campeonato brasileiro que vale classifica\u00e7\u00e3o Ol\u00edmpica para os atletas nacionais. De 22 a 24, quem cai nas piscinas s\u00e3o os astros da <a href=\"http:\/\/cpb.org.br.187.38-89-161.groveurl.com\/cpb-abre-credenciamento-de-imprensa-para-o-open-internacional-caixa-loterias-de-natacao-paralimpica-no-rio\/\" target=\"_blank\">nata\u00e7\u00e3o Paral\u00edmpica<\/a> (com participa\u00e7\u00e3o de 212 atletas de 19 pa\u00edses). De 25 a 29, \u00e9 a vez do <a href=\"http:\/\/www.aquecerio.com\/polo-aquatico\/\" target=\"_blank\">evento-teste de p\u00f3lo aqu\u00e1tico<\/a>.<\/p>\n<p>Nos Jogos Ol\u00edmpicos, a instala\u00e7\u00e3o ser\u00e1 palco de todas as provas de nata\u00e7\u00e3o (entre 6 e 13 de agosto) e tamb\u00e9m das fases decisivas do p\u00f3lo aqu\u00e1tico (de 14 a 20 de agosto). Nos Jogos Paral\u00edmpicos, a nata\u00e7\u00e3o ser\u00e1 disputada no local, entre 8 e 17 de setembro.<\/p>\n<p>Assim como a Arena do Futuro, que ser\u00e1 desmontada e ter\u00e1 <a href=\"http:\/\/www.rio2016.com\/noticias\/parques-olimpico-e-radical-vao-compartilhar-esporte-e-lazer-apos-os-jogos\" target=\"_blank\">partes utilizadas para a constru\u00e7\u00e3o de quatro escolas p\u00fablicas<\/a>, o Est\u00e1dio Aqu\u00e1tico Ol\u00edmpico vai ser reformulado ap\u00f3s os Jogos e transformado em dois centro aqu\u00e1ticos.<\/p>\n<h5><img loading=\"lazy\" class=\"\" src=\"http:\/\/www.rio2016.com\/sites\/default\/files\/users\/Samuel%20Green\/inauguracao_parqueaquatico_po_alexferro.08042016-1492.jpg\" alt=\"Imagem Rio 2016\" width=\"639\" height=\"425\" \/><\/p>\n<p><em>Trabalhos da artista pl\u00e1stica Adriana Varej\u00e3o d\u00e3o cara ao Est\u00e1dio Aqu\u00e1tico Ol\u00edmpico, na Barra da Tijuca (Rio 2016\/Alex Ferro)<\/em><\/h5>\n<h3>Esporte com arte<\/h3>\n<p>O Est\u00e1dio Aqu\u00e1tico Ol\u00edmpico inova tamb\u00e9m na sua &#8220;cara&#8221;: o exterior da estrutura est\u00e1 envelopado por<a href=\"http:\/\/www.rio2016.com\/noticias\/maremoto-artistico-no-estadio-aquatico\" target=\"_blank\"> trabalhos da renomada artista pl\u00e1stica brasileira Adriana Varej\u00e3o<\/a>. Sessenta e seis pain\u00e9is, cada um com 27 metros, reproduzem &#8220;Celacanto Provoca Maremoto&#8221;, instala\u00e7\u00e3o exposta no<a href=\"http:\/\/www.inhotim.org.br\/inhotim\/sobre\/?gclid=CPzm8IyjgMwCFdRZhgodACII9g\" target=\"_blank\"> Instituto Inhotim<\/a> (MG), que tem como refer\u00eancias azulejaria portuguesa e barroco. Todos os paineis receberam tratamento anti-raios ultravioleta para ajudar a regular a temperatura da instala\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Idealizado a partir de princ\u00edpios de sustentabilidade, o Est\u00e1dio Aqu\u00e1tico Ol\u00edmpico foi oficialmente inaugurado nesta<\/p>\n","protected":false},"author":2,"featured_media":40361,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/estadio_aquatico_olimpico.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/estadio_aquatico_olimpico-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/estadio_aquatico_olimpico-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/estadio_aquatico_olimpico.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/estadio_aquatico_olimpico.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/estadio_aquatico_olimpico.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/estadio_aquatico_olimpico.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/estadio_aquatico_olimpico.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/estadio_aquatico_olimpico.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/04\/estadio_aquatico_olimpico.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Idealizado a partir de princ\u00edpios de sustentabilidade, o Est\u00e1dio Aqu\u00e1tico Ol\u00edmpico foi oficialmente inaugurado nesta","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/40360"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=40360"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/40360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/40361"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=40360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=40360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=40360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}