{"id":35755,"date":"2016-01-24T09:00:15","date_gmt":"2016-01-24T12:00:15","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=35755"},"modified":"2016-01-23T21:36:20","modified_gmt":"2016-01-24T00:36:20","slug":"instituto-aponta-tendencia-de-retomada-do-desmatamento-em-mt","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/instituto-aponta-tendencia-de-retomada-do-desmatamento-em-mt\/","title":{"rendered":"Instituto aponta tend\u00eancia de retomada do desmatamento em MT"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignleft size-medium wp-image-35756\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/01\/desmatamento-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/01\/desmatamento-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/01\/desmatamento.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Mato Grosso foi o \u00fanico estado da Amaz\u00f4nia Legal que ampliou sua \u00e1rea desmatada nos \u00faltimos cinco meses de 2015, com aumento de 16% no corte raso da floresta. Os dados, gerados por observa\u00e7\u00e3o de sat\u00e9lites, foram divulgados pelo Instituto do Homem e Meio Ambiente da Amaz\u00f4nia (Imazon) e, ap\u00f3s an\u00e1lise pelo Instituto Centro de Vida (ICV), confirmam uma tend\u00eancia de retomada do desmatamento no estado desde 2013, em contrariedade \u00e0 redu\u00e7\u00e3o que tem sido observada nos vizinhos da regi\u00e3o amaz\u00f4nica.<\/p>\n<p>A tend\u00eancia apontada pelo ICV tamb\u00e9m contraria o compromisso assumido pelo governador Pedro Taques (PSDB), durante a Confer\u00eancia Mundial do Clima em Paris (COP21), de zerar o desmatamento em Mato Grosso at\u00e9 2020.<\/p>\n<p>De acordo com o ICV, a an\u00e1lise de imagens de sat\u00e9lite \u2013 sempre nos meses de agosto a dezembro \u2013 tem evidenciado acelera\u00e7\u00e3o no ritmo do desmatamento em Mato Grosso ano a ano. Em 2015 os sat\u00e9lites detectaram 419 quil\u00f4metros quadrados de desmatamento (km\u00b2), 16% a mais que a \u00e1rea detectada no mesmo per\u00edodo de 2014 (quando foram constatados 362 km\u00b2).<\/p>\n<p>Considerando o mesmo per\u00edodo do ano para an\u00e1lise, o estudo do ICV aponta incremento ainda mais significativo no ritmo do desmatamento: na compara\u00e7\u00e3o entre 2015 e 2013, a \u00e1rea devastada em Mato Grosso foi ampliada em 670%, afirma o instituto.<\/p>\n<p>O per\u00edodo de agosto a dezembro, caracterizado pela seca na maior parte do estado, \u00e9 considerado a primeira metade do ano no calend\u00e1rio oficial de monitoramento pelas entidades de controle da floresta amaz\u00f4nica.<\/p>\n<p>As altas verificadas neste per\u00edodo em Mato Grosso revelam, para o ICV, uma retomada da atividade desmatadora no estado que contraria a tend\u00eancia de redu\u00e7\u00e3o verificada nos vizinhos da Amaz\u00f4nia Legal \u2013 que compreende os estados do Acre, Amap\u00e1, Amazonas, Maranh\u00e3o, Mato Grosso, Par\u00e1, Rond\u00f4nia, Roraima e Tocantins.<\/p>\n<p><strong>Noroeste de MT<\/strong><br \/>\nAs imagens de sat\u00e9lites tamb\u00e9m mostram que a atividade desmatadora em Mato Grosso tem se concentrado na regi\u00e3o noroeste do estado, com o munic\u00edpio de Colniza (a 1.065 km da capital) na condi\u00e7\u00e3o de l\u00edder do ranking dos munic\u00edpios que mais devastaram.<\/p>\n<p>Al\u00e9m de atualmente deter a maior \u00e1rea devastada por munic\u00edpios, Colniza tamb\u00e9m lidera o movimento que o ICV considera uma retomada robusta do corte raso: entre agosto e dezembro de 2013 o munic\u00edpio n\u00e3o havia desmatado nem 10 km\u00b2 de floresta, n\u00famero que saltou para quase 70 km\u00b2 no mesmo per\u00edodo do ano seguinte e para 74 km\u00b2 entre agosto e dezembro de 2015.<\/p>\n<p>Somente a \u00e1rea desmatada por Colniza representa 19% de toda a \u00e1rea devastada entre agosto e dezembro de 2015 em Mato Grosso. Colniza e outros nove munic\u00edpios (Aripuan\u00e3, Cotrigua\u00e7\u00fa, Feliz Natal, Juara, Ju\u00edna, Nova Bandeirantes, Quer\u00eancia, S\u00e3o Jos\u00e9 do Xingu e Uni\u00e3o do Sul) foram respons\u00e1veis por mais de 60% do desmatamento no per\u00edodo em Mato Grosso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mato Grosso foi o \u00fanico estado da Amaz\u00f4nia Legal que ampliou sua \u00e1rea desmatada nos<\/p>\n","protected":false},"author":2,"featured_media":35756,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/01\/desmatamento.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/01\/desmatamento-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/01\/desmatamento-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/01\/desmatamento.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/01\/desmatamento.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/01\/desmatamento.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/01\/desmatamento.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/01\/desmatamento.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/01\/desmatamento.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2016\/01\/desmatamento.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Mato Grosso foi o \u00fanico estado da Amaz\u00f4nia Legal que ampliou sua \u00e1rea desmatada nos","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/35755"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=35755"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/35755\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/35756"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=35755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=35755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=35755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}