{"id":32645,"date":"2015-12-02T17:00:40","date_gmt":"2015-12-02T20:00:40","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=32645"},"modified":"2015-12-01T21:59:51","modified_gmt":"2015-12-02T00:59:51","slug":"humanidade-pode-ficar-sem-oxigenio-com-aumento-da-temperatura-diz-estudo","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/humanidade-pode-ficar-sem-oxigenio-com-aumento-da-temperatura-diz-estudo\/","title":{"rendered":"Humanidade pode ficar sem oxig\u00eanio com aumento da temperatura, diz estudo"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/12\/ar_desastre.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-32646\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/12\/ar_desastre-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/12\/ar_desastre-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/12\/ar_desastre.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Com um aumento de 5\u00b0C da temperatura global, a humanidade poderia ficar sem oxig\u00eanio, de acordo com um estudo publicado nesta ter\u00e7a-feira (1\u00ba), \u00e0 margem da Confer\u00eancia do Clima de Paris (COP-21), embora esse cen\u00e1rio possa ser evitado pelas medidas tomadas pela comunidade internacional.<\/p>\n<p>&#8220;N\u00f3s identificamos uma outra poss\u00edvel consequ\u00eancia das altera\u00e7\u00f5es clim\u00e1ticas que podem ser potencialmente mais perigosas do que todas as outras&#8221;, explicaram dois pesquisadores da Universidade de Leicester, na Gr\u00e3-Bretanha, em uma pesquisa publicada no Bulletin of Mathematical Biology.<\/p>\n<p>Gra\u00e7as a um modelo matem\u00e1tico, os autores estimam que um aquecimento global de 6\u00b0C em compara\u00e7\u00e3o com a era pr\u00e9-industrial poderia parar a produ\u00e7\u00e3o de oxig\u00eanio do fitopl\u00e2ncton, organismos vegetais que vivem em suspens\u00e3o na \u00e1gua e fornecem dois ter\u00e7os do oxig\u00eanio presente na atmosfera.<\/p>\n<p>&#8220;Isso significaria o desaparecimento do oxig\u00eanio da \u00e1gua, mas tamb\u00e9m do ar&#8221;, concluiu a equipe. &#8220;Se isso viesse a acontecer, obviamente, levaria \u00e0 morte de um grande n\u00famero de esp\u00e9cies na Terra&#8221;, acrescentou.<\/p>\n<p>A comunidade internacional, reunida em Paris para uma confer\u00eancia clim\u00e1tica fundamental, estabeleceu o objetivo de limitar o aquecimento a 2\u00b0C em compara\u00e7\u00e3o aos tempos pr\u00e9-industriais e agora deve chegar a um acordo sobre as modalidades para o fazer. Desde 1850, a temperatura da Terra j\u00e1 aumentou mais de 1\u00b0C.<\/p>\n<p>At\u00e9 agora, as medidas anunciadas colocam a Terra no caminho de um aquecimento de entre 2,7\u00b0C e 3,5\u00b0C. E se o mundo realmente n\u00e3o fizer nada para combater as altera\u00e7\u00f5es clim\u00e1ticas descontroladas, a coluna de merc\u00fario subiria +4,8\u00b0C neste s\u00e9culo, segundo o grupo de peritos da ONU (IPCC).<\/p>\n<p>&#8220;Poderia haver poucos sinais de alerta&#8221;, explicou \u00e0 AFP o co-autor Sergei Petrovskii. &#8220;Mas se n\u00f3s superarmos o limiar cr\u00edtico&#8221;, que \u00e9 de 6\u00b0C, &#8220;ir\u00edamos rapidamente rumo \u00e0 cat\u00e1strofe&#8221;.<\/p>\n<p>Os autores ressaltam, por\u00e9m, que o modelo n\u00e3o inclui os efeitos de certos processos naturais, tais como a circula\u00e7\u00e3o oce\u00e2nica &#8211; que poderiam ter um impacto sobre os efeitos do aquecimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com um aumento de 5\u00b0C da temperatura global, a humanidade poderia ficar sem oxig\u00eanio, de<\/p>\n","protected":false},"author":2,"featured_media":32646,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/12\/ar_desastre.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/12\/ar_desastre-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/12\/ar_desastre-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/12\/ar_desastre.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/12\/ar_desastre.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/12\/ar_desastre.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/12\/ar_desastre.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/12\/ar_desastre.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/12\/ar_desastre.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/12\/ar_desastre.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Com um aumento de 5\u00b0C da temperatura global, a humanidade poderia ficar sem oxig\u00eanio, de","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/32645"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=32645"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/32645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/32646"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=32645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=32645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=32645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}