{"id":31614,"date":"2015-11-15T09:05:31","date_gmt":"2015-11-15T12:05:31","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=31614"},"modified":"2015-11-15T09:05:31","modified_gmt":"2015-11-15T12:05:31","slug":"lua-de-marte-ja-apresenta-sinais-de-sua-futura-destruicao-pela-acao-da-gravidade-do-planeta","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/lua-de-marte-ja-apresenta-sinais-de-sua-futura-destruicao-pela-acao-da-gravidade-do-planeta\/","title":{"rendered":"Lua de Marte j\u00e1 apresenta sinais de sua futura destrui\u00e7\u00e3o pela a\u00e7\u00e3o da gravidade do planeta"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/lua.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-31615\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/lua-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/lua-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/lua.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Phobos, a maior das duas pequenas luas de Marte, j\u00e1 apresenta sinais de sua futura destrui\u00e7\u00e3o pela a\u00e7\u00e3o da gravidade do planeta. De acordo com estudo apresentado esta semana durante reuni\u00e3o anual da Sociedade Astron\u00f4mica Americana (AAS), as longas e rasas fendas em sua superf\u00edcie indicam que ela j\u00e1 sofre com as for\u00e7as de mar\u00e9 que dever\u00e3o despeda\u00e7\u00e1-la daqui a 30 a 50 milh\u00f5es de anos. Orbitando a meros 6 mil quil\u00f4metros acima da superf\u00edcie de Marte, Phobos \u00e9 a lua em posi\u00e7\u00e3o mais pr\u00f3xima de seu planeta no Sistema Solar e continua sendo gradualmente atra\u00edda por Marte, chegando cerca de dois metros mais perto a cada s\u00e9culo.<\/p>\n<p>&#8211; Acreditamos que Phobos j\u00e1 come\u00e7ou a se romper, e os primeiro sinal deste colapso \u00e9 a produ\u00e7\u00e3o destas fendas \u2013 diz Terry Hurford, pesquisador do Centro de Voo Espacial Goddard da Nasa e um dos autores do estudo.<\/p>\n<p>Os cientistas a princ\u00edpio acreditavam que as longas fendas em Phobos foram causadas pela colis\u00e3o de um objeto que formou a cratera Stickney e por pouco n\u00e3o a despeda\u00e7ou. Com o tempo, no entanto, eles observaram que as fendas n\u00e3o se irradiavam da cratera como se pensava, mas de um foco pr\u00f3ximo, levando a proporem que elas teriam sido produzidas pro v\u00e1rios pequenos impactos de material ejetado de Marte.<\/p>\n<p>Hurford e seus colegas, por\u00e9m, produziram um modelo que sugere que as fendas na verdade s\u00e3o marcas de tra\u00e7\u00e3o que se formam \u00e0 medida que Phobos \u00e9 deformada pelas for\u00e7as de mar\u00e9 da gravidade marciana. A Terra e a Lua se atraem da mesma forma, o que provoca as idas e vindas das mar\u00e9s nos oceanos e deixa nosso planeta levemente achatado, e n\u00e3o perfeitamente esf\u00e9rico.<\/p>\n<p>Embora a mesma explica\u00e7\u00e3o para as fendas tenha sido proposta d\u00e9cadas atr\u00e1s, depois que as sondas Viking, tamb\u00e9m da Nasa, enviaram imagens de Phobos nos anos 1970, na \u00e9poca acreditava-se que a lua era razoavelmente s\u00f3lida. Assim, quando as for\u00e7as de mar\u00e9 foram calculadas, elas foram apontadas como fracas demais para causar fraturas em uma lua s\u00f3lida daquele tamanho, com formato irregular e dimens\u00f5es de cerca de 27 \u00d7 22 \u00d7 18 quil\u00f4metros. Hoje, por\u00e9m, acredita-se que o interior da lua \u00e9, na verdade, formado por uma pilha de escombros que mal se mant\u00e9m unida, cercado por uma camada de regolito (fragmentos de pedras e poeira) com cerca de cem metros de espessura.<\/p>\n<p>&#8211; O que \u00e9 interessante sobre nosso resultado \u00e9 que ele mostra que Phobos tem um material de certa forma coesivo no seu exterior \u2013 conta Erik Asphaug, pesquisador da Universidade do Estado do Arizona em Tempe e coautor do estudo. &#8211; Isso faz sentido quando voc\u00ea pensa no comportamento de materiais poeirentos em microgravidade, mas \u00e9 um tanto contraintuitivo.<\/p>\n<p>Segundo os cientistas, um n\u00facleo \u201cfrouxo\u201d assim faz com que ele se distor\u00e7a facilmente por n\u00e3o ter a resist\u00eancia necess\u00e1ria para se manter perfeitamente coeso frente \u00e0s for\u00e7as de mar\u00e9, ainda que relativamente pequenas, da gravidade de Marte. Isto for\u00e7a a camada externa a se reajustar, acumulando estresse que eventualmente levar\u00e1 ao surgimento de fendas, como previsto pelo modelo e observado na superf\u00edcie da lua marciana. Isso tamb\u00e9m ajuda a explicar a observa\u00e7\u00e3o de que algumas das fendas parecem muito mais jovens que outras, o que se encaixa no caso de ser um processo em constante a\u00e7\u00e3o.<\/p>\n<p>Trit\u00e3o, uma das luas de Netuno, dever\u00e1 ter o mesmo destino de Phobos. A lua netuniana tamb\u00e9m est\u00e1 lentamente caindo em dire\u00e7\u00e3o ao planeta e apresenta sinais de estresse em sua superf\u00edcie. De acordo com os cientistas, o estudo pode ajudar ainda nas pesquisas sobre planetas extrassolares, muitos dos quais orbitam bem pr\u00f3ximos de suas estrelas.<\/p>\n<p>&#8211; N\u00e3o podemos fazer imagens destes planetas distantes para saber o que est\u00e1 acontecendo, mas este trabalho pode nos ajudar a melhor entender estes sistemas, pois qualquer planeta que esteja caindo em dire\u00e7\u00e3o \u00e0 sua estrela-m\u00e3e seria despeda\u00e7ado da mesma maneira \u2013 conclui Hurford.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Phobos, a maior das duas pequenas luas de Marte, j\u00e1 apresenta sinais de sua futura<\/p>\n","protected":false},"author":2,"featured_media":31615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/lua.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/lua-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/lua-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/lua.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/lua.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/lua.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/lua.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/lua.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/lua.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/lua.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Phobos, a maior das duas pequenas luas de Marte, j\u00e1 apresenta sinais de sua futura","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/31614"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=31614"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/31614\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/31615"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=31614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=31614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=31614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}