{"id":31611,"date":"2015-11-15T08:59:52","date_gmt":"2015-11-15T11:59:52","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=31611"},"modified":"2015-11-15T08:59:52","modified_gmt":"2015-11-15T11:59:52","slug":"carros-a-gasolina-da-volkswagen-tambem-tem-dados-sob-suspeita","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/carros-a-gasolina-da-volkswagen-tambem-tem-dados-sob-suspeita\/","title":{"rendered":"Carros a gasolina da Volkswagen tamb\u00e9m t\u00eam dados sob suspeita"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/co2.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-31612\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/co2-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/co2-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/co2.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Em um segundo cap\u00edtulo do esc\u00e2ndalo de emiss\u00f5es de poluentes, que come\u00e7ou com motores a diesel, a <a class=\"premium-tip\" href=\"http:\/\/g1.globo.com\/carros\/marcas\/volkswagen.html\">Volkswagen<\/a> informou que 4 motores a gasolina t\u00eam dados sob suspeita. Nesse caso, \u00e9 o n\u00edvel de di\u00f3xido de carbono (CO2) que est\u00e1 sendo questionado e a investiga\u00e7\u00e3o envolve tamb\u00e9m propulsores a diesel.<\/p>\n<p>A montadora j\u00e1 havia informado que <a href=\"http:\/\/g1.globo.com\/carros\/noticia\/2015\/11\/volks-diz-que-descobriu-incoerencias-em-mais-800-mil-veiculos.html\">800 mil unidades estavam sob suspeita<\/a>; na \u00faltima\u00a0 sexta-feira (13), ela detalhou que 430 mil s\u00e3o ano 2016 e listou marcas, modelos e motores envolvidos (<a href=\"http:\/\/www.volkswagenag.com\/content\/vwcorp\/info_center\/en\/news\/2015\/11\/CO2.bin.html\/downloadfilelist\/downloadfile\/downloadfile\/file\/List+of+critical+CO2+vehicles%2C+model+year+2016.pdf\" target=\"_blank\">veja a lista completa<\/a>).<\/p>\n<div id=\"entenda_o_caso_381\" class=\"entenda-o-caso componente_materia\">O caso da fraude de emiss\u00f5es come\u00e7ou em setembro passado, com a den\u00fancia da ag\u00eancia ambiental americana (EPA) de que a Volkswagen usava, em propulsores a diesel, um programa de computador que reduzia a emiss\u00e3o de \u00f3xido nitrog\u00eanio (NOx) apenas quando percebia que o carro estava passando por uma inspe\u00e7\u00e3o.<\/div>\n<p>Em condi\u00e7\u00f5es normais de rodagem, esses modelos emitiam mais NOx do que o declarado.<\/p>\n<p>Na \u00e9poca, a Volkswagen admitiu que esse software foi usado em <a href=\"http:\/\/g1.globo.com\/carros\/noticia\/2015\/09\/volkswagen-admite-que-11-milhoes-de-carros-tem-software-que-frauda-testes.html\">11 milh\u00f5es de ve\u00edculos<\/a> equipados com motor EA 189, que \u00e9 2.0 litros. Entre eles, est\u00e3o modelos como o Golf e o Jetta.<\/p>\n<p>No Brasil, onde \u00e9 proibida a venda de carros de passeio com motor a diesel, a montadora disse que apenas a <a href=\"http:\/\/g1.globo.com\/carros\/noticia\/2015\/11\/ibama-multa-volkswagen-em-r-50-milhoes-por-fraude-em-motores.html\">picape Amarok<\/a>, anos 2011 e 2012 (lote parcial), est\u00e1 envolvida. Por causa disso, o Ibama multou a empresa em R$ 50 milh\u00f5es.<\/p>\n<p><strong>Motores 1.0 TSI e 2.0 TFSI<\/strong><br \/>\nNo in\u00edcio de novembro, a Volkswagen divulgou que, durante investiga\u00e7\u00e3o interna, encontrou &#8220;incoer\u00eancias&#8221; tamb\u00e9m nos dados de CO2 de 800 mil ve\u00edculos. Inicialmente, foi informado apenas um modelo com motor a gasolina, o Polo, equipado com o 1.4 litro ACT.<\/p>\n<p>Nesta sexta, a montadora divulgou a lista dos modelos 2016 afetados nessa nova nvestiga\u00e7\u00e3o e relacionou mais 3 motores a gasolina: o 1.0 de 3 cilindros TSI de Polo, Seat Ibiza e Leon, o 1.8 de 4 cilindros TFSI do Seat Leon SC e da Sport Tourer. E o 2.0 TFSI de Volkswagen Golf e Passat, tamb\u00e9m de 4 cilindros. Al\u00e9m deles, s\u00e3o citados motores a diesel de carros como Audi A1, Volkswagen Tiguan e Passat.<\/p>\n<p>O n\u00edvel de CO2 real desses modelos ano 2016 n\u00e3o foi divulgado. A Volkswagen informa que ele ser\u00e1 determinado junto com autoridades locais. E que o site de cada pa\u00eds ou regi\u00e3o atendidos pela marca vai divulgar novas informa\u00e7\u00f5es sobre o caso nas pr\u00f3ximas semanas e disponibilizar\u00e1 a consulta por n\u00famero do chassi.<\/p>\n<p>A fabricante destaca que continuar\u00e1 investigando, junto \u00e0s autoridades, quais modelos de anos anteriores tamb\u00e9m est\u00e3o sob suspeita. &#8220;Baseado no que se sabe at\u00e9 agora, o grupo Volkswagen continua antecipando que o total (de ve\u00edculos envolvidos) dever\u00e1 ser o n\u00famero previamente informado de 800 mil&#8221;, disse a companhia, em comunicado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em um segundo cap\u00edtulo do esc\u00e2ndalo de emiss\u00f5es de poluentes, que come\u00e7ou com motores a<\/p>\n","protected":false},"author":2,"featured_media":31612,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/co2.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/co2-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/co2-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/co2.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/co2.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/co2.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/co2.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/co2.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/co2.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2015\/11\/co2.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Em um segundo cap\u00edtulo do esc\u00e2ndalo de emiss\u00f5es de poluentes, que come\u00e7ou com motores a","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/31611"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=31611"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/31611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/31612"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=31611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=31611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=31611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}