{"id":130386,"date":"2020-07-15T08:00:42","date_gmt":"2020-07-15T11:00:42","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=130386"},"modified":"2020-07-14T19:04:00","modified_gmt":"2020-07-14T22:04:00","slug":"crise-climatica-apresenta-serios-riscos-para-a-gravidez-diz-pesquisadores","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/crise-climatica-apresenta-serios-riscos-para-a-gravidez-diz-pesquisadores\/","title":{"rendered":"Crise clim\u00e1tica apresenta s\u00e9rios riscos para a gravidez, diz pesquisadores"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/ravidez.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-130387\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/ravidez-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/ravidez-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/ravidez.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Pesquisadores descobriram consequ\u00eancias bastante assustadoras para a sa\u00fade<\/p>\n<p>Mais de uma d\u00e9cada de evid\u00eancias irrefut\u00e1veis ligam a polui\u00e7\u00e3o atmosf\u00e9rica e a exposi\u00e7\u00e3o ao calor a resultados negativos na gravidez, nos Estados Unidos, de acordo com uma nova revis\u00e3o de dezenas de estudos.<\/p>\n<p>A investiga\u00e7\u00e3o, publicada no Jornal da Associa\u00e7\u00e3o M\u00e9dica Americana (American Medical Association), identificou 57 estudos desde 2007 mostrando uma associa\u00e7\u00e3o significativa entre os dois fatores e o risco de parto prematuro, baixo peso ao nascer e \u00f3bito fetal (natimorto).<\/p>\n<p>Mulheres negras estavam particularmente em risco, assim como pessoas com asma. A pesquisa analisou 32 mil nascimentos de 68 estudos. Desses, 84% apontaram a polui\u00e7\u00e3o atmosf\u00e9rica e o calor como fatores de risco.<\/p>\n<p>Dist\u00farbios clim\u00e1ticos causados pela a\u00e7\u00e3o humana est\u00e3o provocando o aumento das temperaturas e da umidade e reduzindo a capacidade das pessoas se resfriarem at\u00e9 mesmo \u00e0 noite. As mudan\u00e7as clim\u00e1tica tamb\u00e9m pioram a polui\u00e7\u00e3o do ar. A neblina de fuma\u00e7a resultante da queima de combust\u00edveis f\u00f3sseis \u00e9 formada nos dias quentes, e inc\u00eandios florestais que levam \u00e0 inala\u00e7\u00e3o de fuma\u00e7a s\u00e3o agravados pela crise. \u201cQuando voc\u00ea fala cobre clima, as pessoas pensam que se trata de \u2018tempo ruim\u2019, como fortes<br \/>\ntempestades ou grandes inc\u00eandios\u2026 Mas n\u00f3s quer\u00edamos falar sobre os impactos que s\u00e3o comuns, generalizados, e que est\u00e3o acontecendo agora e s\u00e3o raramente associados \u00e0 crise clim\u00e1tica\u201d, disse Burce Bekkar, obstreta aposentado e co-autor do estudo.<\/p>\n<p>\u201cN\u00f3s j\u00e1 temos gera\u00e7\u00f5es enfraquecidas desde o nascimento. Simplesmente n\u00e3o podemos permitir que isso aconte\u00e7a, e eu gostaria de ver n\u00e3o apenas m\u00e3es e seus maridos e crian\u00e7as aparecendo nas reuni\u00f5es dos conselhos, mas eu gostaria de ver muito mais profissionais da sa\u00fade envolvidos na demanda por legisla\u00e7\u00e3o que reduza os atuais e, bastante assustadores, efeitos da crise clim\u00e1tica na sa\u00fade.\u201d<\/p>\n<p>As descobertas eclodem enquanto a administra\u00e7\u00e3o Trump procura enfraquecer os esfor\u00e7os clim\u00e1ticos e pol\u00edticas de prote\u00e7\u00e3o contra a polui\u00e7\u00e3o, inclusive revertendo os padr\u00f5es de emiss\u00e3o de poluentes pelos carros e usinas de energia. A Ag\u00eancia de Prote\u00e7\u00e3o do Meio Ambiente do governo Trump tamb\u00e9m ignorou as orienta\u00e7\u00f5es de cientistas de decretar regras mais rigorosas sobre a qualidade do ar.<\/p>\n<p>O Col\u00e9gio Americano de Ginecologia e Obstetr\u00edcia j\u00e1 considera as mudan\u00e7as clim\u00e1ticas como uma amea\u00e7a eminente \u00e0 sa\u00fade das mulheres, al\u00e9m de ser um grande desafio para a sa\u00fade p\u00fablica. As mudan\u00e7as clim\u00e1ticas est\u00e3o associadas com a piora de doen\u00e7as card\u00edacas, doen\u00e7as respirat\u00f3rias, sa\u00fade mental e exposi\u00e7\u00e3o a doen\u00e7as infecciosas. Por\u00e9m, gestantes e fetos em desenvolvimento s\u00e3o especialmente vulner\u00e1veis ao seus efeitos.<\/p>\n<p>Na pesquisa, 19 estudos conectaram a polui\u00e7\u00e3o do ar com parto prematuro, definido como nascimento antes de 37 semanas de gesta\u00e7\u00e3o; 25 estudos ligaram a polui\u00e7\u00e3o atmosf\u00e9rica a baixo peso ao nascer; e quatro estudos associaram a polui\u00e7\u00e3o do ar ao \u00f3bito fetal (natimorto). Um estudo descobriu risco aumentado em 42% de \u00f3bito fetal com alta exposi\u00e7\u00e3o no terceiro trimestre de gravidez. \u00d3bito fetal \u00e9 raro, ent\u00e3o os dados sobre isso s\u00e3o limitados o que dificulta tra\u00e7ar conclus\u00f5es sobre as raz\u00f5es pelas quais acontece, afirmou Bekkar.<\/p>\n<p>A pesquisa considerou estudos sobre a neblina de fuma\u00e7a (smog), tamb\u00e9m chamada de oz\u00f4nio, e part\u00edculas finas de polui\u00e7\u00e3o.<\/p>\n<p>Estudos cient\u00edficos emergentes est\u00e3o cada vez mais ligando a polui\u00e7\u00e3o atmosf\u00e9rica a uma gama de problemas de sa\u00fade, incluindo dem\u00eancia. Um novo estudo com roedores da Universidade da Calif\u00f3rnia, Davis, descobriu que a polui\u00e7\u00e3o produzida pelo tr\u00e2nsito est\u00e1 conectada ao aumento do risco de altera\u00e7\u00f5es no desenvolvimento cerebral que podem causar dist\u00farbios no neurodesenvolvimento.<\/p>\n<p>\u201cO que testemunhamos s\u00e3o mudan\u00e7as sutis\u201d, disse o co-autor Kelley Patten. \u201cMas n\u00f3s estamos vendo esses efeitos da exposi\u00e7\u00e3o \u00e0 polui\u00e7\u00e3o do ar que se enquadram dentro dos limites regulat\u00f3rios\u201d.<\/p>\n<p>Eram poucos os estudos para rever sobre o efeito do calor nas gesta\u00e7\u00f5es, mas quase todos eles conclu\u00edram que isso \u00e9 prejudicial. Um estudo postula que o risco de parto prematuro aumentou 11.6% a cada aumento de 5.6C. A m\u00e9dia global de temperatura j\u00e1 est\u00e1 mais de 1C acima do que era antes da industrializa\u00e7\u00e3o e est\u00e1 no caminho para elevar mais 3C.<\/p>\n<p>O estudo confirmou que m\u00e3es negras est\u00e3o ainda mais expostas ao risco de parto prematuro e baixo peso ao nascer. As determina\u00e7\u00f5es sociais de sa\u00fade \u2013 incluindo a pobreza, n\u00edveis prolongados de estresse e acesso \u00e0 assist\u00eancia m\u00e9dica \u2013 recaem desproporcionalmente mais sobre a popula\u00e7\u00e3o negra.<\/p>\n<p>O estudo conclui que \u201ca exposi\u00e7\u00e3o ambiental exacerba ainda mais esse risco e pode ser inclu\u00edda junto aos fatores sociais determinantes\u201d.<\/p>\n<p>Os americanos cada vez mais entendem que a crise clim\u00e1tica est\u00e1 fazendo mal para a sa\u00fade humana, de acordo com uma pesquisa feita pelo Programa de Yale sobre Comunica\u00e7\u00e3o das Mudan\u00e7as Clim\u00e1ticas.<\/p>\n<p>Neste ano, muito mais americanos responderam que acreditam que insola\u00e7\u00f5es, asma, doen\u00e7as transmitidas por insetos e alergias relacionadas ao p\u00f3len piorem conforme o planeta aquece.<\/p>\n<p>Em 2014, por exemplo, 37% dos americanos pensavam que insola\u00e7\u00f5es causadas por severas ondas de calor fossem se tornar mais comuns. Em abril, 57% dos americanos pensaram isso.<\/p>\n<p>Um movimento crescente junto a profissionais m\u00e9dicos visa educar pacientes sobre as mudan\u00e7as clim\u00e1ticas. Bekkar espera que os profissionais da sa\u00fade compartilhem as descobertas do estudo com os seus pacientes, convencendo-os a evitar exposi\u00e7\u00f5es prolongadas ao calor e \u00e0 polui\u00e7\u00e3o.<\/p>\n<p>\u201cN\u00e3o \u00e9 poss\u00edvel para todos, mas aqueles que podem, devem. Se algu\u00e9m n\u00e3o tem um ar condicionado em casa e est\u00e1 gr\u00e1vida, quanto mais tempo puder passar em lugares com ar condicionado que libera ar filtrado, melhor ser\u00e1 o resultado da gesta\u00e7\u00e3o\u201d, alegou Bekkar.<\/p>\n<p>Al\u00e9m disso, ele quer que aqueles que lutam ao lado das mulheres demandem mais das autoridades eleitas.<\/p>\n<p>\u201cReduzir a polui\u00e7\u00e3o atmosf\u00e9rica e lutar contra as mudan\u00e7as clim\u00e1ticas \u00e9 uma quest\u00e3o de sobreviv\u00eancia dos seus filhos e de suas sa\u00fades\u201d, ele disse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisadores descobriram consequ\u00eancias bastante assustadoras para a sa\u00fade Mais de uma d\u00e9cada de evid\u00eancias irrefut\u00e1veis<\/p>\n","protected":false},"author":2,"featured_media":130387,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/ravidez.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/ravidez-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/ravidez-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/ravidez.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/ravidez.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/ravidez.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/ravidez.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/ravidez.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/ravidez.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/ravidez.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Pesquisadores descobriram consequ\u00eancias bastante assustadoras para a sa\u00fade Mais de uma d\u00e9cada de evid\u00eancias irrefut\u00e1veis","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/130386"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=130386"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/130386\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/130387"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=130386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=130386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=130386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}