{"id":130350,"date":"2020-07-14T08:00:51","date_gmt":"2020-07-14T11:00:51","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=130350"},"modified":"2020-07-14T06:25:52","modified_gmt":"2020-07-14T09:25:52","slug":"incerteza-do-isolamento-causa-impactos-na-saude-mental-dizem-especialistas","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/incerteza-do-isolamento-causa-impactos-na-saude-mental-dizem-especialistas\/","title":{"rendered":"Incerteza do isolamento causa impactos na sa\u00fade mental, dizem especialistas"},"content":{"rendered":"<p><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/isolamento-1.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-130351\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/isolamento-1-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/isolamento-1-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/isolamento-1.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Priscila Correia, de 37 anos, est\u00e1 angustiada com a flexibiliza\u00e7\u00e3o do isolamento social. Ela mora com a av\u00f3, de 93 anos, e n\u00e3o sai de casa h\u00e1 mais de cem dias, desde que foi determinada a quarentena por causa do novo coronav\u00edrus. J\u00e1 Fabiano Barcellos, de 40, diz ser \u201cmuito da rua\u201d e se sente incomodado por n\u00e3o saber quando a reclus\u00e3o ter\u00e1 fim. Assim como o Rio, cidades de S\u00e3o Paulo, Minas e Pernambuco precisaram recuar na reabertura ap\u00f3s observar que a libera\u00e7\u00e3o de servi\u00e7os n\u00e3o essenciais criou aglomera\u00e7\u00f5es.<\/p>\n<p>\u2014 O maior problema do ansioso \u00e9 n\u00e3o saber quando isso acaba \u2014 diz Fabiano.<\/p>\n<p>Especialistas veem com preocupa\u00e7\u00e3o a possibilidade de um novo endurecimento das medidas se as contamina\u00e7\u00f5es e mortes voltarem a subir.<\/p>\n<p>O poss\u00edvel retorno \u00e0s aulas presenciais dos filhos \u00e9 o que tem tirado o sono de Aline Borba, de 41 anos. M\u00e3e de Ana Carolina, de 10, e de Matheus, de 14, ela n\u00e3o sabe o que vai fazer quando os col\u00e9gios reabrirem:<\/p>\n<p>\u2014 Meu filho n\u00e3o quer voltar durante a pandemia de jeito nenhum. J\u00e1 Ana Carolina est\u00e1 com medo, por\u00e9m sofrendo com esse isolamento, diz que sente falta das pessoas e do contato humano.<\/p>\n<p>Estudos indicam o aumento do n\u00edvel de ansiedade como o principal efeito da quarentena sobre a sa\u00fade mental. Especialistas dizem que um dos motivos da confus\u00e3o \u00e9 a falta de uma coordena\u00e7\u00e3o nacional de combate ao v\u00edrus.<\/p>\n<p>\u2014 Informa\u00e7\u00f5es conflitantes podem gerar um estado de desamparo nas pessoas, fazendo com que n\u00e3o confiem mais nas not\u00edcias oficiais \u2014 avalia Ronaldo Pilati, professor de Psicologia Social da UnB.<\/p>\n<p>Segundo Guilherme Polanczyk, psiquiatra da USP, \u00e9 esperado que os mais jovens tenham mais dificuldade de lidar com o isolamento social.<\/p>\n<p>\u2014 Essa perspectiva de sair, de estar num grupo social novamente, de enfrentar o mundo, de correr o risco da contamina\u00e7\u00e3o, gera ansiedade \u2014 diz o m\u00e9dico, que indica massagem contra o estresse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Priscila Correia, de 37 anos, est\u00e1 angustiada com a flexibiliza\u00e7\u00e3o do isolamento social. Ela mora<\/p>\n","protected":false},"author":2,"featured_media":130351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/isolamento-1.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/isolamento-1-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/isolamento-1-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/isolamento-1.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/isolamento-1.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/isolamento-1.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/isolamento-1.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/isolamento-1.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/isolamento-1.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/07\/isolamento-1.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Priscila Correia, de 37 anos, est\u00e1 angustiada com a flexibiliza\u00e7\u00e3o do isolamento social. Ela mora","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/130350"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=130350"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/130350\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/130351"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=130350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=130350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=130350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}