{"id":129853,"date":"2020-07-05T16:16:36","date_gmt":"2020-07-05T19:16:36","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=129853"},"modified":"2020-07-05T16:19:26","modified_gmt":"2020-07-05T19:19:26","slug":"poluicao-microplastica-se-acumula-mais-fortemente-em-habitats-costeiros","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/poluicao-microplastica-se-acumula-mais-fortemente-em-habitats-costeiros\/","title":{"rendered":"Polui\u00e7\u00e3o micropl\u00e1stica se acumula mais fortemente em habitats costeiros"},"content":{"rendered":"<p class=\"western\" align=\"left\">A polui\u00e7\u00e3o micropl\u00e1stica em ambientes marinhos concentra-se mais em habitats costeiros, especialmente fiordes e estu\u00e1rios, de acordo com um novo\u00a0<span lang=\"zxx\"><u><a href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S0025326X20305166\">artigo de<\/a><\/u><\/span>\u00a0revis\u00e3o\u00a0publicado na revista\u00a0<i>Marine Pollution Bulletin<\/i>\u00a0.<\/p>\n<p class=\"western\" align=\"left\"><strong>GRID-Arendal<\/strong>*<\/p>\n<p class=\"western\" align=\"left\">Os ambientes do fundo do mar geralmente t\u00eam concentra\u00e7\u00f5es micropl\u00e1sticas muito mais baixas, embora existam pontos de acesso em que ocorrem concentra\u00e7\u00f5es elevadas de micropl\u00e1stico.\u00a0O artigo foi escrito pelo ge\u00f3logo marinho Peter Harris, diretor da GRID-Arendal.<\/p>\n<p class=\"western\" align=\"left\">A cada ano, os humanos produzem 360 milh\u00f5es de toneladas de pl\u00e1stico e, segundo\u00a0<span lang=\"zxx\"><u><a href=\"https:\/\/science.sciencemag.org\/content\/347\/6223\/768\">um estudo<\/a><\/u><\/span>\u00a0, cerca de 8 milh\u00f5es de toneladas entram no oceano.\u00a0At\u00e9 recentemente, o destino dos micropl\u00e1sticos (part\u00edculas com menos de 5 mm de tamanho) no oceano n\u00e3o era claro, mas pesquisas recentes descobriram que part\u00edculas microsc\u00f3picas geralmente se depositam em sedimentos marinhos, seguindo o padr\u00e3o de outros poluentes.<\/p>\n<p class=\"western\" align=\"left\">O novo artigo de revis\u00e3o inclui informa\u00e7\u00f5es de mais de 80 trabalhos de pesquisa que relataram medi\u00e7\u00f5es de micropl\u00e1sticos encontrados em sedimentos em um ou mais ambientes marinhos.<\/p>\n<p class=\"western\" align=\"left\">Combinando os resultados de todos os 80 artigos, mostra que o padr\u00e3o geral de polui\u00e7\u00e3o micropl\u00e1stica reflete os caminhos do ac\u00famulo natural de sedimentos nos quais a maioria dos materiais \u00e9 depositada perto de sua fonte de entrada, na foz dos rios e geralmente perto da costa.<\/p>\n<p class=\"western\" align=\"left\">Alguns ambientes, como fiordes, lagoas e estu\u00e1rios, s\u00e3o naturalmente mais eficientes na captura de sedimentos e part\u00edculas micropl\u00e1sticas.\u00a0Outros, incluindo praias altamente energ\u00e9ticas e deltas e estu\u00e1rios de rios dominados por ondas e mar\u00e9s, mostram menos ac\u00famulo de micropl\u00e1sticos;\u00a0eles vazam uma fra\u00e7\u00e3o significativa de sedimentos especialmente finos e part\u00edculas micropl\u00e1sticas para ambientes offshore em \u00e1guas profundas.<\/p>\n<p class=\"western\" align=\"left\">A polui\u00e7\u00e3o micropl\u00e1stica foi encontrada nos fiordes a uma concentra\u00e7\u00e3o m\u00e9dia de cerca de 7.000 part\u00edculas por quilograma e, em alguns casos, at\u00e9 200.000 part\u00edculas por quilograma de sedimento.\u00a0Verificou-se que as concentra\u00e7\u00f5es s\u00e3o mais baixas em outros ambientes marinhos: cerca de 300 part\u00edculas por quilograma em ambientes estuarinos, 200 em praias e 80 em ambientes de profundidade.<\/p>\n<p class=\"western\" align=\"left\">O artigo identificou lacunas cr\u00edticas que devem ser tratadas por mais pesquisas.\u00a0S\u00e3o necess\u00e1rias mais medi\u00e7\u00f5es das taxas de acumula\u00e7\u00e3o micropl\u00e1stica de diferentes ambientes para modelar o destino real da polui\u00e7\u00e3o micropl\u00e1stica no ambiente marinho.<\/p>\n<p class=\"western\" align=\"left\">Cerca de 80% dos estudos publicados s\u00e3o de ambientes de praia, pois as praias s\u00e3o facilmente acess\u00edveis para a coleta de amostras, mas s\u00e3o necess\u00e1rios mais estudos de outros ambientes, como estu\u00e1rios, lagoas e fiordes.\u00a0Al\u00e9m disso, s\u00e3o necess\u00e1rias mais medi\u00e7\u00f5es da massa de micropl\u00e1sticos (ou seja, gramas de pl\u00e1stico por quilograma de sedimento).<\/p>\n<p class=\"western\" align=\"left\">Apenas tr\u00eas dos 80 estudos pesquisados \u200b\u200binclu\u00edram dados sobre a massa de micropl\u00e1sticos, enquanto a grande maioria dos estudos relatou o n\u00famero de part\u00edculas por quilograma de sedimento.\u00a0Para entender como o micropl\u00e1stico \u00e9 disperso no oceano em muitos ambientes diferentes.<\/p>\n<p class=\"western\" align=\"left\">As conclus\u00f5es deste trabalho ser\u00e3o inclu\u00eddas em uma nova\u00a0publica\u00e7\u00e3o\u00a0<span lang=\"zxx\"><u><a href=\"https:\/\/www.grida.no\/publications?type=3\">gr\u00e1fica vital de<\/a><\/u><\/span>\u00a0lixo marinho\u00a0que est\u00e1 sendo preparada pelo GRID-Arendal em colabora\u00e7\u00e3o com o Programa das Na\u00e7\u00f5es Unidas para o Meio Ambiente.<\/p>\n<p class=\"western\" align=\"left\"><img loading=\"lazy\" class=\"alignnone \" src=\"https:\/\/ars.els-cdn.com\/content\/image\/1-s2.0-S0025326X20305166-ga1_lrg.jpg\" width=\"640\" height=\"374\" \/><\/p>\n<blockquote>\n<p class=\"western\" align=\"left\">Refer\u00eancia:<\/p>\n<p class=\"western\" align=\"left\">\u201c<strong>The fate of microplastic in marine sedimentary environments: A review and synthesis<\/strong>\u201c, Marine Pollution Bulletin, September 2020,\u00a0<a href=\"https:\/\/doi.org\/10.1016\/j.marpolbul.2020.111398\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/doi.org\/10.1016\/j.marpolbul.2020.111398<\/a><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>A polui\u00e7\u00e3o micropl\u00e1stica em ambientes marinhos concentra-se mais em habitats costeiros, especialmente fiordes e estu\u00e1rios,<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"cream-magazine-thumbnail-2":false,"cream-magazine-thumbnail-3":false,"cream-magazine-thumbnail-4":false},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"A polui\u00e7\u00e3o micropl\u00e1stica em ambientes marinhos concentra-se mais em habitats costeiros, especialmente fiordes e estu\u00e1rios,","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/129853"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=129853"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/129853\/revisions"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=129853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=129853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=129853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}