{"id":123836,"date":"2020-03-20T13:30:13","date_gmt":"2020-03-20T16:30:13","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=123836"},"modified":"2020-03-19T21:28:04","modified_gmt":"2020-03-20T00:28:04","slug":"segundo-decisao-interministerial-quem-descumprir-quarentena-pode-ir-para-a-prisao","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/segundo-decisao-interministerial-quem-descumprir-quarentena-pode-ir-para-a-prisao\/","title":{"rendered":"Segundo decis\u00e3o interministerial, quem descumprir quarentena pode ir para a pris\u00e3o"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignleft size-medium wp-image-123837\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/brasil-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/brasil-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/brasil.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Uma decis\u00e3o interministerial passa a regulamentar que o descumprimento da quarentena pode levar \u00e0 pris\u00e3o no Brasil.<\/p>\n<p>Os minist\u00e9rios da Sa\u00fade e da Justi\u00e7a e Seguran\u00e7a P\u00fablica anunciaram, conjuntamente, nessa ter\u00e7a-feira (17), que os pacientes detectados com SARS-CoV-2 que descumprirem a quarentena poder\u00e3o ser presos. Tipificado pelo C\u00f3digo Penal, o crime \u00e9 considerado como contra a sa\u00fade p\u00fablica, ensejando multa ou pena de um m\u00eas a um ano de pris\u00e3o.<\/p>\n<p>Os pr\u00f3prios ministros S\u00e9rgio Moro (Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica) e Luiz Henrique Mandetta (Minist\u00e9rio da Sa\u00fade) divulgaram a portaria interministerial sobre o descumprimento das medidas anunciadas pelo governo federal para conter o avan\u00e7o do novo coronav\u00edrus no pa\u00eds, como a quarentena e o isolamento.<\/p>\n<p>A portaria, que \u00e9 regulamentada pela Lei n\u00ba13.979\/ 2020, a qual delibera sobre as medidas de enfrentamento ao Covid-19, prev\u00ea que:<\/p>\n<p>\u201cO descumprimento das medidas previstas no art. 3\u00ba da Lei n\u00ba 13.979, de 2020, acarretar\u00e1 a responsabiliza\u00e7\u00e3o civil, administrativa e penal dos agentes infratores\u201d.<\/p>\n<p>Em caso de deten\u00e7\u00e3o de pacientes que se recusarem a passar pelos testes, a portaria recomenda, ainda, que eles sejam mantidos \u201cem estabelecimento ou cela separada dos demais presos\u201d.<\/p>\n<p>Essa medida legal torna-se necess\u00e1ria, sobretudo, ap\u00f3s o mau exemplo do presidente Jair Bolsonaro em descumprir as medidas chanceladas por seu pr\u00f3prio ministro da Sa\u00fade e da atitude de um empres\u00e1rio que fugiu do isolamento e deu uma festa, na Bahia, ap\u00f3s ser diagnosticado como positivo para o Covid-19.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma decis\u00e3o interministerial passa a regulamentar que o descumprimento da quarentena pode levar \u00e0 pris\u00e3o<\/p>\n","protected":false},"author":2,"featured_media":123837,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/brasil.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/brasil-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/brasil-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/brasil.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/brasil.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/brasil.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/brasil.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/brasil.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/brasil.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/brasil.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Uma decis\u00e3o interministerial passa a regulamentar que o descumprimento da quarentena pode levar \u00e0 pris\u00e3o","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/123836"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=123836"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/123836\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/123837"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=123836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=123836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=123836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}