{"id":123832,"date":"2020-03-20T12:30:56","date_gmt":"2020-03-20T15:30:56","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=123832"},"modified":"2020-03-19T21:27:42","modified_gmt":"2020-03-20T00:27:42","slug":"estudo-identifica-306-variantes-geneticas-ligadas-a-estrutura-cerebral-e-ao-risco-de-doencas","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/estudo-identifica-306-variantes-geneticas-ligadas-a-estrutura-cerebral-e-ao-risco-de-doencas\/","title":{"rendered":"Estudo identifica 306 variantes gen\u00e9ticas ligadas \u00e0 estrutura cerebral e ao risco de doen\u00e7as"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignleft size-medium wp-image-123833\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/cerebros-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/cerebros-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/cerebros.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Mapear pequenas varia\u00e7\u00f5es no genoma humano capazes de influenciar a arquitetura do c\u00f3rtex cerebral e a predisposi\u00e7\u00e3o a doen\u00e7as como esquizofrenia, epilepsia, autismo, transtorno bipolar, anorexia, depress\u00e3o, dem\u00eancia e v\u00e1rias outras. Esse foi o objetivo de um estudo que envolveu mais de 360 cientistas de 184 institui\u00e7\u00f5es em todo o mundo. Os resultados foram publicados nesta quinta-feira (19\/03) na revista\u00a0<em>Science<\/em>.<\/p>\n<p>Com base em exames de 51.665 pessoas, de diversos pa\u00edses, os cientistas identificaram 306 variantes gen\u00e9ticas que influenciam a estrutura de regi\u00f5es-chave do c\u00e9rebro. A investiga\u00e7\u00e3o foi conduzida no \u00e2mbito de um cons\u00f3rcio internacional chamado ENIGMA (acr\u00f4nimo em ingl\u00eas para Melhorando a Neuroimagem Gen\u00e9tica por Metan\u00e1lise), dedicado a estudar diversas doen\u00e7as neurol\u00f3gicas e psiqui\u00e1tricas. Entre os integrantes est\u00e1 o\u00a0<strong><a href=\"https:\/\/bv.fapesp.br\/pt\/auxilios\/58565\/instituto-brasileiro-de-neurociencia-e-neurotecnologia-brainn\/\" target=\"_blank\" rel=\"noopener noreferrer\">Instituto de Pesquisa sobre Neuroci\u00eancias e Neurotecnologia<\/a><\/strong>\u00a0(<strong><a href=\"https:\/\/www.brainn.org.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">BRAINN<\/a><\/strong>) da Universidade Estadual de Campinas (Unicamp), um Centro de Pesquisa, Inova\u00e7\u00e3o e Difus\u00e3o (CEPID) apoiado pela FAPESP.<\/p>\n<p>\u201cTrata-se do maior estudo de neuroimagem j\u00e1 feito sobre o c\u00f3rtex cerebral humano. Os dados permitem tra\u00e7ar o primeiro mapa da arquitetura gen\u00e9tica do c\u00e9rebro humano\u201d, disse \u00e0\u00a0<strong>Ag\u00eancia FAPESP<\/strong>\u00a0<strong><a href=\"https:\/\/bv.fapesp.br\/pt\/pesquisador\/890\/fernando-cendes\" target=\"_blank\" rel=\"noopener noreferrer\">Fernando Cendes<\/a><\/strong>, professor da Unicamp e coordenador do BRAINN.<\/p>\n<p>Segundo o pesquisador, a principal vantagem de reunir um conjunto t\u00e3o grande de informa\u00e7\u00f5es \u00e9 a possibilidade de detectar at\u00e9 mesmo altera\u00e7\u00f5es muito discretas na estrutura cerebral, que passariam despercebidas em outra situa\u00e7\u00e3o. \u201cEsses resultados nos permitem entender melhor o funcionamento e a estrutura do c\u00e9rebro normal e tamb\u00e9m do c\u00e9rebro doente\u201d, afirmou.<\/p>\n<p><strong>Dois tipos de an\u00e1lise<\/strong><\/p>\n<p>As an\u00e1lises descritas na\u00a0<em>Science<\/em>\u00a0baseiam-se em dois grandes conjuntos de dados. O primeiro inclui imagens de resson\u00e2ncia magn\u00e9tica quantitativa do c\u00e9rebro, por meio das quais os pesquisadores calcularam o volume cortical dos indiv\u00edduos analisados. Cerca de 25 mil participantes eram saud\u00e1veis e serviram de controle. Os demais eram pacientes acometidos por condi\u00e7\u00f5es como ins\u00f4nia, sintomas depressivos, transtorno de d\u00e9ficit de aten\u00e7\u00e3o com hiperatividade (TDAH), epilepsia e doen\u00e7a de Parkinson.<\/p>\n<p>\u201cO c\u00f3rtex \u00e9 a camada mais externa do c\u00e9rebro, composta pela massa cinzenta, repleta de sulcos e giros. \u00c9 a \u00e1rea mais nobre e rica de neur\u00f4nios, respons\u00e1vel por fun\u00e7\u00f5es cognitivas complexas, como linguagem, emo\u00e7\u00f5es, mem\u00f3ria e processamento de informa\u00e7\u00f5es\u201d, explicou Cendes.<\/p>\n<p>No estudo, o c\u00f3rtex foi dividido em 34 regi\u00f5es consideradas relativamente homog\u00eaneas. Em cada uma dessas regi\u00f5es foram medidos dois par\u00e2metros: a espessura cortical (altura entre a subst\u00e2ncia branca, abaixo do c\u00f3rtex, e a dura-m\u00e1ter, a meninge que recobre o c\u00e9rebro) e a \u00e1rea cortical (\u00e1rea total de cada uma das 34 regi\u00f5es).<\/p>\n<p>\u201cTodos os grupos adotaram uma t\u00e9cnica que possibilita a aquisi\u00e7\u00e3o de imagens tridimensionais em alta resolu\u00e7\u00e3o e, com aux\u00edlio de algoritmos computacionais, as medidas foram feitas de forma praticamente autom\u00e1tica. Isso \u00e9 importante porque elimina o vi\u00e9s do examinador\u201d, explicou Cendes.<\/p>\n<p>O outro conjunto de dados inclui as sequ\u00eancias completas dos genomas de participantes e de amostras de tecido depositadas em bancos de c\u00e9rebros, o que possibilitou aos pesquisadores analisar marcadores gen\u00e9ticos como, por exemplo, os polimorfismos de nucleot\u00eddeo \u00fanico (SNPs, na sigla em ingl\u00eas) \u2013 varia\u00e7\u00f5es na sequ\u00eancia de DNA que afetam somente uma base (adenina, timina, citosina ou guanina) e permitem comparar genomas de diferentes indiv\u00edduos.<\/p>\n<p>Com todos os dados em m\u00e3os, o passo seguinte foi correlacionar as medidas corticais com as varia\u00e7\u00f5es encontradas nos genes para, em seguida, comparar os padr\u00f5es observados em indiv\u00edduos saud\u00e1veis com aqueles identificados em pessoas afetadas por diferentes sintomas e doen\u00e7as.<\/p>\n<p>Cada grupo de pesquisa analisou localmente os dados de seus pacientes e indiv\u00edduos-controle. Ao final, uma meta-an\u00e1lise foi conduzida sob a coordena\u00e7\u00e3o de Katrina Grasby e outros integrantes do Grupo de Pesquisa em Gen\u00e9tica Psiqui\u00e1trica do QIMR Berghofer Medical Research Institute, na Austr\u00e1lia, em colabora\u00e7\u00e3o com pesquisadores da University of Southern California e da University of North Carolina at Chapel Hill, ambas nos Estados Unidos. O BRAINN contribuiu com dados de 150 brasileiros.<\/p>\n<p>Ao final, elaborou-se uma esp\u00e9cie de mapa que permite identificar, por exemplo, quais regi\u00f5es do c\u00f3rtex de uma pessoa com epilepsia t\u00eam volume aumentado ou reduzido em compara\u00e7\u00e3o a um indiv\u00edduo sem a doen\u00e7a, bem como quais genes se correlacionam com essas altera\u00e7\u00f5es.<\/p>\n<p>\u201cOs resultados nos permitem entender melhor os genes relacionados com o desenvolvimento de cada uma das 34 regi\u00f5es do c\u00f3rtex estudadas. E nos mostram que tanto as altera\u00e7\u00f5es na arquitetura cortical como as variantes gen\u00e9ticas podem predispor indiv\u00edduos a determinadas doen\u00e7as\u201d, contou Cendes.<\/p>\n<p>Segundo Grasby, o estudou mostrou que as variantes gen\u00e9ticas associadas a uma redu\u00e7\u00e3o do volume cortical tamb\u00e9m contribuem para um maior risco de TDAH, depress\u00e3o e ins\u00f4nia. &#8220;Isso nos d\u00e1 um ponto de partida para explorar ainda mais esse v\u00ednculo gen\u00e9tico entre a estrutura do c\u00e9rebro e o transtorno\u201d, disse a australiana.<\/p>\n<p>De acordo com Cendes, tamb\u00e9m foi poss\u00edvel identificar uma correla\u00e7\u00e3o entre alguns genes e \u00e1reas corticais espec\u00edficas com o desempenho cognitivo e n\u00edvel educacional.<\/p>\n<p>\u201cAinda est\u00e1 longe de ser uma correla\u00e7\u00e3o de 100%, ou seja, ainda h\u00e1 v\u00e1rios outros genes relacionados com a predisposi\u00e7\u00e3o a cada uma das doen\u00e7as ou fun\u00e7\u00f5es cognitivas investigadas que n\u00e3o foram identificados. Mas, com base neste primeiro estudo, \u00e9 poss\u00edvel tra\u00e7ar uma an\u00e1lise com escala ainda maior e aplicar t\u00e9cnicas de intelig\u00eancia artificial para encontrar potenciais biomarcadores de doen\u00e7as complexas que afetam o c\u00e9rebro\u201d, disse Cendes.<\/p>\n<p>O objetivo final do grupo \u00e9 entender como os genes modulam a estrutura cerebral e identificar conjuntos de altera\u00e7\u00f5es gen\u00e9ticas capazes de predizer se uma pessoa est\u00e1 mais sujeita a desenvolver uma determinada doen\u00e7a.<\/p>\n<p>\u201cSeria um passo em dire\u00e7\u00e3o \u00e0 medicina personalizada. Se soubermos como o c\u00e9rebro de um indiv\u00edduo se difere de outro poderemos adequar o tratamento ou mesmo orientar medidas de preven\u00e7\u00e3o mais espec\u00edficas\u201d, disse o coordenador do BRAINN.<\/p>\n<p>O artigo\u00a0<em>The genetic architecture of the human cerebral cortex<\/em>\u00a0pode ser lido em\u00a0<strong><a href=\"https:\/\/science.sciencemag.org\/content\/367\/6484\/eaay6690\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/science.sciencemag.org\/content\/367\/6484\/eaay6690<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mapear pequenas varia\u00e7\u00f5es no genoma humano capazes de influenciar a arquitetura do c\u00f3rtex cerebral e<\/p>\n","protected":false},"author":2,"featured_media":123833,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/cerebros.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/cerebros-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/cerebros-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/cerebros.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/cerebros.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/cerebros.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/cerebros.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/cerebros.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/cerebros.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/cerebros.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Mapear pequenas varia\u00e7\u00f5es no genoma humano capazes de influenciar a arquitetura do c\u00f3rtex cerebral e","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/123832"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=123832"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/123832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/123833"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=123832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=123832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=123832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}