{"id":123273,"date":"2020-03-10T14:30:02","date_gmt":"2020-03-10T17:30:02","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=123273"},"modified":"2020-03-09T20:51:44","modified_gmt":"2020-03-09T23:51:44","slug":"cultivar-alface-hidroponica-evita-desperdicios-e-e-uma-opcao-pratica-para-produtores","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/cultivar-alface-hidroponica-evita-desperdicios-e-e-uma-opcao-pratica-para-produtores\/","title":{"rendered":"Cultivar alface hidrop\u00f4nica evita desperd\u00edcios e \u00e9 uma op\u00e7\u00e3o pr\u00e1tica para produtores"},"content":{"rendered":"<div class=\"td-post-content\">\n<p><img loading=\"lazy\" class=\"alignleft size-medium wp-image-123274\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/alface-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/alface-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/alface.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Plantar sem necessariamente utilizar solo f\u00e9rtil como principal estrutura \u00e9 uma das t\u00e9cnicas mais antigas da agricultura, sendo, inclusive, utilizada na produ\u00e7\u00e3o dos Jardins Suspensos da Babil\u00f4nia.<\/p>\n<p>Atualmente, o m\u00e9todo de agricultura hidrop\u00f4nica vem sendo cada vez mais utilizado como alternativa ao cultivo org\u00e2nico, tanto pela sua praticidade ao evitar o contato das plantas com pragas e doen\u00e7as, quanto pela rentabilidade, visto que h\u00e1 um aumento consider\u00e1vel na produ\u00e7\u00e3o de frutas, verduras e at\u00e9 mesmo\u00a0<a href=\"http:\/\/thiagoorganico.com\/como-plantar-flores-organicas\">flores<\/a>, quando cultivadas em um sistema hidrop\u00f4nico.<\/p>\n<p>O NFT (Nutrient Film Technique) \u00e9 o sistema hidrop\u00f4nico mais utilizado nos cultivos brasileiros, pois al\u00e9m de ser um m\u00e9todo barato, n\u00e3o exige alta manuten\u00e7\u00e3o. Sua estrutura \u00e9 composta por tubula\u00e7\u00f5es de PVC organizadas verticalmente em zig-zag, de modo a induzir a descida da \u00e1gua com nutrientes e garantir que todas as plantas recebam a solu\u00e7\u00e3o nutritiva. Para impulsionar a solu\u00e7\u00e3o para o topo dos tubos, \u00e9 recomendado o uso de uma bomba de aqu\u00e1rio comum.<\/p>\n<p><a href=\"http:\/\/thiagoorganico.com\/hidroponia-cultivo-hidroponico\">O sistema hidrop\u00f4nico<\/a>\u00a0conta com o uso de um substrato nutritivo para sustentar as plantas dentro de sua estrutura ao mesmo tempo em que permite que suas ra\u00edzes se desenvolvam em contato com a \u00e1gua, garantindo que haja sempre nutrientes e que a planta consiga se desenvolver fora da terra.<\/p>\n<h3><strong>Como produzir alface hidrop\u00f4nica org\u00e2nica?<\/strong><\/h3>\n<p>Dentre as hortali\u00e7as cultivadas em sistemas hidrop\u00f4nicos, a alface est\u00e1 em primeiro lugar na agricultura brasileira. A forte presen\u00e7a da alface na cozinha dos brasileiros exigiu que o sistema de produ\u00e7\u00e3o aumentasse, por\u00e9m, o uso excessivo de agrot\u00f3xicos e pesticidas tornou a hortali\u00e7a demasiadamente nociva para a popula\u00e7\u00e3o, tornando necess\u00e1ria a cria\u00e7\u00e3o de m\u00e9todos alternativos e org\u00e2nicos de produ\u00e7\u00e3o da alface org\u00e2nica no Brasil.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" class=\"wp-image-74884 lazyloaded\" src=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-5.jpg\" sizes=\"(max-width: 660px) 100vw, 660px\" srcset=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-5.jpg 660w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-5-300x136.jpg 300w\" alt=\"\" width=\"640\" height=\"291\" data-srcset=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-5.jpg 660w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-5-300x136.jpg 300w\" data-src=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-5.jpg\" \/><\/figure>\n<\/div>\n<p>Produzir alface org\u00e2nica pelo sistema hidrop\u00f4nico \u00e9 um processo simples, mas exige alguns cuidados. A maioria dos produtores opta pelo uso de\u00a0<a href=\"http:\/\/thiagoorganico.com\/cultivo-protegido-estufa\/\">estufas<\/a>, para garantir melhor controle do ambiente, mas tamb\u00e9m \u00e9 poss\u00edvel criar sua pr\u00f3pria horta org\u00e2nica hidrop\u00f4nica em casa, utilizando um modelo de jardim vertical ou at\u00e9 mesmo t\u00e9cnicas como o floating.<\/p>\n<h3><strong>Escolhendo o local adequado<\/strong><\/h3>\n<p>O primeiro passo para quem deseja cultivar alface hidrop\u00f4nica \u00e9 a escolha do local. O uso de estufas facilita o controle do ambiente, o que \u00e9 extremamente necess\u00e1rio para produ\u00e7\u00f5es em larga escala.<\/p>\n<p>O cultivo da alface em hidroponia exige que a temperatura permane\u00e7a em torno de 25\u00b0C e com umidade relativa do ar de aproximadamente 70%. Para quem deseja cultivar a alface hidrop\u00f4nica em locais menores e fazer a sua pr\u00f3pria\u00a0<a href=\"http:\/\/thiagoorganico.com\/como-fazer-uma-horta-organica-em-casa\/\">horta org\u00e2nica em casa<\/a>\u00a0a melhor op\u00e7\u00e3o \u00e9 encontrar um espa\u00e7o coberto com boa entrada de luz.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><img loading=\"lazy\" class=\"wp-image-74885 lazyloaded\" src=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-3.jpg\" sizes=\"(max-width: 358px) 100vw, 358px\" srcset=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-3.jpg 600w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-3-228x300.jpg 228w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-3-319x420.jpg 319w\" alt=\"\" width=\"358\" height=\"470\" data-srcset=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-3.jpg 600w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-3-228x300.jpg 228w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-3-319x420.jpg 319w\" data-src=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-3.jpg\" \/><\/figure>\n<\/div>\n<h3><strong>Preparando o substrato<\/strong><\/h3>\n<p>Para que as plantas consigam se desenvolver fora do solo tradicional, \u00e9 preciso que, dentro dos tubos de PVC, haja um substrato respons\u00e1vel pela sustenta\u00e7\u00e3o. Para o modelo NTF, recomenda-se o uso de produtos de espuma, mas o produtor org\u00e2nico tamb\u00e9m pode optar pela l\u00e3 de rocha, perlita, esc\u00f3ria, serragem e pela fibra de coco.<\/p>\n<p>A alface deve ser acomodada no substrato, mas tamb\u00e9m deve possuir liberdade para acessar a solu\u00e7\u00e3o nutritiva, portanto, \u00e9 fundamental que o material tenha porosidade e permita o desenvolvimento das ra\u00edzes da planta.<\/p>\n<h3><strong>Sementes ou mudas?<\/strong><\/h3>\n<p>Escolher entre come\u00e7ar o cultivo com sementes ou mudas faz toda a diferen\u00e7a no processo de cultivo hidrop\u00f4nico. As sementes, al\u00e9m de fr\u00e1geis, exigem maior cuidado e aten\u00e7\u00e3o do produtor; seu cultivo deve ser iniciado em estuma fen\u00f3lica e a germina\u00e7\u00e3o leva aproximadamente uma semana. No entanto, optar pelas mudas \u00e9 uma forma mais pr\u00e1tica e segura de dar in\u00edcio ao cultivo, visto que h\u00e1 maior facilidade para a instala\u00e7\u00e3o e um menor risco de perda, visto que as mudas j\u00e1 est\u00e3o adaptadas ao sistema hidrop\u00f4nico de cultivo.<\/p>\n<p>Tanto as mudas quanto as sementes de alface devem ser adquiridas de produtores org\u00e2nicos certificados, garantindo que n\u00e3o houve nenhum processo qu\u00edmico para induzir o crescimento, desenvolvimento ou rendimento das plantas.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" class=\"wp-image-74883 lazyloaded\" src=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-4.jpg\" sizes=\"(max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-4.jpg 800w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-4-300x173.jpg 300w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-4-768x443.jpg 768w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-4-696x401.jpg 696w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-4-729x420.jpg 729w\" alt=\"\" width=\"640\" height=\"369\" data-srcset=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-4.jpg 800w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-4-300x173.jpg 300w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-4-768x443.jpg 768w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-4-696x401.jpg 696w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-4-729x420.jpg 729w\" data-src=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-4.jpg\" \/><\/figure>\n<\/div>\n<h3><strong>Irriga\u00e7\u00e3o e solu\u00e7\u00e3o nutritiva<\/strong><\/h3>\n<p>A irriga\u00e7\u00e3o na hidroponia \u00e9 parte fundamental para um bom cultivo, primeiramente por fazer o papel do solo permitindo o desenvolvimento das ra\u00edzes e, em segundo lugar, por ser a respons\u00e1vel pelo transporte de nutrientes. No m\u00e9todo NFT, as ra\u00edzes da alface ficar\u00e3o diretamente na \u00e1gua e ter\u00e3o contato com um pequeno filme no qual estar\u00e1 dispon\u00edvel a solu\u00e7\u00e3o nutritiva, enriquecida com Nitrato de C\u00e1lcio, Nitrato de Pot\u00e1ssio, F\u00f3sforo, Sulfato de Zinco, dentre outros nutrientes essenciais para o bom desenvolvimento da planta.<\/p>\n<p>Uma vez que a bomba de aqu\u00e1rio reutiliza a \u00e1gua j\u00e1 presente no sistema, n\u00e3o h\u00e1 desperd\u00edcio na hidroponia. O produtor deve apenas estar atento aos n\u00edveis de nutrientes presentes na solu\u00e7\u00e3o nutritiva e realizar a manuten\u00e7\u00e3o de acordo com a necessidade. A solu\u00e7\u00e3o pode ser feita em casa e ajustada para suprir todas as demandas nutritivas da alface.<\/p>\n<h3><strong>Monitorando o sistema da horta hidrop\u00f4nica<\/strong><\/h3>\n<p>O verdadeiro segredo para uma horta hidrop\u00f4nica de qualidade est\u00e1 no controle do sistema como um todo. Apesar de se tratar de um modelo com baixa manuten\u00e7\u00e3o, \u00e9 importante que o produtor verifique diariamente os n\u00edveis de pH da solu\u00e7\u00e3o, mantendo-o entre 5,8 e 6,4. Al\u00e9m disso, a concentra\u00e7\u00e3o de nutrientes tamb\u00e9m deve ser analisada, repondo de acordo com o consumo e, se preciso, melhorando sua composi\u00e7\u00e3o para tratar das plantas.<\/p>\n<p>Para o produtor que optar por estufas, vale ficar atento \u00e0 resposta das plantas aos n\u00edveis de\u00a0<a href=\"http:\/\/thiagoorganico.com\/iluminacao-artificial-para-plantas\/\">luminosidade<\/a>, temperatura e umidade relativa do ar, controlando o ambiente de acordo com o desenvolvimento das plantas, garantindo um crescimento saud\u00e1vel.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" class=\"wp-image-74881 lazyloaded\" src=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-6.jpg\" sizes=\"(max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-6.jpg 800w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-6-300x169.jpg 300w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-6-768x432.jpg 768w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-6-696x392.jpg 696w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-6-747x420.jpg 747w\" alt=\"\" width=\"640\" height=\"360\" data-srcset=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-6.jpg 800w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-6-300x169.jpg 300w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-6-768x432.jpg 768w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-6-696x392.jpg 696w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-6-747x420.jpg 747w\" data-src=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/alface-hidroponica-6.jpg\" \/><\/figure>\n<\/div>\n<h3>Como c<strong>ultivar alface org\u00e2nica hidrop\u00f4nica<\/strong><\/h3>\n<p>Para que as alfaces cres\u00e7am e se desenvolvam livremente, \u00e9 importante realizar furos no cano de PVC com aproximadamente 25cm de dist\u00e2ncia. A alface leva cerca de tr\u00eas semanas para estar pronta para o consumo e durante a colheita o produtor deve retirar as plantas pela parte a\u00e9rea da raiz, garantindo assim maior durabilidade dos p\u00e9s de alface. Al\u00e9m disso, por se tratar de uma planta n\u00e3o desenvolvida na terra, n\u00e3o \u00e9 necess\u00e1rio realizar nenhum processo de limpeza ou lavagem, preservando ainda mais a integridade das folhas.<\/p>\n<p>Ap\u00f3s colhidos, os p\u00e9s de alface hidrop\u00f4nico devem ser armazenados em um ambiente fresco e com alto n\u00edvel de umidade, preservando suas folhas e principalmente seus nutrientes. Assim como todos os produtos org\u00e2nicos, as alfaces produzidas em meio hidrop\u00f4nico garantem melhor disponibiliza\u00e7\u00e3o de nutrientes e vitaminas, sendo uma op\u00e7\u00e3o saud\u00e1vel e sustent\u00e1vel para sua fam\u00edlia.<\/p>\n<h4><strong>Horta Hidrop\u00f4nica x Horta Convencional<\/strong><\/h4>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" class=\"wp-image-74880 lazyloaded\" src=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia--1024x688.jpg\" sizes=\"(max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia--1024x688.jpg 1024w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia--300x202.jpg 300w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia--768x516.jpg 768w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia--696x467.jpg 696w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia--1068x717.jpg 1068w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia--625x420.jpg 625w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia-.jpg 1200w\" alt=\"\" width=\"639\" height=\"429\" data-srcset=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia--1024x688.jpg 1024w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia--300x202.jpg 300w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia--768x516.jpg 768w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia--696x467.jpg 696w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia--1068x717.jpg 1068w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia--625x420.jpg 625w, https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia-.jpg 1200w\" data-src=\"https:\/\/cdn-cv.r4you.co\/wp-content\/uploads\/2020\/03\/hidropinia--1024x688.jpg\" \/><\/figure>\n<\/div>\n<p>A horta hidrop\u00f4nica \u00e9 uma op\u00e7\u00e3o simples e vi\u00e1vel para produtores org\u00e2nicos que desejam fazer da agricultura um estilo de vida. Al\u00e9m da alta rentabilidade, visto que 1m\u00b2 pode produzir at\u00e9 12 mil plantas, o sistema hidrop\u00f4nico garante alfaces mais saud\u00e1veis e um menor risco de perda quando comparado com o m\u00e9todo de plantio convencional.<\/p>\n<p>O n\u00e3o contato com o solo evita a chegada de pragas como pulg\u00f5es e formigas, reduzindo, consequentemente, o consumo de inseticidas org\u00e2nicos e demais solu\u00e7\u00f5es utilizadas para os tratos culturais da alface.<\/p>\n<p>Se voc\u00ea \u00e9 um produtor org\u00e2nico urbano, o sistema hidrop\u00f4nico pode ser uma op\u00e7\u00e3o para cultivar em sacadas, deixando o ambiente mais agrad\u00e1vel e contribuindo para a decora\u00e7\u00e3o. Pensar em agricultura n\u00e3o \u00e9, necessariamente, cultivar em hortas, mas sim encontrar meios diferentes, criativos e principalmente sustent\u00e1veis de levar a produ\u00e7\u00e3o de alimentos para o dia a dia das pessoas e garantir uma vida mais saud\u00e1vel e nutritiva!<\/p>\n<p>Agora que voc\u00ea j\u00e1 sabe como fazer e cuidar de sua horta hidrop\u00f4nica de alfaces \u00e9 hora de colocar a m\u00e3o na massa e escolher um local apropriado para come\u00e7ar seu cultivo em casa!<\/p>\n<\/div>\n<footer>\n<div class=\"td-post-sharing-bottom\">\n<div id=\"td_social_sharing_article_bottom\" class=\"td-post-sharing td-ps-bg td-ps-notext td-ps-rounded td-post-sharing-style3 \">\n<div class=\"td-post-sharing-visible\">\n<div class=\"td-social-but-icon\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"author-box-wrap\"><a href=\"https:\/\/ciclovivo.com.br\/author\/thiago-campos\/\"><img loading=\"lazy\" class=\"avatar avatar-96 wp-user-avatar wp-user-avatar-96 photo avatar-default alignleft\" src=\"https:\/\/secure.gravatar.com\/avatar\/330a95c4a651f5c373dc5cdcb64f089b?s=96&amp;d=mm&amp;r=g\" alt=\"Avatar\" width=\"96\" height=\"96\" \/><\/a><\/p>\n<div class=\"desc\">\n<div class=\"td-author-description\">*Thiago Tadeu Campos \u00e9 especialista em agricultura org\u00e2nica e consultor master em produ\u00e7\u00e3o org\u00e2nica na empresa ImGrower. Um de seus principais hobbies \u00e9 compartilhar conte\u00fado em seu pr\u00f3prio blog, cuja miss\u00e3o \u00e9 fornecer material pr\u00e1tico, atualizado e de qualidade sobre a produ\u00e7\u00e3o de alimento org\u00e2nico e cultivo protegido.<\/div>\n<\/div>\n<\/div>\n<\/footer>\n","protected":false},"excerpt":{"rendered":"<p>Plantar sem necessariamente utilizar solo f\u00e9rtil como principal estrutura \u00e9 uma das t\u00e9cnicas mais antigas<\/p>\n","protected":false},"author":2,"featured_media":123274,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/alface.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/alface-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/alface-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/alface.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/alface.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/alface.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/alface.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/alface.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/alface.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/alface.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Plantar sem necessariamente utilizar solo f\u00e9rtil como principal estrutura \u00e9 uma das t\u00e9cnicas mais antigas","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/123273"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=123273"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/123273\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/123274"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=123273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=123273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=123273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}