{"id":123200,"date":"2020-03-09T07:00:06","date_gmt":"2020-03-09T10:00:06","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=123200"},"modified":"2020-03-08T18:43:54","modified_gmt":"2020-03-08T21:43:54","slug":"grupo-engenheiras-da-borborema-apresentara-trabalhos-em-evento-nacional","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/grupo-engenheiras-da-borborema-apresentara-trabalhos-em-evento-nacional\/","title":{"rendered":"Grupo Engenheiras da Borborema apresentar\u00e1 trabalhos em evento nacional"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignleft size-medium wp-image-123201\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/engenheiras-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/engenheiras-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/engenheiras.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>O grupo IEEE WIE da Universidade Federal de Campina Grande (UFCG), ligado \u00e0 rede global Mulheres nas Engenharias (sigla do ingl\u00eas para Women in Engineering &#8211; WIE) da organiza\u00e7\u00e3o profissional Institutos de Engenheiros Eletricistas e Eletr\u00f4nicos (sigla do ingl\u00eas para Institute of Electrical and Electronic Engineers &#8211; IEEE) teve tr\u00eas trabalhos aceitos no I Simp\u00f3sio Brasileiro de Mulheres em STEM, que ocorrer\u00e1 no Instituto Tecnol\u00f3gico da Aeron\u00e1utica (ITA), em S\u00e3o Jos\u00e9 dos Campo, SP, nos pr\u00f3ximos dias 13 e 14 de mar\u00e7o.<\/p>\n<p>Os trabalhos que ser\u00e3o apresentados se referem a atividades desenvolvidas pelo grupo por meio do projeto Engenheiras da Borborema, realizado em escolas p\u00fablicas da cidade com o objetivo de motivar o ingresso de meninas em cursos de engenharia e tecnologia, encorajando-as a buscarem uma carreira na \u00e1rea das Ci\u00eancias Exatas.<\/p>\n<p>\u201cTer tr\u00eas trabalhos aceitos no I Simp\u00f3sio Brasileiro de Mulheres em STEM \u00e9 muito gratificante e recompensador. \u00c9 uma forma de divulgar os projetos e atividades desenvolvidos com muita dedica\u00e7\u00e3o por volunt\u00e1rios do grupo ao longo de todo o ano. Al\u00e9m disso, o simp\u00f3sio \u00e9 uma excelente oportunidade para conhecer e compartilhar experi\u00eancias com participantes de projetos com prop\u00f3sitos semelhantes ao nosso em todo o Brasil\u201d, diz Wislayne Silva, atual presidente do IEEE WIE UFCG.<\/p>\n<p>Sobre o IEEE WIE UFCG<\/p>\n<p>O IEEE WIE UFCG \u00e9 um grupo de afinidade da rede global Women in Engineering (WIE), que tem como objetivo promover mulheres engenheiras e cientistas, e inspirar meninas a seguirem seus interesses acad\u00eamicos e profissionais em uma carreira em Engenharia e Ci\u00eancia.<\/p>\n<p>Fundado em outubro de 2015 e conduzido por estudantes, o grupo vem realizando uma s\u00e9rie de atividades voltadas para a comunidade acad\u00eamica e externa, por meio de a\u00e7\u00f5es realizadas em escolas p\u00fablicas da cidade.<\/p>\n<p>Ao longo de quase cinco anos de atua\u00e7\u00e3o, obteve diversas premia\u00e7\u00f5es nacionais e internacinais, a exemplo do segundo lugar no concurso Grupo de Afinidade Estudantil Exemplar 2018 da Am\u00e9rica Latina e Caribe; e men\u00e7\u00e3o honrosa no concurso IEEE WIE Student Branch Affinity Group of the Year, promovido pelo IEEE Women in Engineering Commitee em 2019.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O grupo IEEE WIE da Universidade Federal de Campina Grande (UFCG), ligado \u00e0 rede global<\/p>\n","protected":false},"author":2,"featured_media":123201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/engenheiras.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/engenheiras-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/engenheiras-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/engenheiras.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/engenheiras.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/engenheiras.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/engenheiras.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/engenheiras.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/engenheiras.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/engenheiras.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"O grupo IEEE WIE da Universidade Federal de Campina Grande (UFCG), ligado \u00e0 rede global","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/123200"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=123200"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/123200\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/123201"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=123200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=123200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=123200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}