{"id":123101,"date":"2020-03-07T15:39:06","date_gmt":"2020-03-07T18:39:06","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=123101"},"modified":"2020-03-07T15:39:06","modified_gmt":"2020-03-07T18:39:06","slug":"surto-de-coronavirus-e-reflexo-da-degradacao-ambiental-afirma-pnuma","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/surto-de-coronavirus-e-reflexo-da-degradacao-ambiental-afirma-pnuma\/","title":{"rendered":"Surto de coronav\u00edrus \u00e9 reflexo da degrada\u00e7\u00e3o ambiental, afirma PNUMA"},"content":{"rendered":"<h4><img loading=\"lazy\" class=\"alignleft size-medium wp-image-123102\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/corona_-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/corona_-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/corona_.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Cientistas sugerem que habitats degradados podem incitar e diversificar doen\u00e7as, j\u00e1 que os pat\u00f3genos se espalham facilmente para rebanhos e seres humanos<\/h4>\n<p>As\u00a0<span class=\"Apple-style-span\">doen\u00e7as transmitidas de animais para seres humanos est\u00e3o em ascens\u00e3o<\/span>\u00a0e pioram \u00e0 medida que\u00a0<span class=\"Apple-style-span\">habitats selvagens s\u00e3o destru\u00eddos pela atividade humana<\/span>. Cientistas\u00a0<a href=\"https:\/\/www.unenvironment.org\/pt-br\/noticias-e-reportagens\/reportagem\/surto-de-coronavirus-e-reflexo-da-degradacao-ambiental-afirma\" target=\"_blank\" rel=\"noopener noreferrer\">sugerem<\/a>\u00a0que habitats degradados podem incitar e diversificar doen\u00e7as, j\u00e1 que os pat\u00f3genos se espalham facilmente para rebanhos e seres humanos.<\/p>\n<p>A Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) relata que um animal \u00e9 a prov\u00e1vel fonte de transmiss\u00e3o do coronav\u00edrus de 2019 (<span class=\"Apple-style-span\">COVID-19<\/span>), que j\u00e1 infectou milhares de pessoas em todo o mundo e pressiona a economia global.<\/p>\n<p>Segundo a OMS, os morcegos s\u00e3o os mais prov\u00e1veis transmissores \u200b\u200bdo\u00a0<span class=\"Apple-style-span\">COVID-19<\/span>. Por\u00e9m, tamb\u00e9m \u00e9 poss\u00edvel que o v\u00edrus tenha sido transmitido aos seres humanos a partir de outro hospedeiro intermedi\u00e1rio, seja um animal dom\u00e9stico ou selvagem.<\/p>\n<p>Os\u00a0<span class=\"Apple-style-span\">coronav\u00edrus<\/span>\u00a0s\u00e3o zoon\u00f3ticos, o que significa que s\u00e3o transmitidos\u00a0<span class=\"Apple-style-span\">de animais para pessoas<\/span>. Estudos anteriores constataram que a S\u00edndrome Respirat\u00f3ria Aguda Grave (SARS, em ingl\u00eas) foi transmitida de gatos dom\u00e9sticos para seres humanos, enquanto a S\u00edndrome Respirat\u00f3ria do Oriente M\u00e9dio passou de dromed\u00e1rios para humanos.<\/p>\n<p>\u201cPortanto, como regra geral, o consumo de produtos de origem animal crua ou mal cozida deve ser evitado. Carne crua, leite fresco ou \u00f3rg\u00e3os de animais crus devem ser manuseados com cuidado para evitar a contamina\u00e7\u00e3o cruzada com alimentos n\u00e3o cozidos\u201d, comunicou a OMS.<\/p>\n<p>A declara\u00e7\u00e3o veio alguns dias antes de a China tomar medidas para coibir o com\u00e9rcio e o consumo de animais silvestres.<\/p>\n<p>\u201cOs seres humanos e a natureza fazem parte de um sistema interconectado. A natureza fornece comida, rem\u00e9dios, \u00e1gua, ar e muitos outros benef\u00edcios que permitiram \u00e0s pessoas prosperar\u201d, disse Doreen Robinson, chefe para a Vida Selvagem no Programa das Na\u00e7\u00f5es Unidas para o Meio Ambiente (PNUMA).<\/p>\n<p>\u201cContudo, como acontece com todos os sistemas, precisamos entender como este funciona para n\u00e3o exagerarmos e provocarmos consequ\u00eancias cada vez mais negativas\u201d, complementou.<\/p>\n<p>O relat\u00f3rio \u201cFronteiras 2016 sobre quest\u00f5es emergentes de preocupa\u00e7\u00e3o ambiental\u201d do PNUMA mostra que as zoonoses amea\u00e7am o desenvolvimento econ\u00f4mico, o bem-estar animal e humano e a integridade do ecossistema.<\/p>\n<p>Nos \u00faltimos anos, v\u00e1rias\u00a0<span class=\"Apple-style-span\">doen\u00e7as zoon\u00f3ticas emergentes<\/span>\u00a0foram manchete no mundo por causarem ou amea\u00e7arem causar\u00a0<span class=\"Apple-style-span\">grandes pandemias<\/span>, como ebola, gripe avi\u00e1ria, febre do Vale do Rift, febre do Nilo Ocidental e zika v\u00edrus.<\/p>\n<p>Segundo esse relat\u00f3rio, nas \u00faltimas duas d\u00e9cadas, as doen\u00e7as emergentes tiveram custos diretos de mais de 100 bilh\u00f5es de d\u00f3lares, podendo saltar para v\u00e1rios trilh\u00f5es de d\u00f3lares caso os surtos tivessem se tornado pandemias humanas.<\/p>\n<p>Para impedir o surgimento de zoonoses, \u00e9 fundamental endere\u00e7ar as m\u00faltiplas amea\u00e7as aos ecossistemas e \u00e0 vida selvagem, entre elas, a redu\u00e7\u00e3o e fragmenta\u00e7\u00e3o de habitats, o com\u00e9rcio ilegal, a polui\u00e7\u00e3o, a prolifera\u00e7\u00e3o de esp\u00e9cies invasoras e, cada vez mais, as mudan\u00e7as clim\u00e1ticas.<\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cientistas sugerem que habitats degradados podem incitar e diversificar doen\u00e7as, j\u00e1 que os pat\u00f3genos se<\/p>\n","protected":false},"author":2,"featured_media":123102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/corona_.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/corona_-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/corona_-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/corona_.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/corona_.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/corona_.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/corona_.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/corona_.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/corona_.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2020\/03\/corona_.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Cientistas sugerem que habitats degradados podem incitar e diversificar doen\u00e7as, j\u00e1 que os pat\u00f3genos se","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/123101"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=123101"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/123101\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/123102"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=123101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=123101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=123101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}