{"id":109590,"date":"2019-07-19T14:28:06","date_gmt":"2019-07-19T17:28:06","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=109590"},"modified":"2019-07-19T19:50:14","modified_gmt":"2019-07-19T22:50:14","slug":"aplicativo-detecta-se-pessoa-esta-com-depressao-pela-voz-do-usuario","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/aplicativo-detecta-se-pessoa-esta-com-depressao-pela-voz-do-usuario\/","title":{"rendered":"Aplicativo detecta se pessoa est\u00e1 com depress\u00e3o pela voz do usu\u00e1rio"},"content":{"rendered":"<p class=\"texto\"><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/invencao.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-109591\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/invencao-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/invencao-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/invencao.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Uma inven\u00e7\u00e3o desenvolvida por uma pesquisadora da\u00a0<a href=\"https:\/\/www.ualberta.ca\/\" target=\"_blank\" rel=\"noopener noreferrer\">Universidade de Alberta<\/a>, no Canad\u00e1, pode se tornar um grande aliado de psic\u00f3logos e psiquiatras no diagn\u00f3stico da depress\u00e3o.<\/p>\n<p class=\"texto\">O estudo baseia-se em pesquisas anteriores que sugerem que o timbre da nossa voz cont\u00e9m informa\u00e7\u00f5es sobre o nosso humor. Usando padr\u00f5es de dados de refer\u00eancia coletados em estudos anteriores, as pesquisadoras da Universidade de Alberta desenvolveram uma metodologia que combina v\u00e1rios algoritmos de aprendizado de m\u00e1quina para reconhecer a depress\u00e3o com mais precis\u00e3o usando sinais ac\u00fasticos.<\/p>\n<p class=\"texto\">Segundo Eleni Stroulia, professora do Departamento de Ci\u00eancia da Computa\u00e7\u00e3o da Universidade, um cen\u00e1rio realista \u00e9 que as pessoas usem um aplicativo que coletar\u00e1 amostras de voz enquanto elas falam naturalmente. \u201cO aplicativo, executado no telefone do usu\u00e1rio, reconhecer\u00e1 e rastrear\u00e1 indicadores de humor, como depress\u00e3o, ao longo do tempo. Assim como voc\u00ea tem um contador de passos no seu telefone, voc\u00ea pode ter um indicador de depress\u00e3o baseado na sua voz enquanto usa o telefone\u201d, explica Stroulia.<\/p>\n<p class=\"texto\">A ferramenta pode ser \u00fatil tanto para apoiar o trabalho com os prestadores de cuidados quanto para ajudar as pessoas a refletirem sobre seus pr\u00f3prios humores ao longo do tempo. \u201cEste trabalho, desenvolvendo uma detec\u00e7\u00e3o mais precisa em conjuntos de dados padr\u00e3o de refer\u00eancia, \u00e9 o primeiro passo\u201d, acrescentou Stroulia.<\/p>\n<p class=\"texto\"><a href=\"https:\/\/link.springer.com\/chapter\/10.1007\/978-3-030-18305-9_47\" target=\"_blank\" rel=\"noopener noreferrer\">A pesquisa<\/a>\u00a0foi conduzida tamb\u00e9m pela estudante de doutorado Mashrura Tasnim e foi apresentada na Confer\u00eancia Canadense de Intelig\u00eancia Artificial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma inven\u00e7\u00e3o desenvolvida por uma pesquisadora da\u00a0Universidade de Alberta, no Canad\u00e1, pode se tornar um<\/p>\n","protected":false},"author":2,"featured_media":109591,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/invencao.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/invencao-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/invencao-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/invencao.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/invencao.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/invencao.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/invencao.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/invencao.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/invencao.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/invencao.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Uma inven\u00e7\u00e3o desenvolvida por uma pesquisadora da\u00a0Universidade de Alberta, no Canad\u00e1, pode se tornar um","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/109590"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=109590"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/109590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/109591"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=109590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=109590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=109590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}