{"id":109573,"date":"2019-07-19T09:00:35","date_gmt":"2019-07-19T12:00:35","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/?p=109573"},"modified":"2019-07-18T18:59:32","modified_gmt":"2019-07-18T21:59:32","slug":"moratoria-da-soja-no-cerrado-evitaria-desmatamento-de-area-maior-que-a-belgica-diz-estudo","status":"publish","type":"post","link":"https:\/\/espacoecologico.com.br\/arquivo\/moratoria-da-soja-no-cerrado-evitaria-desmatamento-de-area-maior-que-a-belgica-diz-estudo\/","title":{"rendered":"&#8216;Morat\u00f3ria da soja&#8217; no Cerrado evitaria desmatamento de \u00e1rea maior que a B\u00e9lgica, diz estudo"},"content":{"rendered":"<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"41\" data-block-id=\"2\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><a href=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/cerrado.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-109574\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/cerrado-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/cerrado-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/cerrado.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>A controversa ideia de expandir para a regi\u00e3o de Cerrado a chamada morat\u00f3ria da soja, um pacto firmado em 2006 que freou parte do desmatamento da Amaz\u00f4nia gerado pelo avan\u00e7o do plantio da leguminosa, ganhou um novo ingrediente nesta semana.<\/p>\n<\/div>\n<div class=\"wall protected-content\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"86\" data-block-id=\"3\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">No primeiro estudo cient\u00edfico quantitativo realizado para a eventual ado\u00e7\u00e3o dessa medida no Cerrado brasileiro, um grupo internacional de pesquisadores concluiu que a medida, se implementada at\u00e9 2020, impediria a convers\u00e3o direta de 3,6 milh\u00f5es de hectares de vegeta\u00e7\u00e3o nativa em terras agr\u00edcolas nos 30 anos seguintes &#8211; \u00e1rea maior do que o tamanho da B\u00e9lgica. Com um adendo importante: isso n\u00e3o evitaria o avan\u00e7o da agricultura de soja no pa\u00eds &#8211; apenas &#8220;organizaria&#8221; de um jeito mais sustent\u00e1vel seus locais, priorizando \u00e1reas j\u00e1 desmatadas anteriormente.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"38\" data-block-id=\"4\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Segundo o levantamento dos cientistas, mais de 80% dessa \u00e1rea que poderia ser protegida est\u00e1 na regi\u00e3o conhecida como Matopiba &#8211; entre os Estados do Maranh\u00e3o, Tocantins, Piau\u00ed e Bahia &#8211; a chamada nova fronteira agr\u00edcola brasileira.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"63\" data-block-id=\"5\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O trabalho acad\u00eamico foi divulgado nesta semana pelo peri\u00f3dico Science Advances. &#8220;Quando n\u00e3o h\u00e1 fiscaliza\u00e7\u00e3o e a governan\u00e7a \u00e9 fraca, acordos do setor privado se tornam relevantes para combater o desmatamento e a perda de vegeta\u00e7\u00e3o nativa&#8221;, resume \u00e0 BBC News Brasil uma das autoras da pesquisa, a matem\u00e1tica brasileira Aline Soterroni, cientista do Instituto Internacional de An\u00e1lise de Sistemas Aplicados, na \u00c1ustria.<\/p>\n<\/div>\n<div class=\"content-ads content-ads--reveal\" data-block-type=\"ads\" data-block-id=\"6\">\n<div id=\"banner_materia2\" class=\"tag-manager-publicidade-container mc-has-reveal mc-has-ad-lazyload tag-manager-publicidade-banner_materia2 tag-manager-publicidade-container--carregado tag-manager-publicidade-container--visivel\" data-id=\"banner_materia2\" data-google-query-id=\"CJiswa66v-MCFdNmwQodQ6IEiQ\" data-cid=\"138269900646\" data-lid=\"4909143808\">\n<div id=\"google_ads_iframe_\/95377733\/tvg_G1\/Natureza_2__container__\">No entendimento de pesquisadores e ambientalistas, acordos como a morat\u00f3ria da soja t\u00eam mais efic\u00e1cia do que leis justamente por serem pactos firmados entre os setores envolvidos &#8211; e n\u00e3o regras verticais que precisam de fiscaliza\u00e7\u00e3o de \u00f3rg\u00e3os p\u00fablicos.<\/div>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"66\" data-block-id=\"8\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Mas a proposta de expandir a morat\u00f3ria da soja para proteger o Cerrado enfrenta resist\u00eancia de grandes empresas e da chamada bancada ruralista, influente grupo de parlamentares com liga\u00e7\u00e3o ao agroneg\u00f3cio. Em nota divulgada no m\u00eas de junho, a Associa\u00e7\u00e3o Brasileira dos Produtores de Soja (Aposoja) se posicionou &#8220;totalmente contr\u00e1ria&#8221; a qualquer pacto do g\u00eanero para o bioma. A entidade ressaltou que &#8220;o agro \u00e9 sustent\u00e1vel&#8221;.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"75\" data-block-id=\"9\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A Cargill, uma das maiores multinacionais do setor, tamb\u00e9m se manifestou. Em carta aberta aos produtores rurais brasileiros, a companhia americana afirmou que entende que esta n\u00e3o seria a solu\u00e7\u00e3o mais adequada para os problemas ambientais. &#8220;A morat\u00f3ria n\u00e3o endere\u00e7a os desafios sociais, econ\u00f4micos e, em \u00faltima an\u00e1lise, ambientais&#8221;, diz trecho do documento. &#8220;E \u00e9 muito prov\u00e1vel que cause consequ\u00eancias, mesmo que n\u00e3o intencionais, para agricultores e comunidades que dependem da agricultura para subsist\u00eancia.&#8221;<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"6\" data-block-id=\"10\">\n<div class=\"content-intertitle\">\n<h2>A origem da morat\u00f3ria da soja<\/h2>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"54\" data-block-id=\"11\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Em 2006, um pacto foi firmado entre governos, agroind\u00fastria e organiza\u00e7\u00f5es de defesa ambiental: ningu\u00e9m compraria soja produzida em regi\u00e3o de desmatamento da Amaz\u00f4nia. No ano passado, balan\u00e7o divulgado pelo Minist\u00e9rio do Meio Ambiente mostrou que a pol\u00edtica deu resultados: a m\u00e9dia anual de desmatamento nos 89 munic\u00edpios participantes caiu 85% depois do acordo.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"128\" data-block-id=\"12\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Nos \u00faltimos anos, ativistas e organismos ambientais t\u00eam sugerido uma medida semelhante para proteger o Cerrado. &#8220;A principal causa de desmatamento no cerrado \u00e9 a expans\u00e3o do agroneg\u00f3cio sobre a vegeta\u00e7\u00e3o nativa. Entre 2007 e 2014, 26% da expans\u00e3o agr\u00edcola ocorreu diretamente sobre vegeta\u00e7\u00e3o de Cerrado. Quando considerada somente a regi\u00e3o do Matopiba &#8211; por\u00e7\u00f5es de Cerrado dos Estados do Maranh\u00e3o, Tocantins, Piau\u00ed e Bahia -, que \u00e9 a principal fronteira do desmatamento, 62% da expans\u00e3o agr\u00edcola ocorreu sobre vegeta\u00e7\u00e3o nativa. Em rela\u00e7\u00e3o \u00e0s pastagens, an\u00e1lises recentes apontam que, entre 2000 e 2016, 49% da expans\u00e3o no Matopiba ocorreu sobre o cerrado. Note-se que, muitas vezes, a \u00e1rea desmatada para pastagem torna-se, posteriormente, \u00e1rea de uso agr\u00edcola&#8221;, ressalta manifesto da organiza\u00e7\u00e3o World Wide Fund for Nature (WWF).<\/p>\n<\/div>\n<div class=\"content-ads content-ads--reveal\" data-block-type=\"ads\" data-block-id=\"13\">\n<div id=\"banner_materia__052f2631-4358-4cf1-90b0-68167fb3df29\" class=\"tag-manager-publicidade-container mc-has-reveal mc-has-ad-lazyload tag-manager-publicidade-banner_materia__052f2631-4358-4cf1-90b0-68167fb3df29 tag-manager-publicidade-container--carregado tag-manager-publicidade-container--visivel\" data-id=\"banner_materia__052f2631-4358-4cf1-90b0-68167fb3df29\" data-google-query-id=\"CNSgu6-6v-MCFZB_wQodu_8Njw\" data-cid=\"138275708879\" data-lid=\"5101782934\">\n<div id=\"google_ads_iframe_\/95377733\/tvg_G1\/Natureza_3__container__\">&#8220;O setor privado aprendeu que \u00e9 poss\u00edvel produzir sem provocar novos desmatamentos diretamente associados \u00e0 sua cadeia produtiva, como \u00e9 o caso de sucesso da morat\u00f3ria da soja na Amaz\u00f4nia&#8221;, prossegue o posicionamento da ONG.<\/div>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"94\" data-block-id=\"15\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">De acordo com o estudo de Aline Soterroni, a morat\u00f3ria da soja no Cerrado n\u00e3o impediria o avan\u00e7o da produ\u00e7\u00e3o da mercadoria. &#8220;A \u00e1rea da soja projetada para 2050 ficaria reduzida em apenas 1 milh\u00e3o de hectares, se a morat\u00f3ria come\u00e7ar a funcionar em 2020&#8221;, explica ela. &#8220;Isso corresponde a uma redu\u00e7\u00e3o de 2% da \u00e1rea de soja no Brasil projetada para 2050.&#8221; Para efeitos de compara\u00e7\u00e3o, se o atual C\u00f3digo Florestal fosse cumprido rigorosamente na regi\u00e3o, ele evitaria, no mesmo per\u00edodo, o desmatamento de um quarto desse total (0,9 milh\u00e3o de hectares).<\/p>\n<\/div>\n<div class=\"row medium-uncollapsed content-media content-photo\" data-block-type=\"backstage-photo\" data-block-id=\"16\">\n<div class=\"column medium-22 large-20 medium-centered content-media__container\">\n<div class=\"progressive-img can-open-lightbox\" data-min-size=\"1008x671\" data-min-size-url=\"https:\/\/s2.glbimg.com\/AAOiTlVHK44w24jbbHzd8aSuE8U=\/0x0:620x413\/1008x0\/smart\/filters:strip_icc()\/s.glbimg.com\/jo\/g1\/f\/original\/2015\/02\/03\/185.jpg\" data-max-size=\"1600x1065\" data-max-size-url=\"https:\/\/s2.glbimg.com\/a47kQt7O-yAlgGJBWGR4lTdI7PA=\/0x0:620x413\/1600x0\/smart\/filters:strip_icc()\/s.glbimg.com\/jo\/g1\/f\/original\/2015\/02\/03\/185.jpg\" data-media-index=\"1\">\n<div class=\"placeholder-container\"><\/div>\n<picture><img loading=\"lazy\" class=\"image content-media__image progressive-loaded\" title=\"Al\u00e9m de reduzir desmatamento, a morat\u00f3ria da soja teve impacto tamb\u00e9m na fauna dos munic\u00edpios que adoraram a medida \u2014 Foto: Ang\u00e9lica Pizzolato \/ TG\" src=\"https:\/\/s2.glbimg.com\/AAOiTlVHK44w24jbbHzd8aSuE8U=\/0x0:620x413\/1008x0\/smart\/filters:strip_icc()\/s.glbimg.com\/jo\/g1\/f\/original\/2015\/02\/03\/185.jpg\" alt=\"Al\u00e9m de reduzir desmatamento, a morat\u00f3ria da soja teve impacto tamb\u00e9m na fauna dos munic\u00edpios que adoraram a medida \u2014 Foto: Ang\u00e9lica Pizzolato \/ TG\" width=\"640\" height=\"426\" data-src=\"https:\/\/s2.glbimg.com\/AAOiTlVHK44w24jbbHzd8aSuE8U=\/0x0:620x413\/1008x0\/smart\/filters:strip_icc()\/s.glbimg.com\/jo\/g1\/f\/original\/2015\/02\/03\/185.jpg\" \/><\/picture>\n<\/div>\n<p class=\"content-media__description \">Al\u00e9m de reduzir desmatamento, a morat\u00f3ria da soja teve impacto tamb\u00e9m na fauna dos munic\u00edpios que adoraram a medida \u2014 Foto: Ang\u00e9lica Pizzolato \/ TG<\/p>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"35\" data-block-id=\"17\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Soterroni lembra que as prote\u00e7\u00f5es ambientais para o cerrado s\u00e3o baixas. &#8220;No cerrado, al\u00e9m dos n\u00edveis de prote\u00e7\u00e3o da vegeta\u00e7\u00e3o nativa, definidos pelo C\u00f3digo Florestal de 2012, serem baixos, n\u00e3o h\u00e1 cumprimento dessa lei&#8221;, aponta.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"31\" data-block-id=\"18\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Um outro efeito ben\u00e9fico da medida, segundo o mesmo estudo, \u00e9 que nos mesmos 30 anos ela significaria uma redu\u00e7\u00e3o de 8% do total de emiss\u00f5es de carbono do Pa\u00eds.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"3\" data-block-id=\"19\">\n<div class=\"content-intertitle\">\n<h2>China e Europa<\/h2>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"77\" data-block-id=\"20\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O estudo rec\u00e9m-publicado tamb\u00e9m comparou quais os riscos representam os dois principais clientes do Brasil &#8211; China e Uni\u00e3o Europeia &#8211; para esse cen\u00e1rio de desmatamento. &#8220;Surpreendentemente os riscos s\u00e3o semelhantes. Apesar de o volume de soja produzido no Cerrado para o mercado chin\u00eas ser 2,5 vezes maior do que aquele que vai para a Uni\u00e3o Europeia. Isso acontece porque a Europa compra de traders com atividades pr\u00f3ximas das \u00e1reas de remanescentes de vegeta\u00e7\u00e3o nativa no Cerrado.&#8221;<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"34\" data-block-id=\"22\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A pesquisadora espera que o estudo possa ser utilizado em futuras tratativas comerciais internacionais, como nas negocia\u00e7\u00f5es atuais entre Uni\u00e3o Europeia e Mercosul, que pode condicionar a compra da produ\u00e7\u00e3o brasileira \u00e0 preserva\u00e7\u00e3o ambiental.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"94\" data-block-id=\"23\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">De acordo com o levantamento, 25,4 milh\u00f5es de hectares de terras na regi\u00e3o de Cerrado, desmatadas anteriormente, j\u00e1 s\u00e3o adequadas para o uso agr\u00edcola &#8211; duas vezes o tamanho da Inglaterra. &#8220;Com a extens\u00e3o da morat\u00f3ria da soja para o Cerrado, os resultados da modelagem indicam que a soja ir\u00e1 expandir, sobretudo, em \u00e1reas de pastagens e \u00e1reas n\u00e3o produtivas que podem ser consideradas, em grande parte, pastagens degradadas. Uma pequena intensifica\u00e7\u00e3o das pastagens libera terra suficiente para a soja expandir no Cerrado sem a necessidade da convers\u00e3o de vegeta\u00e7\u00e3o nativa&#8221;, explica ela.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"3\" data-block-id=\"24\">\n<div class=\"content-intertitle\">\n<h2>Cerrado em risco<\/h2>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"80\" data-block-id=\"25\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Soterroni e sua equipe quantificaram o impacto da medida na fauna e na flora nativas. Entre plantas e animais &#8211; tanto vertebrados quanto invertebrados &#8211; 4.800 esp\u00e9cies aut\u00f3ctones s\u00e3o potencialmente amea\u00e7adas pelo desmatamento da regi\u00e3o. De acordo com o Instituto Chico Mendes de Conserva\u00e7\u00e3o da Biodiversidade (ICMBio), hoje s\u00e3o 624 esp\u00e9cies de flora amea\u00e7adas de extin\u00e7\u00e3o no bioma e 138 de fauna &#8211; sendo 95 vertebrados. &#8220;Alguns exemplos da fauna s\u00e3o o lobo-guar\u00e1 e o tamandu\u00e1-bandeira&#8221;, cita a cientista brasileira.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"69\" data-block-id=\"26\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A pesquisa levanta a necessidade de um olhar mais cauteloso para o Cerrado brasileiro, bioma com gradiente de vegeta\u00e7\u00e3o que vai desde forma\u00e7\u00f5es campestres a forma\u00e7\u00f5es florestais e que \u00e9 menos &#8220;pop&#8221; do que a Amaz\u00f4nia e a Mata Atl\u00e2ntica, por exemplo. &#8220;Estima-se que metade do Cerrado j\u00e1 foi convertida, e que existam menos de 20% de vegeta\u00e7\u00e3o nativa remanescente, ou seja, que n\u00e3o foi antropizada&#8221;, afirma Soterroni.<\/p>\n<\/div>\n<div class=\"row medium-uncollapsed content-media content-photo\" data-block-type=\"backstage-photo\" data-block-id=\"27\">\n<div class=\"column medium-22 large-20 medium-centered content-media__container\">\n<div class=\"progressive-img can-open-lightbox\" data-min-size=\"1008x756\" data-min-size-url=\"https:\/\/s2.glbimg.com\/4uV2AN7f8snM7fjuRGbSuVHtsPg=\/0x0:1024x768\/1008x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2017\/8\/t\/o5BQNARBWbTudgY5NGfw\/img-20170425-wa0024.jpg\" data-max-size=\"1600x1200\" data-max-size-url=\"https:\/\/s2.glbimg.com\/ASx1tZIPRBDLkUWVwcttPnTmToM=\/0x0:1024x768\/1600x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2017\/8\/t\/o5BQNARBWbTudgY5NGfw\/img-20170425-wa0024.jpg\" data-media-index=\"2\">\n<div class=\"placeholder-container\"><\/div>\n<picture><img loading=\"lazy\" class=\"image content-media__image progressive-loaded\" title=\"Ao longo de mais de uma d\u00e9cada de exist\u00eancia, a Morat\u00f3ria da Soja mostrou na pr\u00e1tica que \u00e9 poss\u00edvel reduzir o desmatamento \u2014 Foto: Divulga\u00e7\u00e3o\/Aprosoja\" src=\"https:\/\/s2.glbimg.com\/4uV2AN7f8snM7fjuRGbSuVHtsPg=\/0x0:1024x768\/1008x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2017\/8\/t\/o5BQNARBWbTudgY5NGfw\/img-20170425-wa0024.jpg\" alt=\"Ao longo de mais de uma d\u00e9cada de exist\u00eancia, a Morat\u00f3ria da Soja mostrou na pr\u00e1tica que \u00e9 poss\u00edvel reduzir o desmatamento \u2014 Foto: Divulga\u00e7\u00e3o\/Aprosoja\" width=\"640\" height=\"480\" data-src=\"https:\/\/s2.glbimg.com\/4uV2AN7f8snM7fjuRGbSuVHtsPg=\/0x0:1024x768\/1008x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2017\/8\/t\/o5BQNARBWbTudgY5NGfw\/img-20170425-wa0024.jpg\" \/><\/picture>\n<\/div>\n<p class=\"content-media__description \">Ao longo de mais de uma d\u00e9cada de exist\u00eancia, a Morat\u00f3ria da Soja mostrou na pr\u00e1tica que \u00e9 poss\u00edvel reduzir o desmatamento \u2014 Foto: Divulga\u00e7\u00e3o\/Aprosoja<\/p>\n<\/div>\n<\/div>\n<div class=\"content-ads content-ads--reveal\" data-block-type=\"ads\" data-block-id=\"28\"><\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"64\" data-block-id=\"29\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A pesquisadora afirma que acompanha atentamente o cen\u00e1rio. De um lado, &#8220;a falta de fiscaliza\u00e7\u00e3o e o n\u00e3o cumprimento das leis ambientais&#8221;. De outro, &#8220;a demanda crescente por commodities como soja e carne&#8221;. Segundo ela, um estudo mostrou que das fazendas de soja avaliadas na por\u00e7\u00e3o Amaz\u00f4nia do estado do Mato Grosso, 65% n\u00e3o cumprem o C\u00f3digo Florestal, mas cumprem a morat\u00f3ria da soja.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"58\" data-block-id=\"30\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Na modelagem cient\u00edfica utilizada pelos pesquisadores eles procuraram saber tamb\u00e9m quanto se perde com o atraso da implementa\u00e7\u00e3o da morat\u00f3ria do cerrado na soja, considerando a demora de o projeto sair do papel. Para tanto, avaliaram tr\u00eas cen\u00e1rios: se a medida estivesse em vigor desde 2015, se ela for iniciada em 2020 ou se apenas come\u00e7ar em 2025.<\/p>\n<\/div>\n<div data-track-category=\"multicontent\" data-track-action=\"ultimo chunk conteudo\" data-track-noninteraction=\"false\" data-track-scroll=\"view\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"39\" data-block-id=\"31\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;Os resultados indicam que esse atraso na implementa\u00e7\u00e3o da morat\u00f3ria da soja no cerrado pode causar uma perda m\u00e9dia de 140 mil hectares por ano no bioma&#8221;, diz a cientista. Isso equivale \u00e0 \u00e1rea do munic\u00edpio de S\u00e3o Paulo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A controversa ideia de expandir para a regi\u00e3o de Cerrado a chamada morat\u00f3ria da soja,<\/p>\n","protected":false},"author":2,"featured_media":109574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/cerrado.jpg",415,265,false],"thumbnail":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/cerrado-150x150.jpg",150,150,true],"medium":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/cerrado-300x192.jpg",300,192,true],"medium_large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/cerrado.jpg",415,265,false],"large":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/cerrado.jpg",415,265,false],"1536x1536":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/cerrado.jpg",415,265,false],"2048x2048":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/cerrado.jpg",415,265,false],"cream-magazine-thumbnail-2":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/cerrado.jpg",415,265,false],"cream-magazine-thumbnail-3":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/cerrado.jpg",415,265,false],"cream-magazine-thumbnail-4":["https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2019\/07\/cerrado.jpg",415,265,false]},"uagb_author_info":{"display_name":"","author_link":"https:\/\/espacoecologico.com.br\/arquivo\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"A controversa ideia de expandir para a regi\u00e3o de Cerrado a chamada morat\u00f3ria da soja,","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/109573"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=109573"}],"version-history":[{"count":0,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/posts\/109573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/109574"}],"wp:attachment":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media?parent=109573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/categories?post=109573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/tags?post=109573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}