{"id":64798,"date":"2017-04-30T11:53:42","date_gmt":"2017-04-30T14:53:42","guid":{"rendered":"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/plantas_toxicas.jpg"},"modified":"2017-04-30T11:53:42","modified_gmt":"2017-04-30T14:53:42","slug":"plantas_toxicas-3","status":"inherit","type":"attachment","link":"https:\/\/espacoecologico.com.br\/arquivo\/estudo-mapeia-plantas-decorativas-toxicas-que-expoem-animais-ao-perigo\/plantas_toxicas-3\/","title":{"rendered":"plantas_toxicas"},"author":6,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/plantas_toxicas.jpg'><img width=\"300\" height=\"192\" src=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/plantas_toxicas-300x192.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/plantas_toxicas-300x192.jpg 300w, https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/plantas_toxicas.jpg 415w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":415,"height":265,"file":"2017\/04\/plantas_toxicas.jpg","sizes":{"thumbnail":{"file":"plantas_toxicas-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/plantas_toxicas-150x150.jpg"},"medium":{"file":"plantas_toxicas-300x192.jpg","width":300,"height":192,"mime_type":"image\/jpeg","source_url":"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/plantas_toxicas-300x192.jpg"},"miniatura":{"file":"plantas_toxicas-139x112.jpg","width":139,"height":112,"mime_type":"image\/jpeg","source_url":"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/plantas_toxicas-139x112.jpg"},"full":{"file":"plantas_toxicas.jpg","width":415,"height":265,"mime_type":"image\/jpeg","source_url":"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/plantas_toxicas.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":64797,"source_url":"https:\/\/espacoecologico.com.br\/arquivo\/wp-content\/uploads\/2017\/04\/plantas_toxicas.jpg","_links":{"self":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media\/64798"}],"collection":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/espacoecologico.com.br\/arquivo\/wp-json\/wp\/v2\/comments?post=64798"}]}}